{"id":74855,"date":"2017-06-29T12:21:59","date_gmt":"2017-06-29T12:21:59","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74855"},"modified":"2017-06-29T12:21:59","modified_gmt":"2017-06-29T12:21:59","slug":"detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/","title":{"rendered":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-74856\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg 496w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos pa\u00edses se est\u00e1n realizando varios registros relacionados con esta operaci\u00f3n antiterrorista a instancias de las autoridades espa\u00f1olas.<\/p>\n<p>La investigaci\u00f3n se inici\u00f3 en 2015 cuando fueron detectados en una p\u00e1gina web una serie de v\u00eddeos que mostraban el proceso de adoctrinamiento, captaci\u00f3n y viaje a Siria de un joven musulm\u00e1n residente en Espa\u00f1a. Se identific\u00f3 al promotor de la filmaci\u00f3n, un im\u00e1n salafista, detenido ahora en el Reino Unido e investigado por varios pa\u00edses europeos. Esta persona hab\u00eda viajado en esas fechas a Palma de Mallorca y comenzaba a dinamizar a un grupo, los ahora arrestados, para ejercer funciones de captaci\u00f3n, adoctrinamiento y radicalizaci\u00f3n en favor de DAESH, convirti\u00e9ndose a partir de ese momento en su l\u00edder espiritual.<\/p>\n<p>El predicador salafista, cuyo discurso p\u00fablico era muy conocido por los servicios policiales y de inteligencia europeos, se dedicaba, en su vertiente m\u00e1s privada, a la captaci\u00f3n de combatientes y recaudaci\u00f3n de fondos para Siria. Sin embargo, las medidas de seguridad que adoptaba y sus cambios constantes de residencia dificultaban mucho su detenci\u00f3n.<\/p>\n<p>El detenido en Alemania ten\u00eda tambi\u00e9n como referente espiritual e ideol\u00f3gico al im\u00e1n salafista detenido en Reino Unido. Adem\u00e1s, manten\u00eda contacto directo con el resto de arrestados y hab\u00eda participado en los v\u00eddeos propagand\u00edsticos elaborados por el grupo.<\/p>\n<p>La investigaci\u00f3n ha constatado que el grupo radicado en Palma de Mallorca hab\u00eda ido multiplicando progresivamente el n\u00famero de adeptos, no s\u00f3lo mediante su actividad en las redes sociales, sino tambi\u00e9n mediante reuniones semanales clandestinas, escenificadas con un claro reparto de tareas, un sheikh o sabio, dirigiendo el contenido cada vez m\u00e1s extremista, un ojeador de nuevos adeptos, y un captador quien realizaba el contacto directo con el futuro miembro.<\/p>\n<p>Su polarizaci\u00f3n hacia el radicalismo m\u00e1s extremo, su total compromiso y adhesi\u00f3n con las directrices de DAESH, la justificaci\u00f3n de los procedimientos terroristas llevados a cabo por los actores solitarios en Europa y su predisposici\u00f3n para acometer la yihad violenta, propiciaron el desarrollo de esta operaci\u00f3n en Espa\u00f1a, Reino Unido y Alemania.<\/p>\n<p>Estas detenciones han contado con la colaboraci\u00f3n del Centro Nacional de Inteligencia, la Polic\u00eda Federal alemana-BKA, LKA de Renania del Norte-Westfalia, Metropolitan Police de Londres y CTU West Midlans Birmingham, as\u00ed como con el apoyo de las agencias europeas EUROPOL -que traslad\u00f3 a uno de sus expertos a Palma de Mallorca-, EUROJUST y SIRENE.<\/p>\n<p>La compleja operaci\u00f3n desarrollada por la Comisar\u00eda General de Informaci\u00f3n manifiesta su total compromiso en el marco de la colaboraci\u00f3n y cooperaci\u00f3n nacional e internacional, y sit\u00faa la interlocuci\u00f3n con todos los agentes, instituciones y agencias implicados en la seguridad europea como el eje integrador necesario para la lucha contra el terrorismo yihadista en todas sus formas.<\/p>\n<p>La operaci\u00f3n, que contin\u00faa abierta, se ha desarrollado bajo la supervisi\u00f3n del Juzgado Central Instrucci\u00f3n, N\u00famero 1, y la coordinaci\u00f3n de la Fiscal\u00eda de la Audiencia Nacional.<\/p>\n<p>Desde el 26 de junio de 2015, fecha en el que el Ministerio del Interior elev\u00f3 a 4 el Nivel de Alerta Antiterrorista (NAA), las Fuerzas y Cuerpos de Seguridad han detenido a 178 terroristas yihadistas en operaciones realizadas en Espa\u00f1a y en el exterior y a un total de 223 desde principios de 2015.<\/p>\n<p>El Ministerio del Interior recuerda que, a trav\u00e9s de la iniciativa STOP RADICALISMOS, los ciudadanos pueden colaborar a trav\u00e9s de una serie de canales a su disposici\u00f3n para que, de forma confidencial y segura, notifiquen a las Fuerzas y Cuerpos de Seguridad aquellos posibles casos de radicalizaci\u00f3n en su entorno a trav\u00e9s de la p\u00e1gina web www.stop-radicalismos.es, la aplicaci\u00f3n m\u00f3vil de alertas de seguridad ciudadana Alertcops y el tel\u00e9fono gratuito 900 822 066.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos<\/p>\n","protected":false},"author":1,"featured_media":74856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-74855","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-29T12:21:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-29T12:21:59+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#listItem\",\"name\":\"Detenidas seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#listItem\",\"position\":3,\"name\":\"Detenidas seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#newsarticle\",\"name\":\"Detenidas seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH | Cand\\u00e1s 365\",\"headline\":\"Detenidas seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/22062017_Stop.jpg\",\"width\":496,\"height\":329},\"datePublished\":\"2017-06-29T12:21:59+02:00\",\"dateModified\":\"2017-06-29T12:21:59+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 29, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/\",\"name\":\"Detenidas seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH | Cand\\u00e1s 365\",\"description\":\"Agentes de la Comisar\\u00eda General de Informaci\\u00f3n de la Polic\\u00eda Nacional, en colaboraci\\u00f3n con la Brigada Provincial de Informaci\\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\\u00f3n en la organizaci\\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\\u00e1s, en estos dos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/22062017_Stop.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#mainImage\",\"width\":496,\"height\":329},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\\\/#mainImage\"},\"datePublished\":\"2017-06-29T12:21:59+02:00\",\"dateModified\":\"2017-06-29T12:21:59+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365","description":"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos","canonical_url":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#listItem","name":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#listItem","position":3,"name":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#newsarticle","name":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365","headline":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg","width":496,"height":329},"datePublished":"2017-06-29T12:21:59+02:00","dateModified":"2017-06-29T12:21:59+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 29, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#webpage","url":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/","name":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365","description":"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg","@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#mainImage","width":496,"height":329},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/#mainImage"},"datePublished":"2017-06-29T12:21:59+02:00","dateModified":"2017-06-29T12:21:59+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365","og:description":"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos","og:url":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg","og:image:width":496,"og:image:height":329,"article:published_time":"2017-06-29T12:21:59+00:00","article:modified_time":"2017-06-29T12:21:59+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH | Cand\u00e1s 365","twitter:description":"Agentes de la Comisar\u00eda General de Informaci\u00f3n de la Polic\u00eda Nacional, en colaboraci\u00f3n con la Brigada Provincial de Informaci\u00f3n de Palma de Mallorca, han detenido a seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH. Las detenciones han sido practicadas en Palma de Mallorca (4), Reino Unido (1) y Alemania (1). Adem\u00e1s, en estos dos","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/22062017_Stop.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"74855","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:20:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:58:00","updated":"2025-08-25 17:20:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDetenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Detenidas seis personas por integraci\u00f3n en la organizaci\u00f3n terrorista DAESH","link":"https:\/\/candas365.es\/noticias\/detenidas-seis-personas-por-integracion-en-la-organizacion-terrorista-daesh\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74855"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/74856"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}