{"id":74808,"date":"2017-06-28T12:20:10","date_gmt":"2017-06-28T12:20:10","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74808"},"modified":"2017-06-28T12:20:10","modified_gmt":"2017-06-28T12:20:10","slug":"coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/","title":{"rendered":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17671\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-650x433.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s o menos graciosas, referencias a \u2018santos Job\u2019 o amenazas tan veladas como falsas\u201d.<\/p>\n<p>\u201cEn resumen: \u00bfFern\u00e1ndez tiene mayor\u00eda parlamentario s\u00ed o no? \u00bfTiene respaldo de su propio partido s\u00ed o no? Desde su llegada al Gobierno \u00bfAsturias est\u00e1 peor o mejor?\u201d, ha dicho Cristina Coto, quien el pasado lunes, en rueda informativa, ya avanzaba que \u201c\u201cLa situaci\u00f3n es de absoluto aislamiento; Javier Fern\u00e1ndez se encuentra instalado sobre la base de 14 diputados con el a\u00f1adido de que la inercia emblem\u00e1tica en la que ha basado su gesti\u00f3n desde 2012 ahora ya se ha convertido en par\u00e1lisis y, peor a\u00fan, en retroceso\u201d, motivo por el cual \u201cla continuidad de Javier Fern\u00e1ndez como presidente del Principado es insostenible, con un balance de gesti\u00f3n penoso, sin apoyos parlamentarios y censurado por sus propios compa\u00f1eros de partido\u201d.<\/p>\n<p>\u201cQue Javier Fern\u00e1ndez se\u00f1ale a su Ejecutivo como \u2018el espejo de la gesti\u00f3n socialista en el que nos miraremos todos\u2019 supera todos los l\u00edmites de la extravagancia y la soberbia, una vez conocidos los indicadores que nos ponen en cola del crecimiento y a la cabeza del paro\u201d, concluy\u00f3 Cristina Coto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s<\/p>\n","protected":false},"author":1,"featured_media":17671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-74808","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-28T12:20:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-28T12:20:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#listItem\",\"name\":\"Coto: \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#listItem\",\"position\":3,\"name\":\"Coto: \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#newsarticle\",\"name\":\"Coto: \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Coto: \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Cristina-Coto.jpg\",\"width\":800,\"height\":533},\"datePublished\":\"2017-06-28T12:20:10+02:00\",\"dateModified\":\"2017-06-28T12:20:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el junio 28, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/\",\"name\":\"Coto: \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados\\u00bb | Cand\\u00e1s 365\",\"description\":\"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\\u00f3n en la Junta General, ha manifestado esta ma\\u00f1ana a diversos medios informativos que \\u201cJavier Fern\\u00e1ndez est\\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\\u00e1s\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Cristina-Coto.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#mainImage\",\"width\":800,\"height\":533},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\\\/#mainImage\"},\"datePublished\":\"2017-06-28T12:20:10+02:00\",\"dateModified\":\"2017-06-28T12:20:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365","description":"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s","canonical_url":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#listItem","name":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#listItem","position":3,"name":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#newsarticle","name":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365","headline":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg","width":800,"height":533},"datePublished":"2017-06-28T12:20:10+02:00","dateModified":"2017-06-28T12:20:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el junio 28, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#webpage","url":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/","name":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365","description":"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg","@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#mainImage","width":800,"height":533},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/#mainImage"},"datePublished":"2017-06-28T12:20:10+02:00","dateModified":"2017-06-28T12:20:10+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365","og:description":"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s","og:url":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2017-06-28T12:20:10+00:00","article:modified_time":"2017-06-28T12:20:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb | Cand\u00e1s 365","twitter:description":"La presidenta de FORO, Cristina Coto, al hilo de las declaraciones del presidente del Principado por su hartazgo ante la postura del resto de partidos con representaci\u00f3n en la Junta General, ha manifestado esta ma\u00f1ana a diversos medios informativos que \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados, no con frases m\u00e1s","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/10\/Cristina-Coto.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"74808","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:16:10","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:58:00","updated":"2025-08-25 17:16:10"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCoto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Coto: \u201cJavier Fern\u00e1ndez est\u00e1 obligado a responder ante los asturianos con resultados\u00bb","link":"https:\/\/candas365.es\/noticias\/coto-javier-fernandez-esta-obligado-a-responder-ante-los-asturianos-con-resultados\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74808"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/17671"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}