{"id":74659,"date":"2017-06-26T13:58:57","date_gmt":"2017-06-26T13:58:57","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74659"},"modified":"2017-06-26T13:58:57","modified_gmt":"2017-06-26T13:58:57","slug":"air-europa-estrena-en-lima-su-nuevo-dreamliner","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/","title":{"rendered":"Air Europa estrena en Lima su nuevo Dreamliner"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-74660\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-360x288.jpg\" alt=\"\" width=\"360\" height=\"288\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-360x288.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-768x614.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-600x480.jpg 600w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-696x557.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-1068x854.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115-525x420.jpg 525w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lima es desde\u00a0el d\u00eda 24 de junio\u00a0el sexto <strong>destino Dreamliner de Air Europa<\/strong> despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda.<\/p>\n<p>La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico <strong>Globalia<\/strong> opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con ella su nueva red Dreamliner, compuesta por Miami, Bogot\u00e1, Santo Domingo, Buenos Aires y La Habana. A partir de ahora, Air Europa trabaja ya en la llegada de los nuevos Boeing 787-9, previstos desde 2018 hasta 2022.<\/p>\n<p>El primer B787-8 que ha aterrizado en Lima a las 05.29 horas (hora local) despeg\u00f3 del aeropuerto Adolfo Su\u00e1rez Madrid Barajas poco despu\u00e9s de las doce de la pasada noche, con una ocupaci\u00f3n superior al 95%.<\/p>\n<p>El Dreamliner, con capacidad para 296 pasajeros de los que 274 viajan en clase turista y 22 en business, est\u00e1 especialmente dise\u00f1ado para los vuelos de largo radio, reduce el tiempo de vuelo 40 minutos y combina a bordo el m\u00e1ximo confort del pasajero con un excepcional rendimiento medioambiental.<\/p>\n<p>Sus avances tecnol\u00f3gicos se traducen en un incomparable rendimiento al consumir un 20% menos de combustible y generar menos emisiones que cualquier otra aeronave de tama\u00f1o similar. Su impacto ac\u00fastico es tambi\u00e9n un 60% inferior al de otras aeronaves de su mismo tama\u00f1o. Por otra parte, destacar que la cabina est\u00e1 presurizada 609.6 metros por debajo de la mayor\u00eda de los aviones, lo que reporta en una mayor sensaci\u00f3n de confort para el pasajero.<\/p>\n<p>La apuesta por el largo radio de Air Europa se traduce igualmente en la consecuci\u00f3n de notables mejoras en los servicios de a bordo como son, en el caso del Dreamliner, los nuevos asientos flat bed en clase business, que permiten un reclinado total y garantizan la comodidad y el descanso del pasajero; as\u00ed como el servicio Wi-FI y el sistema ex3 IFE que permite ofrecer a pasajero el mejor entretenimiento. Adem\u00e1s, Air Europa en su apuesta por la comida saludable, sirve a bordo de sus aviones de largo alcance los nuevos men\u00fas ecol\u00f3gicos, elaborados con productos con certificado de origen de calidad. Los pasajeros que viajan en clase business pueden, adem\u00e1s, degustar a bordo la cocina creativa del prestigioso chef espa\u00f1ol Mart\u00edn Berasategui.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lima es desde\u00a0el d\u00eda 24 de junio\u00a0el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con<\/p>\n","protected":false},"author":1,"featured_media":74660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-74659","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-26T13:58:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-26T13:58:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#listItem\",\"name\":\"Air Europa estrena en Lima su nuevo Dreamliner\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#listItem\",\"position\":3,\"name\":\"Air Europa estrena en Lima su nuevo Dreamliner\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#newsarticle\",\"name\":\"Air Europa estrena en Lima su nuevo Dreamliner | Cand\\u00e1s 365\",\"headline\":\"Air Europa estrena en Lima su nuevo Dreamliner\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ARE-7878_Slide18B_MR-1115.jpg\",\"width\":1280,\"height\":1024},\"datePublished\":\"2017-06-26T13:58:57+02:00\",\"dateModified\":\"2017-06-26T13:58:57+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el junio 26, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/\",\"name\":\"Air Europa estrena en Lima su nuevo Dreamliner | Cand\\u00e1s 365\",\"description\":\"Lima es desde el d\\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\\u00e9s de que la aerol\\u00ednea haya aterrizado esta ma\\u00f1ana en el Aeropuerto Internacional Jorge Ch\\u00e1vez con el \\u00faltimo Boeing 787-8 de la compa\\u00f1\\u00eda. La divisi\\u00f3n a\\u00e9rea del grupo tur\\u00edstico Globalia opera esta ruta con sus dos \\u00faltimos Boeing 787-8 y cierra con\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/ARE-7878_Slide18B_MR-1115.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#mainImage\",\"width\":1280,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/air-europa-estrena-en-lima-su-nuevo-dreamliner\\\/#mainImage\"},\"datePublished\":\"2017-06-26T13:58:57+02:00\",\"dateModified\":\"2017-06-26T13:58:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365","description":"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con","canonical_url":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#listItem","name":"Air Europa estrena en Lima su nuevo Dreamliner"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#listItem","position":3,"name":"Air Europa estrena en Lima su nuevo Dreamliner","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#newsarticle","name":"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365","headline":"Air Europa estrena en Lima su nuevo Dreamliner","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg","width":1280,"height":1024},"datePublished":"2017-06-26T13:58:57+02:00","dateModified":"2017-06-26T13:58:57+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el junio 26, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#webpage","url":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/","name":"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365","description":"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg","@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#mainImage","width":1280,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/#mainImage"},"datePublished":"2017-06-26T13:58:57+02:00","dateModified":"2017-06-26T13:58:57+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365","og:description":"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con","og:url":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg","og:image:width":1280,"og:image:height":1024,"article:published_time":"2017-06-26T13:58:57+00:00","article:modified_time":"2017-06-26T13:58:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Air Europa estrena en Lima su nuevo Dreamliner | Cand\u00e1s 365","twitter:description":"Lima es desde el d\u00eda 24 de junio el sexto destino Dreamliner de Air Europa despu\u00e9s de que la aerol\u00ednea haya aterrizado esta ma\u00f1ana en el Aeropuerto Internacional Jorge Ch\u00e1vez con el \u00faltimo Boeing 787-8 de la compa\u00f1\u00eda. La divisi\u00f3n a\u00e9rea del grupo tur\u00edstico Globalia opera esta ruta con sus dos \u00faltimos Boeing 787-8 y cierra con","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/ARE-7878_Slide18B_MR-1115.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"74659","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 17:05:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:58:25","updated":"2025-08-25 17:05:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAir Europa estrena en Lima su nuevo Dreamliner\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Air Europa estrena en Lima su nuevo Dreamliner","link":"https:\/\/candas365.es\/noticias\/air-europa-estrena-en-lima-su-nuevo-dreamliner\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74659"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/74660"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}