{"id":74032,"date":"2017-06-21T11:46:38","date_gmt":"2017-06-21T11:46:38","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=74032"},"modified":"2017-06-21T11:46:38","modified_gmt":"2017-06-21T11:46:38","slug":"anytime-fitness-celebra-su-i-conferencia-anual-en-espana","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/","title":{"rendered":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a"},"content":{"rendered":"<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-74033\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-360x203.jpg\" alt=\"\" width=\"360\" height=\"203\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-360x203.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-768x432.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-655x368.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-696x392.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-1068x601.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-747x420.jpg 747w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126-499x280.jpg 499w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg 1200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Anytime Fitness<\/strong>, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia.<\/p>\n<p>Con la vista puesta en <em>el nuevo curso<\/em>, m\u00e1s de 250 asistentes, entre franquiciados, club managers y proveedores, se dieron cita en esta localidad costera durante dos d\u00edas para dialogar sobre el presente y futuro del l\u00edder del fitness de conveniencia mundial, que prev\u00e9 cerrar el a\u00f1o con 50 clubes operativos en el pa\u00eds.<\/p>\n<p>El encuentro comenz\u00f3 con un divertido mensaje que los fundadores de la franquicia quisieron hacer llegar a sus franquiciados a trav\u00e9s de un divertido v\u00eddeo en el que mostraron su complicidad con nuestro pa\u00eds. A \u00e9ste siguieron las palabras de Emilio Quero \u2013Director General de Anytime Fitness Iberia- y Jeannie Nove \u2013 Directora Internacional de operaciones- desplazada desde Australia para el evento, que hablaron mano a mano de la posici\u00f3n de dominio de la franquicia dentro y fuera de Espa\u00f1a, as\u00ed como la estrategia a seguir en los pr\u00f3ximos meses. Entre los dem\u00e1s ponentes, caras muy conocidas de dentro y fuera del gremio, como Victor K\u00fcppers, quien dio una charla magistral sobre motivaci\u00f3n y actitud, y Lucas Pe\u00f1as, quien a trav\u00e9s de un workshop y una interesante presentaci\u00f3n, trat\u00f3 de la importancia de la fidelizaci\u00f3n y de la realidad del sector desde el punto de vista del usuario. La importancia de la marca, la visi\u00f3n, la tecnolog\u00eda, el trato al cliente y la experiencia dentro de la franquicia tambi\u00e9n tuvieron su hueco en formato de ponencia o mesa redonda.<\/p>\n<p>En cuanto a los proveedores asistentes, no faltaron los grandes de la maquinaria del sector: LifeFitness y Precor. Tambi\u00e9n otros partners de la franquicia como ControlGroup, Harlands, Membr, Atipic, GHSports, CardioSafe, WeFitter, Banco Sabadell, Nutrisport o Pure Fitness, quien adem\u00e1s recibi\u00f3 el premio al mejor proveedor del a\u00f1o, elegido por los franquiciados de nuestro territorio por la calidad de sus productos y su servicio. Otros premiados durante la ceremonia de los Runningman Awards celebrada durante este encuentro fueron: Anytime Fitness C\u00e1diz \u2013que se llev\u00f3 el premio al mejor club 2017-, Daniel Oses \u2013 premio al mejor Club Manager del a\u00f1o, de Anytime Fitness Sant Cugat-, Mauro Espita \u2013 como mejor entrenador personal del a\u00f1o, de Anytime Fitness Lagasca-, Pere Brualla \u2013 como caso de \u00e9xito del a\u00f1o, con una preciosa historia de superaci\u00f3n y lucha- y un \u00faltimo premio especial por su compromiso y contribuci\u00f3n a la marca para la club manager Cecibell C\u00e1ceres, de Anytime Fitness Lagasca.<\/p>\n<p>Este evento se desarrolla por primera vez en la regi\u00f3n Iberia, dentro de los encuentros peri\u00f3dicos con los franquiciados que la americana lleva a cabo a lo largo del a\u00f1o y complementa a los ciclos formativos <em>Vitales <\/em>que ya celebra desde hace a\u00f1os.<\/p>\n<p>\u201cVivimos un importante momento de la franquicia y era importante juntar a todos nuestros franquiciados para hacer realidad ese t\u00f3pico del sector franquicias que habla de <em>familia<\/em>. Busc\u00e1bamos compartir experiencias, escucharlos, que nos escuchen, para poder hacer este t\u00f3pico realidad y poder seguir creciendo juntos de la mano. Este evento va un paso m\u00e1s all\u00e1 de las formaciones en operaciones que organizamos peri\u00f3dicamente con ellos; se trata de motivarles, de hacerles ver que su sue\u00f1o, nuestro sue\u00f1o, se est\u00e1 convirtiendo en una realidad y que cerraremos el a\u00f1o siendo el l\u00edder del fitness de conveniencia en Espa\u00f1a\u201d \u2013 se\u00f1ala Emilio Quero.<\/p>\n<p>La franquicia acaba de inaugurar en menos de un mes tres nuevos clubes en El Prat, Gand\u00eda y Vilanova i la Geltr\u00fa, y prepara la apertura de otros tantos en diferentes provincias espa\u00f1olas, entre las que cabe destacar Madrid, Barcelona y Huelva, donde la franquicia aterrizar\u00e1 por primera vez en los pr\u00f3ximos meses de la mano de un franquiciado que ya tiene otros dos clubes operativos. Su objetivo: alcanzar los 250 clubes en Espa\u00f1a en menos de 5 a\u00f1os.<\/p>\n<p><strong>Notas para el editor:<\/strong><\/p>\n<ul>\n<li>La franquicia Anytime Fitness es la cadena de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes repartidos por m\u00e1s de 25 pa\u00edses, en los que entrenan para mejorar su calidad de vida m\u00e1s de 3 millones de socios, personas corrientes que apuestan por un presente y futuro mejor a trav\u00e9s del deporte.<\/li>\n<li>En Espa\u00f1a hoy cuenta con 36 clubes operativos, cuatro de los cuales son propiedad de la franquicia, y m\u00e1s de 60 territorios reservados.<\/li>\n<li>La franquicia naci\u00f3 en Minnesota, donde se encuentra su sede central, gracias a la visi\u00f3n de tres apasionados del mundo del fitness: Dave Mortensen, Chuck Runyon y Jeff Klinger.<\/li>\n<li>Su crecimiento exponencial les ha situado como la franquicia de m\u00e1s r\u00e1pido crecimiento de la historia, alcanzando en tan solo 13 a\u00f1os las 3.000 unidades operativas.<\/li>\n<li>Nombrada tres a\u00f1os consecutivos la mejor franquicia global por la revista Entrepreneur: 2014, 2015 y 2016.<\/li>\n<li>Galardonada en 2016 por Club Fitness Internacional entre los cuatro primeros puestos en las categor\u00edas: Mejor franquicia #1, M\u00e1s r\u00e1pido crecimiento #1, Ganancias #2 y Mayor n\u00famero de socios #4.<\/li>\n<li>ANYTIME FITNESS es una marca registrada de Self Esteem Brands\u2122 Company.<\/li>\n<li>Para m\u00e1s informaci\u00f3n acerca de la franquicia Anytime Fitness, puede visitar nuestra web <a href=\"http:\/\/www.anytimefitness.es\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff6600;\"><strong>www.anytimefitness.es<\/strong><\/span><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre<\/p>\n","protected":false},"author":1,"featured_media":74033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-74032","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-21T11:46:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-21T11:46:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#listItem\",\"name\":\"Anytime Fitness celebra su I Conferencia Anual en Espa\\u00f1a\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#listItem\",\"position\":3,\"name\":\"Anytime Fitness celebra su I Conferencia Anual en Espa\\u00f1a\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#newsarticle\",\"name\":\"Anytime Fitness celebra su I Conferencia Anual en Espa\\u00f1a | Cand\\u00e1s 365\",\"headline\":\"Anytime Fitness celebra su I Conferencia Anual en Espa\\u00f1a\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/1497889126.jpg\",\"width\":1200,\"height\":675},\"datePublished\":\"2017-06-21T11:46:38+02:00\",\"dateModified\":\"2017-06-21T11:46:38+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el junio 21, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/\",\"name\":\"Anytime Fitness celebra su I Conferencia Anual en Espa\\u00f1a | Cand\\u00e1s 365\",\"description\":\"Anytime Fitness, la franquicia de gimnasios de conveniencia m\\u00e1s grande del mundo, con m\\u00e1s de 3.600 clubes operativos en m\\u00e1s de 25 pa\\u00edses de los cinco continentes, celebr\\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\\u00e1s de 250 asistentes, entre\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/1497889126.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#mainImage\",\"width\":1200,\"height\":675},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\\\/#mainImage\"},\"datePublished\":\"2017-06-21T11:46:38+02:00\",\"dateModified\":\"2017-06-21T11:46:38+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365","description":"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre","canonical_url":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#listItem","name":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#listItem","position":3,"name":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#newsarticle","name":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365","headline":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg","width":1200,"height":675},"datePublished":"2017-06-21T11:46:38+02:00","dateModified":"2017-06-21T11:46:38+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el junio 21, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#webpage","url":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/","name":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365","description":"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg","@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#mainImage","width":1200,"height":675},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/#mainImage"},"datePublished":"2017-06-21T11:46:38+02:00","dateModified":"2017-06-21T11:46:38+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365","og:description":"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre","og:url":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg","og:image:width":1200,"og:image:height":675,"article:published_time":"2017-06-21T11:46:38+00:00","article:modified_time":"2017-06-21T11:46:38+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a | Cand\u00e1s 365","twitter:description":"Anytime Fitness, la franquicia de gimnasios de conveniencia m\u00e1s grande del mundo, con m\u00e1s de 3.600 clubes operativos en m\u00e1s de 25 pa\u00edses de los cinco continentes, celebr\u00f3 la pasada semana en Sitges su I Conferencia Anual de franquiciados Anytime Fitness Iberia. Con la vista puesta en el nuevo curso, m\u00e1s de 250 asistentes, entre","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497889126.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"74032","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 16:47:08","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:58:36","updated":"2025-08-25 16:47:08"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAnytime Fitness celebra su I Conferencia Anual en Espa\u00f1a\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Anytime Fitness celebra su I Conferencia Anual en Espa\u00f1a","link":"https:\/\/candas365.es\/noticias\/anytime-fitness-celebra-su-i-conferencia-anual-en-espana\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=74032"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/74032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/74033"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=74032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=74032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=74032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}