{"id":73924,"date":"2017-06-20T13:39:24","date_gmt":"2017-06-20T13:39:24","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=73924"},"modified":"2017-06-20T13:39:24","modified_gmt":"2017-06-20T13:39:24","slug":"documentos-legales-a-medida","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/","title":{"rendered":"Documentos legales a medida"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-73925\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos-360x123.jpg\" alt=\"\" width=\"360\" height=\"123\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos-360x123.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg 646w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente<\/p>\n<p>La start up <span style=\"color: #ff6600;\"><a href=\"https:\/\/www.milcontratos.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">MILCONTRATOS.COM<\/span><\/a><\/span> ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad de acudir a un abogado. Para conseguirlo, esta startup cuenta con una base de datos de m\u00e1s de 1.200 \u00a0contratos y documentos legales diferentes y accesibles que se pueden adquirir por un precio muy bajo, ya que el coste de los mismos empieza desde los cinco euros.<\/p>\n<p>De este modo y adem\u00e1s de los contratos est\u00e1ndar elaborados por el equipo de <b>Milcontratos.com<\/b>, que est\u00e1 formado por expertos en Derecho, Inform\u00e1tica y Comunicaci\u00f3n, la herramienta digital permite la creaci\u00f3n de documentos legales y la personalizaci\u00f3n de los mismos,adaptandolos a \u00a0las necesidades de los clientes.<\/p>\n<p>\u201cEl usuario puede descargarse y modificar los contratos y documentos en formatos WORD y PDF, personaliz\u00e1ndolos y creando documentos legales a medida\u201d, explican desde esta startup. Asimismo, los responsables tambi\u00e9n inciden en que en caso de que los usuarios tengan dudas a la hora de crear un contrato a medida <b><i>\u201c<\/i><\/b><i>tenemos un servicio de asesoramiento y de redacci\u00f3n del contrato o documento por abogados que pueden estudiar cada caso personalmente, ayudando a realizar los cambios pertinentes\u201d<\/i>. Esta consulta tambi\u00e9n se puede realizar a trav\u00e9s de un chat online sin coste alguno.<\/p>\n<p>Toda la base de datos de <b>Milcontratos.com<\/b> cuenta con <a href=\"https:\/\/www.milcontratos.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">documentos legales creados por abogados<\/span><\/a> y todos los contratos y documentos que est\u00e1n en esta plataforma tienen plena validez legal. <b><i>\u201cTodos nuestros documentos est\u00e1n constantemente actualizados por abogados de acuerdo a la ley vigente y pueden ser firmados digitalmente<\/i><\/b>\u201d, explican desde la compa\u00f1\u00eda.<\/p>\n<p>Entre los contratos disponibles, <b>Milcontratos.com<\/b> cuenta, por ejemplo, documentos sobre el c\u00e1lculo y devoluci\u00f3n de cantidades por aplicaci\u00f3n de la cl\u00e1usula suelo, as\u00ed como contratos de confidencialidad, de arras penitenciales para compraventa de vivienda. Tambi\u00e9n hay contratos de pr\u00e9stamo, de estatutos de sociedad limitada y de arrendamiento.<\/p>\n<p><i>\u201cCon nuestra plataforma facilitamos el acceso a documentos legales mediante la cumplimentaci\u00f3n de diferentes campos en un tiempo r\u00e9cord, sin los elevados costes que tiene la visita a un abogado y, por tanto, haci\u00e9ndolos m\u00e1s accesibles a toda la poblaci\u00f3n\u201d<\/i>, recalcan desde <b>Milcontratos.com<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad<\/p>\n","protected":false},"author":1,"featured_media":73925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-73924","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Documentos legales a medida | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"646\" \/>\n\t\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-20T13:39:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-20T13:39:24+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Documentos legales a medida | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#listItem\",\"name\":\"Documentos legales a medida\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#listItem\",\"position\":3,\"name\":\"Documentos legales a medida\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#newsarticle\",\"name\":\"Documentos legales a medida | Cand\\u00e1s 365\",\"headline\":\"Documentos legales a medida\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/milcontratos.jpg\",\"width\":646,\"height\":220},\"datePublished\":\"2017-06-20T13:39:24+02:00\",\"dateModified\":\"2017-06-20T13:39:24+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el junio 20, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/\",\"name\":\"Documentos legales a medida | Cand\\u00e1s 365\",\"description\":\"La start up Milcontratos.com cuenta con una base de datos de m\\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\\u00e1pido, sencillo y econ\\u00f3mico sin necesidad\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/milcontratos.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#mainImage\",\"width\":646,\"height\":220},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/documentos-legales-a-medida\\\/#mainImage\"},\"datePublished\":\"2017-06-20T13:39:24+02:00\",\"dateModified\":\"2017-06-20T13:39:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Documentos legales a medida | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Documentos legales a medida | Cand\u00e1s 365","description":"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad","canonical_url":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#listItem","name":"Documentos legales a medida"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#listItem","position":3,"name":"Documentos legales a medida","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#newsarticle","name":"Documentos legales a medida | Cand\u00e1s 365","headline":"Documentos legales a medida","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg","width":646,"height":220},"datePublished":"2017-06-20T13:39:24+02:00","dateModified":"2017-06-20T13:39:24+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el junio 20, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#webpage","url":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/","name":"Documentos legales a medida | Cand\u00e1s 365","description":"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg","@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#mainImage","width":646,"height":220},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/#mainImage"},"datePublished":"2017-06-20T13:39:24+02:00","dateModified":"2017-06-20T13:39:24+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Documentos legales a medida | Cand\u00e1s 365","og:description":"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad","og:url":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg","og:image:width":646,"og:image:height":220,"article:published_time":"2017-06-20T13:39:24+00:00","article:modified_time":"2017-06-20T13:39:24+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Documentos legales a medida | Cand\u00e1s 365","twitter:description":"La start up Milcontratos.com cuenta con una base de datos de m\u00e1s de 1.200 documentos legales elaborados por abogados que se pueden adaptar a las necesidades de cada cliente La start up MILCONTRATOS.COM ha desarrollado una herramienta digital que permite adquirir, crear y personalizar documentos legales de un modo r\u00e1pido, sencillo y econ\u00f3mico sin necesidad","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/milcontratos.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"73924","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 16:39:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:58:42","updated":"2025-08-25 16:39:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDocumentos legales a medida\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Documentos legales a medida","link":"https:\/\/candas365.es\/noticias\/documentos-legales-a-medida\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/73924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=73924"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/73924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/73925"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=73924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=73924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=73924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}