{"id":73454,"date":"2017-06-13T10:58:26","date_gmt":"2017-06-13T10:58:26","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=73454"},"modified":"2017-06-13T10:58:26","modified_gmt":"2017-06-13T10:58:26","slug":"la-alfombra-de-crevillente-se-pone-de-moda","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/","title":{"rendered":"La alfombra de Crevillente se pone de moda"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-73455\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327-90x67.jpg 90w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg 1024w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y seguir siendo referencia en el sector.<\/p>\n<p>Crevillente, Ciudad de la Alfombra, seg\u00fan cifras de UNIFAM, ha conseguido aumentar en un 100% las exportaciones en los \u00faltimos cinco a\u00f1os, gracias en gran medida a la apuesta por el reconocimiento de la marca, asociada a tradici\u00f3n, calidad y prestigio. UNIFAM es la asociaci\u00f3n empresarial que agrupa y representa a los fabricantes de esta localidad.<\/p>\n<p>Este a\u00f1o, uno de sus principales fabricantes por tradici\u00f3n y calidad ha apostado por la elaboraci\u00f3n de un nuevo modelo de cat\u00e1logo, incorporando a los nuevos dise\u00f1os las tendencias en moda de ferias internacionales en el sector, y no solo de la alfombra sino del textil y el hogar.<\/p>\n<p>Seg\u00fan palabras del gerente de <strong><a href=\"http:\/\/alfombrashispania.com\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"color: #ff6600;\">Alfombras Hispania<\/span><\/a><\/strong>, Alfredo Rodr\u00edguez Cerd\u00e1, empresa fabricante que lidera este proyecto: \u201cha sido todo un desaf\u00edo: hemos tenido que emplear mucho tiempo y recursos, as\u00ed como visitar ferias internacionales y asesorarnos con profesionales del interiorismo para poder ofrecer las tendencias y los nuevos dise\u00f1os. Verdaderamente este a\u00f1o podemos hablar de moda 2017 en la alfombra\u201d.<\/p>\n<p><strong>La moda y tendencias en la alfombra este 2017<\/strong><\/p>\n<p>En los \u00faltimos a\u00f1os, en el sector de la alfombra y moqueta, han ido ganando peso los tejidos de un solo tono, en una amplia gama de colores, manteni\u00e9ndose la tendencia en el periodo actual. Aunque se mantienen con derecho propio (as\u00ed lo demuestran las cifras de ventas), los dise\u00f1os cl\u00e1sicos, conocidos por sus motivos arabescos, los cuales tienen nicho de mercado propio y bastante estabilizado.<\/p>\n<p>Por otro lado, en el sector profesional, el cual tambi\u00e9n representa un importante porcentaje de volumen, cada vez se apuesta m\u00e1s por la personalizaci\u00f3n y los dise\u00f1os a medida, siguiendo en parte las tendencias, pero aportando personalizaci\u00f3n tanto en formas, como en motivos y grabados.<\/p>\n<p>Sobre las tendencias en los colores de este a\u00f1o, Alfredo Rodr\u00edguez destaca que \u201cen los ambientes modernos el verde es el protagonista a nivel internacional, aunque tambi\u00e9n se va a apostar fuerte por el mostaza y el azul cobalto\u201d.<\/p>\n<p>Tambi\u00e9n se ve una clara evoluci\u00f3n en las formas: \u201clos dise\u00f1os circulares son una opci\u00f3n que est\u00e1 cobrando mucho peso este a\u00f1o. Destacan, por otro lado, las alfombras de pasillo, en muchas ocasiones elaboradas a medida para el cliente profesional, como hoteles, iglesias, etc.\u201d.<\/p>\n<p>Se hace dif\u00edcil una pasarela con alfombras, pero s\u00ed se han realizado unos espectaculares <em>shooting moda<\/em> (sesiones fotogr\u00e1ficas) en distintos ambientes muy especiales, para resaltar las bondades de cada alfombra y permitir la visualizaci\u00f3n del producto en una estancia real.<\/p>\n<p>La marcas <em>Alfombras de Crevillente<\/em> y Made in Spain hoy en d\u00eda ya son reconocidas a nivel internacional. Este fabricante crevillentino aspira adem\u00e1s, a ser un aut\u00e9ntico referente en las tendencias de moda del sector en unos a\u00f1os, y en su apuesta por ello ya trabaja en novedades de cara a la pr\u00f3xima temporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y<\/p>\n","protected":false},"author":1,"featured_media":73455,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-73454","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-13T10:58:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-13T10:58:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#listItem\",\"name\":\"La alfombra de Crevillente se pone de moda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#listItem\",\"position\":3,\"name\":\"La alfombra de Crevillente se pone de moda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#newsarticle\",\"name\":\"La alfombra de Crevillente se pone de moda | Cand\\u00e1s 365\",\"headline\":\"La alfombra de Crevillente se pone de moda\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/1497274327.jpg\",\"width\":1024,\"height\":768},\"datePublished\":\"2017-06-13T10:58:26+02:00\",\"dateModified\":\"2017-06-13T10:58:26+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el junio 13, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/\",\"name\":\"La alfombra de Crevillente se pone de moda | Cand\\u00e1s 365\",\"description\":\"En la Alfombra de Crevillente, uno de los n\\u00facleos principales de producci\\u00f3n a nivel nacional, llevan a\\u00f1os apostando por la calidad, los dise\\u00f1os exclusivos y los servicios de valor a\\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\\u00e1 dando hoy en d\\u00eda, contin\\u00faan desarrollando estrategias para dar un paso adelante y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/1497274327.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#mainImage\",\"width\":1024,\"height\":768},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-alfombra-de-crevillente-se-pone-de-moda\\\/#mainImage\"},\"datePublished\":\"2017-06-13T10:58:26+02:00\",\"dateModified\":\"2017-06-13T10:58:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La alfombra de Crevillente se pone de moda | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365","description":"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y","canonical_url":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#listItem","name":"La alfombra de Crevillente se pone de moda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#listItem","position":3,"name":"La alfombra de Crevillente se pone de moda","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#newsarticle","name":"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365","headline":"La alfombra de Crevillente se pone de moda","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg","width":1024,"height":768},"datePublished":"2017-06-13T10:58:26+02:00","dateModified":"2017-06-13T10:58:26+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el junio 13, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/","name":"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365","description":"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg","@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#mainImage","width":1024,"height":768},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/#mainImage"},"datePublished":"2017-06-13T10:58:26+02:00","dateModified":"2017-06-13T10:58:26+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365","og:description":"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y","og:url":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg","og:image:width":1024,"og:image:height":768,"article:published_time":"2017-06-13T10:58:26+00:00","article:modified_time":"2017-06-13T10:58:26+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La alfombra de Crevillente se pone de moda | Cand\u00e1s 365","twitter:description":"En la Alfombra de Crevillente, uno de los n\u00facleos principales de producci\u00f3n a nivel nacional, llevan a\u00f1os apostando por la calidad, los dise\u00f1os exclusivos y los servicios de valor a\u00f1adido con los clientes, pero ante una competencia tan encarnizada como se est\u00e1 dando hoy en d\u00eda, contin\u00faan desarrollando estrategias para dar un paso adelante y","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/06\/1497274327.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"73454","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 16:07:46","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:59:06","updated":"2025-08-25 16:07:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa alfombra de Crevillente se pone de moda\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"La alfombra de Crevillente se pone de moda","link":"https:\/\/candas365.es\/noticias\/la-alfombra-de-crevillente-se-pone-de-moda\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/73454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=73454"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/73454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/73455"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=73454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=73454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=73454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}