{"id":72396,"date":"2017-05-26T22:31:20","date_gmt":"2017-05-26T22:31:20","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=72396"},"modified":"2017-05-26T22:31:20","modified_gmt":"2017-05-26T22:31:20","slug":"clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/","title":{"rendered":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-72397\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-360x225.jpg\" alt=\"\" width=\"360\" height=\"225\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-360x225.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-768x480.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-655x409.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-696x435.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-672x420.jpg 672w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull-279x173.jpg 279w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg 1000w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull.<\/p>\n<p>En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica Curull presenta diferentes propuestas. Igualmente, durante la consulta, el equipo m\u00e9dico eval\u00faa cada caso, pues cada uno de ellos es particular y tendr\u00e1 una intervenci\u00f3n adaptada.<\/p>\n<p>\u20222 meses antes<\/p>\n<p><strong>Dise\u00f1o de la sonrisa<\/strong><\/p>\n<p>El Digital Smile Design (DSD) o An\u00e1lisis Digital de la Sonrisa es una t\u00e9cnica que dise\u00f1a la sonrisa ideal para cada paciente considerando sus caracter\u00edsticas faciales, sus movimientos al hablar o sus gestos de expresi\u00f3n. Utilizando fotos e im\u00e1genes en v\u00eddeo de la persona, se realiza un estudio est\u00e9tico facial y dental individualizado. Para la Dra. Curull, fundadora de la Cl\u00ednica Curull, la clave de este tratamiento de est\u00e9tica dental es que \u201cantes de iniciarlo, el paciente puede saber cu\u00e1l va a ser el resultado final\u201d. Adem\u00e1s, se lleva a cabo una maqueta o provisional instant\u00e1neo, lo que permite ver c\u00f3mo se integra ese tratamiento en el rostro de la persona que va a ser tratada. Cabe remarcar que el An\u00e1lisis Digital de la Sonrisa es la t\u00e9cnica id\u00f3nea para todo aquel que quiera someterse a un tratamiento de est\u00e9tica m\u00e1s global. Tambi\u00e9n es muy personalizado, por lo que, en funci\u00f3n de las necesidades de cada uno, ser\u00e1 m\u00e1s o menos prolongado.<\/p>\n<p>\u20221 mes antes<\/p>\n<p><strong>Limpieza bucal<\/strong><\/p>\n<p>La limpieza bucal sirve para eliminar el sarro que est\u00e1 en la superficie de los dientes, as\u00ed como las tinciones o manchas provocadas por agentes externos como el tabaco, el caf\u00e9 o el vino. \u201cEn la Cl\u00ednica Curull aprovechamos este tratamiento para repasar junto con el paciente las t\u00e9cnicas de cepillado y para asegurarnos de que la pasta dent\u00edfrica, el cepillo o el colutorio que usa son los adecuados. Si adem\u00e1s coincide con el verano, le damos consejos sobre la dieta como no ingerir alimentos muy \u00e1cidos o evitar cosas fr\u00edas, no morder hielo o no abusar de las bebidas isot\u00f3nicas que son muy azucaradas\u201d, se\u00f1ala Conchita Curull.<\/p>\n<p>Por otra parte, la doctora indica que es aconsejable realizarse dos limpiezas al a\u00f1o y que una sea antes del verano, ya que puede ayudar a detectar alg\u00fan problema bucodental que pueda afectar negativamente al paciente durante las vacaciones.<\/p>\n<p><strong>Blanqueamiento dental<\/strong><\/p>\n<p>El blanqueamiento dental es una buena opci\u00f3n para aquellos dientes sanos que con el paso del tiempo han sufrido una modificaci\u00f3n en su color. Esto puede deberse al caf\u00e9, al t\u00e9, al tabaco o a medicamentos como la tetraciclina. En la Cl\u00ednica Curull este tratamiento se lleva a cabo aplicando geles blanqueadores que liberan ox\u00edgeno y producen un efecto blanqueador. Posteriormente, el paciente debe continuar con el tratamiento blanqueador en casa. Para ello, se le suministra un kit de blanqueamiento y se le proporcionan instrucciones detalladas del proceso que debe seguir. La Dra. Curull advierte que \u201cesta fase de blanqueamiento domiciliario es muy importante, ya que, en gran medida, el \u00e9xito total de este tratamiento depender\u00e1 de ello\u201d.<\/p>\n<p>El blanqueamiento dental tiene una duraci\u00f3n de entre uno y tres a\u00f1os y, tras la primera sesi\u00f3n, los resultados suelen ser visibles. Al tratarse de una t\u00e9cnica muy personalizada, el n\u00famero de sesiones var\u00eda en funci\u00f3n de las necesidades del paciente. Sin embargo, siempre es combinado, es decir, una primera parte se realiza en la cl\u00ednica y una segunda en casa. Tambi\u00e9n es imprescindible que el paciente tenga una boca sana, sin caries ni enfermedades periodontales.<\/p>\n<p>Durante el blanqueamiento dental e inmediatamente despu\u00e9s de \u00e9ste, Curull recomienda \u201cevitar la ingesta de bebidas o alimentos con efecto colorante como el caf\u00e9, el vino tinto, la salsa de soja, la remolacha, las alcachofas, los frutos rojos, las nueces, etc. Tambi\u00e9n se deben obviar los alimentos y las bebidas que sean \u00e1cidas o que est\u00e9n heladas\u201d.<\/p>\n<p>\u202215 d\u00edas antes<\/p>\n<p><strong>Carillas de cer\u00e1mica o de composite<\/strong><\/p>\n<p>Las carillas dentales se usan para corregir dientes fracturados, oscuros o con manchas, desgastados, torcidos, desiguales y separados. Hay dos tipos de carillas, las de cer\u00e1mica y las de composite. Las primeras son unas finas l\u00e1minas de cer\u00e1mica que se adhieren a la superficie del diente. Generalmente, sustituyen la cara visible de la pieza dental consiguiendo importantes mejoras de su posici\u00f3n, color y forma, con un m\u00ednimo desgaste del diente. \u201cLas carillas de porcelana destacan por su poder de adhesi\u00f3n, resistencia al desgaste y la gran sensaci\u00f3n de est\u00e9tica que generan. Con ellas, siempre se mantendr\u00e1 el mismo color y brillo\u201d, explica Conchita Curull.<\/p>\n<p>Por su parte, las carillas de composite son materiales est\u00e9ticos que se adhieren al esmalte. Al igual que las anteriores, son \u00fatiles para modificar la forma y la anatom\u00eda de los dientes o para reparar dientes fracturados. La diferencia reside en que son m\u00e1s econ\u00f3micas y que con el tiempo se desgastan y su color var\u00eda. En este sentido, la doctora puntualiza que \u201csi el paciente busca est\u00e9tica, lo mejor son las de porcelana, y si busca un tratamiento econ\u00f3mico, las de composite\u201d.<\/p>\n<p>Para ponerse carillas son necesarias dos sesiones, y una vez colocadas, se puede hacer vida normal. Los resultados son visibles inmediatamente despu\u00e9s de la implantaci\u00f3n, que es indolora. Su duraci\u00f3n var\u00eda en funci\u00f3n de si son de porcelana o de composite; mientras que las primeras tienen una vida de m\u00e1s de 10 a\u00f1os, la duraci\u00f3n de las segundas depender\u00e1 de los h\u00e1bitos del paciente.<\/p>\n<p>En opini\u00f3n de la Dra. Curull, \u201ccon ambos tratamientos el resultado son unos dientes m\u00e1s blancos, m\u00e1s uniformes y m\u00e1s bonitos, pero la clave reside en que el aspecto es totalmente natural\u201d.<\/p>\n<p>\u2022En el d\u00eda a d\u00eda<\/p>\n<p><strong>Una correcta higiene diaria y acudir al dentista de forma regular<\/strong><\/p>\n<p>La clave para mantener una boca sana y lucir una bonita sonrisa reside en mantener una correcta higiene diaria, lo que incluye una buena t\u00e9cnica de cepillado, el correcto uso del hilo dental y un uso adecuado de colutorios. As\u00ed lo asegura Conchita Curull, quien adem\u00e1s recomienda visitar al dentista dos veces al a\u00f1o para poder evitar o minimizar futuros problemas dentales.<\/p>\n<p><strong>Cl\u00ednica Curull<\/strong><\/p>\n<p>Cl\u00ednica Curull es un centro privado de referencia en odontolog\u00eda avanzada y en tratamiento de diversas patolog\u00edas relacionadas con la salud bucodental. Fundada en Tarragona en el a\u00f1o 1995 por la Dra. Conchita Curull Gasol, ha tratado a m\u00e1s de 10.000 pacientes y cuenta con un amplio equipo humano formado por odont\u00f3logos y personal sanitario con una gran experiencia en implantes dentales, periodoncia, odontolog\u00eda integrada y est\u00e9tica dental.<\/p>\n<p>En Cl\u00ednica Curull se trabaja con un gran compromiso con los pacientes, a los que se les ofrece un tratamiento personalizado y un trato cercano. Su equipo trabaja con el m\u00e1ximo rigor cient\u00edfico y con las t\u00e9cnicas m\u00e1s avanzadas en est\u00e9tica dental para ofrecer soluciones dise\u00f1adas y personalizadas, as\u00ed como diferentes tratamientos para las enc\u00edas o el bruxismo, entre otras patolog\u00edas. El centro se ha caracterizado siempre por su apuesta constante por las tecnolog\u00edas m\u00e1s innovadoras en odontolog\u00eda y est\u00e9tica bucal para mantenerse en la vanguardia del sector. Varios servicios sit\u00faan Cl\u00ednica Curull en la excelencia del sector, como el An\u00e1lisis Digital de la Sonrisa, un revolucionario sistema que permite dise\u00f1ar la sonrisa ideal para cada paciente, o los implantes y dientes en un d\u00eda.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica<\/p>\n","protected":false},"author":1,"featured_media":72397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-72396","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-05-26T22:31:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-26T22:31:20+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#listItem\",\"name\":\"Cl\\u00ednica Curull propone 5 tratamientos de est\\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#listItem\",\"position\":3,\"name\":\"Cl\\u00ednica Curull propone 5 tratamientos de est\\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#newsarticle\",\"name\":\"Cl\\u00ednica Curull propone 5 tratamientos de est\\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\\u00e1s 365\",\"headline\":\"Cl\\u00ednica Curull propone 5 tratamientos de est\\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495704074_Cl_nica_Curull.jpg\",\"width\":1000,\"height\":625},\"datePublished\":\"2017-05-26T22:31:20+02:00\",\"dateModified\":\"2017-05-26T22:31:20+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el mayo 26, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/\",\"name\":\"Cl\\u00ednica Curull propone 5 tratamientos de est\\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\\u00e1s 365\",\"description\":\"La Cl\\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \\u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\\u00edr\\u201d, se\\u00f1ala la Dra. Curull. En funci\\u00f3n de los objetivos y la antelaci\\u00f3n, la Cl\\u00ednica\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495704074_Cl_nica_Curull.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#mainImage\",\"width\":1000,\"height\":625},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\\\/#mainImage\"},\"datePublished\":\"2017-05-26T22:31:20+02:00\",\"dateModified\":\"2017-05-26T22:31:20+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365","description":"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica","canonical_url":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#listItem","name":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#listItem","position":3,"name":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#newsarticle","name":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365","headline":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg","width":1000,"height":625},"datePublished":"2017-05-26T22:31:20+02:00","dateModified":"2017-05-26T22:31:20+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el mayo 26, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#webpage","url":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/","name":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365","description":"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg","@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#mainImage","width":1000,"height":625},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/#mainImage"},"datePublished":"2017-05-26T22:31:20+02:00","dateModified":"2017-05-26T22:31:20+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365","og:description":"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica","og:url":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg","og:image:width":1000,"og:image:height":625,"article:published_time":"2017-05-26T22:31:20+00:00","article:modified_time":"2017-05-26T22:31:20+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones | Cand\u00e1s 365","twitter:description":"La Cl\u00ednica Curull lanza diferentes propuestas para tener una buena salud bucodental y presumir de sonrisa este verano. \u201cUna sonrisa perfecta va a reforzar nuestra autoestima, har\u00e1 que nos sintamos mejor con nosotros mismos y que descubramos el placer de sonre\u00edr\u201d, se\u00f1ala la Dra. Curull. En funci\u00f3n de los objetivos y la antelaci\u00f3n, la Cl\u00ednica","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495704074_Cl_nica_Curull.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"7 minutos"},"aioseo_meta_data":{"post_id":"72396","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 14:51:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:59:47","updated":"2025-08-25 14:51:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Cl\u00ednica Curull propone 5 tratamientos de est\u00e9tica dental para conseguir la mejor sonrisa antes de las vacaciones","link":"https:\/\/candas365.es\/noticias\/clinica-curull-propone-5-tratamientos-de-estetica-dental-para-conseguir-la-mejor-sonrisa-antes-de-las-vacaciones\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=72396"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/72397"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=72396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=72396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=72396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}