{"id":72300,"date":"2017-05-25T13:17:00","date_gmt":"2017-05-25T13:17:00","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=72300"},"modified":"2017-05-25T13:17:00","modified_gmt":"2017-05-25T13:17:00","slug":"lumion-es-finalista-de-los-premios-bbconstrumat-2017","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/","title":{"rendered":"Lumion es finalista de los premios BBConstrumat 2017"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-72301\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-360x203.jpg\" alt=\"\" width=\"360\" height=\"203\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-360x203.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg 1920w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-768x432.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-655x368.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-696x392.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-1068x601.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-747x420.jpg 747w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p-499x280.jpg 499w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en la categor\u00eda de Producto y\/o Material Innovador por su desarrollo en las condiciones de habitabilidad del usuario final.<\/p>\n<p>Con usuarios en m\u00e1s de 100 pa\u00edses de todo el mundo, Lumion es un software altamente intuitivo, con el que cualquiera es capaz de realizar videos, im\u00e1genes y vistas panor\u00e1micas de 360\u00ba sin necesidad de experiencia previa o conocimientos avanzados en programas de estas caracter\u00edsticas. Gracias al renderizado en tiempo real, Lumion permite interactuar simult\u00e1neamente con el cliente, habl\u00e1ndole en su propio lenguaje y haciendo el proyecto f\u00e1cilmente entendible para todo el mundo.<\/p>\n<p>En palabras de Eugenio Donado, CEO de Lumion Espa\u00f1a, \u00abLumion es como jugar a un videojuego de arquitectura\u00bb.<\/p>\n<p>Como alternativa a los motores tradicionales de renderizado, Lumion es un sue\u00f1o hecho realidad para los profesionales del sector AEC. Antes, el renderizado de un proyecto pod\u00eda convertirse en un proceso demasiado complicado. Ahora, con Lumion, puedes hacerlo todo t\u00fa mismo, crear paso a paso el dise\u00f1o, compartir en tiempo real, visualizar cambios de forma instant\u00e1nea con el plug-in LiveSync para Revit incluido en la \u00faltima versi\u00f3n de Lumion 7.3 y producir renders incre\u00edbles de forma r\u00e1pida y \u00e1gil.<\/p>\n<p>Adem\u00e1s, el alto grado de realismo es otra de las grandes ventajas que ofrece Lumion frente a otros softwares competidores en el mercado. Los proyectos realizados en Lumion son f\u00e1cilmente identificables, porque respiran vida propia, gracias a su amplia biblioteca de materiales, entre los que puedes elegir todo tipo de vegetaci\u00f3n, personajes, veh\u00edculos, efectos meteorol\u00f3gicos, etc.<\/p>\n<p>Perfectamente adaptado para presentaciones hiper-realistas en v\u00eddeo y demostraciones en vivo con una respuesta inmediata, Lumion ofrece compatibilidad con la mayor\u00eda de los programas de modelado 3D: Revit, Sketchup, AutoCAD, ArchiCAD, 3D Studio, Allplan, Rhinoceros, etc, convirti\u00e9ndose en el software complementario ideal para la presentaci\u00f3n de todo tipo de proyectos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en<\/p>\n","protected":false},"author":1,"featured_media":72301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-72300","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-05-25T13:17:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-25T13:17:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#listItem\",\"name\":\"Lumion es finalista de los premios BBConstrumat 2017\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#listItem\",\"position\":3,\"name\":\"Lumion es finalista de los premios BBConstrumat 2017\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#newsarticle\",\"name\":\"Lumion es finalista de los premios BBConstrumat 2017 | Cand\\u00e1s 365\",\"headline\":\"Lumion es finalista de los premios BBConstrumat 2017\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495642595_Curtains_0303_1080p.jpg\",\"width\":1920,\"height\":1080},\"datePublished\":\"2017-05-25T13:17:00+02:00\",\"dateModified\":\"2017-05-25T13:17:00+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el mayo 25, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/\",\"name\":\"Lumion es finalista de los premios BBConstrumat 2017 | Cand\\u00e1s 365\",\"description\":\"El software de visualizaci\\u00f3n arquitect\\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\\u00e1cter pr\\u00e1ctico, y capacidad innovadora son las principales caracter\\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495642595_Curtains_0303_1080p.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\\\/#mainImage\"},\"datePublished\":\"2017-05-25T13:17:00+02:00\",\"dateModified\":\"2017-05-25T13:17:00+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365","description":"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en","canonical_url":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#listItem","name":"Lumion es finalista de los premios BBConstrumat 2017"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#listItem","position":3,"name":"Lumion es finalista de los premios BBConstrumat 2017","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#newsarticle","name":"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365","headline":"Lumion es finalista de los premios BBConstrumat 2017","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg","width":1920,"height":1080},"datePublished":"2017-05-25T13:17:00+02:00","dateModified":"2017-05-25T13:17:00+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el mayo 25, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#webpage","url":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/","name":"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365","description":"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg","@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/#mainImage"},"datePublished":"2017-05-25T13:17:00+02:00","dateModified":"2017-05-25T13:17:00+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365","og:description":"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en","og:url":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg","og:image:width":1920,"og:image:height":1080,"article:published_time":"2017-05-25T13:17:00+00:00","article:modified_time":"2017-05-25T13:17:00+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Lumion es finalista de los premios BBConstrumat 2017 | Cand\u00e1s 365","twitter:description":"El software de visualizaci\u00f3n arquitect\u00f3nica 3D Lumion ha resultado finalista de los premios BBConstrumat 2017, otorgados en esta feria celebrada en Barcelona entre el 23 y 26 de mayo. Su funcionalidad, car\u00e1cter pr\u00e1ctico, y capacidad innovadora son las principales caracter\u00edsticas destacadas por el equipo de Construmat, presentando Lumion como uno de los mejores productos en","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495642595_Curtains_0303_1080p.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"72300","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 14:45:06","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:59:47","updated":"2025-08-25 14:45:06"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLumion es finalista de los premios BBConstrumat 2017\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Lumion es finalista de los premios BBConstrumat 2017","link":"https:\/\/candas365.es\/noticias\/lumion-es-finalista-de-los-premios-bbconstrumat-2017\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=72300"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/72301"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=72300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=72300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=72300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}