{"id":72030,"date":"2017-05-20T18:42:45","date_gmt":"2017-05-20T18:42:45","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=72030"},"modified":"2017-05-20T18:42:45","modified_gmt":"2017-05-20T18:42:45","slug":"quart-sportswear-estara-presente-en-la-sea-otter-europe","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/","title":{"rendered":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-72031\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-298x300.png\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-298x300.png 298w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-477x480.png 477w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-768x773.png 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-150x150.png 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-450x453.png 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-696x700.png 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-417x420.png 417w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988-50x50.png 50w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png 942w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo y la presentaci\u00f3n de novedades en ropa deportiva ser\u00e1n los puntos claves del estand de Quart Sportswear en esta feria dedicada al sector del ciclismo.<\/p>\n<p>La interacci\u00f3n es el concepto principal con el cual Quart Sportswear ha basado la elaboraci\u00f3n de su estand n\u00famero 5, situado junto a la recogida de los dorsales de la zona de exposici\u00f3n. En todo momento, habr\u00e1 un punto de atenci\u00f3n con un dise\u00f1ador que ofrecer\u00e1 la posibilidad de personalizar una prenda de ropa deportiva la cual se ver\u00e1 reflejada en una de las pantallas de televisi\u00f3n del estand. \u201cTodo el mundo que se acerque a nuestro estand tendr\u00e1 la posibilidad de ver in situ la capacidad ilimitada de personalizaci\u00f3n que somos capaces de ofrecer\u201d, afirma el gerente de Quart Sportswear, Francesc Com\u00ed.<\/p>\n<p>Por otro lado, Quart Sportswear tambi\u00e9n presentar\u00e1 de forma oficial cuatro innovadoras colecciones de su nuevo culotte y su nuevo maillot para los amantes del ciclismo. Esta Sea Otter Europe Costa Brava-Girona Bike Show ser\u00e1 el marco perfecto para promocionar los nuevos modelos, con dise\u00f1os rompedores, y las nuevas mejoras tanto por hombres y mujeres, a nivel de competici\u00f3n, como para los m\u00e1s peque\u00f1os, a nivel de entrenamiento. \u201cMediante el patronazgo base hemos buscado mejorar las prestaciones iniciales, que ya eran buenas, para conseguir la excelencia de un producto hasta convertirlo como una segunda piel\u201d, explica Francesc Com\u00ed.<\/p>\n<p><strong>El estand n\u00famero 5 de Quart Sportswear<\/strong><\/p>\n<p>Aparte del punto de personalizaci\u00f3n 100% en directo e ilimitado con un dise\u00f1ador permanente, el estand de Quart Sportswear contar\u00e1 con una zona informativa para explicar al cliente la singularidad del producto y el tipo de servicio que ofrece. Tambi\u00e9n, estar\u00e1 equipado con un almac\u00e9n y un probador donde los clientes que lo deseen podr\u00e1n probarse el producto all\u00ed mismo. Adem\u00e1s, tendr\u00e1n la posibilidad de escoger los nuevos modelos de maillots y culottes de ciclistas que estar\u00e1n expuestos en el mismo estand.<\/p>\n<p><em>Fuente: agencia de marketing y comunicaci\u00f3n e-deon.net<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo<\/p>\n","protected":false},"author":1,"featured_media":72031,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-72030","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"942\" \/>\n\t\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-05-20T18:42:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-20T18:42:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#listItem\",\"name\":\"Quart Sportswear estar\\u00e1 presente en la Sea Otter Europe\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#listItem\",\"position\":3,\"name\":\"Quart Sportswear estar\\u00e1 presente en la Sea Otter Europe\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#newsarticle\",\"name\":\"Quart Sportswear estar\\u00e1 presente en la Sea Otter Europe | Cand\\u00e1s 365\",\"headline\":\"Quart Sportswear estar\\u00e1 presente en la Sea Otter Europe\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495004988.png\",\"width\":942,\"height\":948},\"datePublished\":\"2017-05-20T18:42:45+02:00\",\"dateModified\":\"2017-05-20T18:42:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el mayo 20, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/\",\"name\":\"Quart Sportswear estar\\u00e1 presente en la Sea Otter Europe | Cand\\u00e1s 365\",\"description\":\"Este acontecimiento, que tiene lugar desde hace 25 a\\u00f1os en Laguna Seca (California \\u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\\u00e1s grandes y completos del mundo. La personalizaci\\u00f3n 100% en directo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1495004988.png\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#mainImage\",\"width\":942,\"height\":948},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/quart-sportswear-estara-presente-en-la-sea-otter-europe\\\/#mainImage\"},\"datePublished\":\"2017-05-20T18:42:45+02:00\",\"dateModified\":\"2017-05-20T18:42:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365","description":"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo","canonical_url":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#listItem","name":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#listItem","position":3,"name":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#newsarticle","name":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365","headline":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png","width":942,"height":948},"datePublished":"2017-05-20T18:42:45+02:00","dateModified":"2017-05-20T18:42:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el mayo 20, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#webpage","url":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/","name":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365","description":"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png","@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#mainImage","width":942,"height":948},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/#mainImage"},"datePublished":"2017-05-20T18:42:45+02:00","dateModified":"2017-05-20T18:42:45+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365","og:description":"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo","og:url":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png","og:image:width":942,"og:image:height":948,"article:published_time":"2017-05-20T18:42:45+00:00","article:modified_time":"2017-05-20T18:42:45+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe | Cand\u00e1s 365","twitter:description":"Este acontecimiento, que tiene lugar desde hace 25 a\u00f1os en Laguna Seca (California \u2013 Estados Unidos), es la primera vez que aterriza en el continente europeo y est\u00e1 considerado como uno de los festivales dedicados al ciclismo y a los deportes al aire libre m\u00e1s grandes y completos del mundo. La personalizaci\u00f3n 100% en directo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1495004988.png","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"72030","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 14:26:59","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:00:01","updated":"2025-08-25 14:26:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tQuart Sportswear estar\u00e1 presente en la Sea Otter Europe\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Quart Sportswear estar\u00e1 presente en la Sea Otter Europe","link":"https:\/\/candas365.es\/noticias\/quart-sportswear-estara-presente-en-la-sea-otter-europe\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=72030"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/72030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/72031"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=72030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=72030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=72030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}