{"id":71439,"date":"2017-05-08T19:22:12","date_gmt":"2017-05-08T19:22:12","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=71439"},"modified":"2017-05-08T19:22:12","modified_gmt":"2017-05-08T19:22:12","slug":"pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/","title":{"rendered":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-71440\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-650x432.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-768x510.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-450x299.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-655x435.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-696x462.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-1068x709.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg 1072w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado.<\/p>\n<p>PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros Hipercor como Gourmet, en tiendas bio y org\u00e1nicas, en supermercados Ulabox y tambi\u00e9n a trav\u00e9s de la web de Interflora. Adem\u00e1s de ser 100% org\u00e1nicos, PACARI cuenta con certificaciones internacionales como Certificaci\u00f3n Org\u00e1nica USDA, Certificaci\u00f3n Org\u00e1nica EU, Kosher, Biodinamico, SPP (comercio justo) y Empresa B, que reconoce el cuidado en los procesos de elaboraci\u00f3n de los chocolates.<\/p>\n<p>Seg\u00fan el estudio de la consultora Market Research Future, el mercado global de chocolate alcanzar\u00e1 en 2022 los 977 millones de d\u00f3lares si contin\u00faa las tasas de crecimiento actual que se encuentran en el 2,5% de incrementos anuales.<\/p>\n<p>Market Research Future es una prestigiosa empresa de investigaci\u00f3n de mercado en especial en el campo de la alimentaci\u00f3n y la salud, entre otros sectores. El informe publicado por Market Research Future ha tenido en cuenta aspectos fundamentales como las calor\u00edas por porci\u00f3n o la inclusi\u00f3n de nuevos sabores e ingredientes.<\/p>\n<p>Para Santiago Peralta, fundador de PACARI, \u201clos chocolates PACARI cuentan con un gran crecimiento y aceptaci\u00f3n en el mercado internacional y europeo por su calidad y por un contexto en el que el consumidor est\u00e1 interesado en consumir alimentos saludables, con gran valor nutricional y que adem\u00e1s vengan de un comercio directo y justo\u201d. Tambi\u00e9n ha destacado que \u201cen Espa\u00f1a se est\u00e1 dando un gran crecimiento de los productos gourmet y de los productos org\u00e1nicos y PACARI es al mismo tiempo una marca Premium y org\u00e1nica con chocolate de primera calidad con ingredientes y sabores innovadores y superalimentos\u201d.<\/p>\n<p>El fundador de PACARI tiene previsto visitar Espa\u00f1a del 5 al 12 de mayo con el objetivo de incrementar su distribuci\u00f3n y favorecer el conocimiento de los que han sido reconocidos como mejor chocolate en barra del mundo en las \u00faltimas ediciones de la International Chocolate Awards y que suma ya m\u00e1s de 160 premios internacionales.<\/p>\n<p><strong>PACARI<\/strong><\/p>\n<p>PACARI es una empresa familiar ecuatoriana que produce chocolate 100% org\u00e1nico de m\u00e1xima calidad, es el primer chocolate org\u00e1nico y biodin\u00e1mico de Am\u00e9rica Latina. PACARI beneficia a 3.500 familias de agricultores. PACARI est\u00e1 presente en 42 pa\u00edses alrededor del mundo, entre ellos: Suiza, B\u00e9lgica, Francia, Italia, Emiratos \u00c1rabes, Rusia, Colombia, Argentina, Estados Unidos, Espa\u00f1a, entre otros.<\/p>\n<p>PACARI ha recibido m\u00e1s de 160 premios a nivel internacional por la calidad y caracter\u00edsticas \u00fanicas de sus productos, entre los que destacan: 128 medallas de oro, plata y bronce obtenidos en las \u00faltimas cinco ediciones de los International Chocolate Awards, ubic\u00e1ndose como el principal ganador de uno de los cert\u00e1menes m\u00e1s importantes del sector a nivel mundial.<\/p>\n<p>Dentro de las certificaciones que la empresa ha logrado se encuentra la certificaci\u00f3n Demeter Biodynamic, la cual es el m\u00e1s alto reconocimiento de sostenibilidad. PACARI es importado a Espa\u00f1a a trav\u00e9s de COPADE, una organizaci\u00f3n internacional de desarrollo sostenible.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros<\/p>\n","protected":false},"author":1,"featured_media":71440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-71439","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1072\" \/>\n\t\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-05-08T19:22:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-08T19:22:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#listItem\",\"name\":\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\\u00e1nico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#listItem\",\"position\":3,\"name\":\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\\u00e1nico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#newsarticle\",\"name\":\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\\u00e1nico | Cand\\u00e1s 365\",\"headline\":\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\\u00e1nico\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1493980313_PACARI_RAW_100_CACAO.jpg\",\"width\":1072,\"height\":712},\"datePublished\":\"2017-05-08T19:22:12+02:00\",\"dateModified\":\"2017-05-08T19:22:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el mayo 8, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/\",\"name\":\"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\\u00e1nico | Cand\\u00e1s 365\",\"description\":\"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \\u00faltimo estudio presentado. PACARI est\\u00e1 presente en Espa\\u00f1a en El Corte Ingl\\u00e9s, tanto en sus centros\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/1493980313_PACARI_RAW_100_CACAO.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#mainImage\",\"width\":1072,\"height\":712},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\\\/#mainImage\"},\"datePublished\":\"2017-05-08T19:22:12+02:00\",\"dateModified\":\"2017-05-08T19:22:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365","description":"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros","canonical_url":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#listItem","name":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#listItem","position":3,"name":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#newsarticle","name":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365","headline":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg","width":1072,"height":712},"datePublished":"2017-05-08T19:22:12+02:00","dateModified":"2017-05-08T19:22:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el mayo 8, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#webpage","url":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/","name":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365","description":"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg","@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#mainImage","width":1072,"height":712},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/#mainImage"},"datePublished":"2017-05-08T19:22:12+02:00","dateModified":"2017-05-08T19:22:12+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365","og:description":"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros","og:url":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg","og:image:width":1072,"og:image:height":712,"article:published_time":"2017-05-08T19:22:12+00:00","article:modified_time":"2017-05-08T19:22:12+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico | Cand\u00e1s 365","twitter:description":"PACARI, considerado el mejor chocolate en barra del mundo, ha entrado a formar parte del Top 10 internacional de empresas que impulsan la industria del chocolate org\u00e1nico, tal y como publica la consultora Market Research Future (MRFR) en su \u00faltimo estudio presentado. PACARI est\u00e1 presente en Espa\u00f1a en El Corte Ingl\u00e9s, tanto en sus centros","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/1493980313_PACARI_RAW_100_CACAO.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"71439","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 13:48:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:00:15","updated":"2025-08-25 13:48:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"PACARI, el mejor chocolate en barra del mundo, en el Top 10 de empresas de chocolate org\u00e1nico","link":"https:\/\/candas365.es\/noticias\/pacari-el-mejor-chocolate-en-barra-del-mundo-en-el-top-10-de-empresas-de-chocolate-organico\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/71439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=71439"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/71439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/71440"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=71439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=71439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=71439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}