{"id":70990,"date":"2017-05-04T09:04:57","date_gmt":"2017-05-04T09:04:57","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=70990"},"modified":"2017-05-04T09:04:57","modified_gmt":"2017-05-04T09:04:57","slug":"la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/","title":{"rendered":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-70991\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-360x227.jpg\" alt=\"\" width=\"360\" height=\"227\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-360x227.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-650x410.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-768x485.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-150x95.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-450x284.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-655x413.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-696x439.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-665x420.jpg 665w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995-269x170.jpg 269w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus hijos.<\/p>\n<p>Gorka explica que en La Silla se venden ahora tambi\u00e9n muchas mesas de todo tipo \u00abpara cocinas, salones,etc. Se trabaja sobre pedido, tenemos una ampl\u00edsima exposici\u00f3n y una silla o una mesa, la que quieras, se puede hacer de mil formas diferentes, con una amplia variedad de colores y acabados\u00bb, asegura.<\/p>\n<p>\u00abLos materiales tambi\u00e9n ha evolucionado con los tiempos\u00bb, insisten Maider y Gorka, que recuerdan que hay multitud como el metal y la madera, cristal, laminados o materiales que imitan al gres y la porcelana. En cuanto a las sillas existen, igualmente, infinidad de posibilidades dado que \u00e9stas pueden ser de madera, de propileno, laminadas, o tapizadas en polipiel, etc.<\/p>\n<p>Y es que Maider y Gorka con su dilatada experiencia y cercan\u00eda a los clientes pueden ayudar a elegir el mejor modelo que se ajusta a nuestras necesidades. \u00abSolemos recomendar llevar las muestras a casa para poder comprobar como queda\u00bb, dice Gorka.<\/p>\n<p>\u00abNo se puede olvidar que las sillas son uno de los muebles que m\u00e1s usamos y el que m\u00e1s sufre porque aguanta todo nuestro peso, por lo que hay que elegir\u00bb, asegura Gorka, una silla de calidad \u00abc\u00f3moda y fuerte\u00bb.<\/p>\n<p>Maider destaca que adem\u00e1s de sillas en la tienda (fue renovada totalmente en 2004) tambi\u00e9n venden \u00abtaburetes, sillas tipo relax y butacas, sillas de oficina, para hosteler\u00eda y colectividades\u00bb. La tienda cuenta con m\u00e1s de 150 metros cuadrados de planta con m\u00e1s de 150 tipos de sillas en exposici\u00f3n. Existe adem\u00e1s una sobreplanta con sillas de liquidaci\u00f3n.<\/p>\n<p>Las islas con taburetes altos tambi\u00e9n est\u00e1n ahora de moda y las mesas, que se han ido haciendo m\u00e1s peque\u00f1as con el paso de los a\u00f1os, y las modalidades de vivienda, tambi\u00e9n han cambiado los usos de las sillas y las mesas en las que Gorka y Maider ofrecen un asesoramiento al detalle al cliente con art\u00edculos de calidad y precio ajustado. Por si fuera poco, el transporte va incluido en el precio.<\/p>\n<p>Aunque puntualmente pueden ofertar liquidaciones y ofertas concretas por cambio de decoraci\u00f3n o similar, La Silla ofrece durante todo el a\u00f1o importantes descuentos a sus clientes a partir de una cantidad de compra y en funci\u00f3n del gasto efectuado. As\u00ed, a partir de 500 euros descuentan un 5% en el coste total, y hasta un 15% a partir de 1.500 euros.<\/p>\n<p>La Silla est\u00e1 situada en la calle Olite, n\u00famero 4 de Pamplona, muy cerca de la Plaza de Toros. Puedes contactar con ellos en el tel\u00e9fono 948 228197 o en el correo electr\u00f3nico info@lasillapamplona.com. Disponen tambi\u00e9n de una p\u00e1gina en facebook y de una web www.lasillapamplona.com con un amplio cat\u00e1logo de sillas y productos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus<\/p>\n","protected":false},"author":1,"featured_media":70991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-70990","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-05-04T09:04:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-04T09:04:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#listItem\",\"name\":\"La Silla cumplir\\u00e1 30 a\\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#listItem\",\"position\":3,\"name\":\"La Silla cumplir\\u00e1 30 a\\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#newsarticle\",\"name\":\"La Silla cumplir\\u00e1 30 a\\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\\u00e1s 365\",\"headline\":\"La Silla cumplir\\u00e1 30 a\\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LASILLA_MG_995.jpg\",\"width\":800,\"height\":505},\"datePublished\":\"2017-05-04T09:04:57+02:00\",\"dateModified\":\"2017-05-04T09:04:57+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el mayo 4, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/\",\"name\":\"La Silla cumplir\\u00e1 30 a\\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\\u00e1s 365\",\"description\":\"La Silla, en Pamplona, cumplir\\u00e1, en 2018, 30 a\\u00f1os en funcionamiento. La pasi\\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\\u00f3 primero, durante a\\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\\u00f3 el traspaso del negocio que ahora regentan sus\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LASILLA_MG_995.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#mainImage\",\"width\":800,\"height\":505},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\\\/#mainImage\"},\"datePublished\":\"2017-05-04T09:04:57+02:00\",\"dateModified\":\"2017-05-04T09:04:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365","description":"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus","canonical_url":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#listItem","name":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#listItem","position":3,"name":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#newsarticle","name":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365","headline":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg","width":800,"height":505},"datePublished":"2017-05-04T09:04:57+02:00","dateModified":"2017-05-04T09:04:57+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el mayo 4, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/","name":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365","description":"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg","@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#mainImage","width":800,"height":505},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/#mainImage"},"datePublished":"2017-05-04T09:04:57+02:00","dateModified":"2017-05-04T09:04:57+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365","og:description":"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus","og:url":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg","og:image:width":800,"og:image:height":505,"article:published_time":"2017-05-04T09:04:57+00:00","article:modified_time":"2017-05-04T09:04:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad | Cand\u00e1s 365","twitter:description":"La Silla, en Pamplona, cumplir\u00e1, en 2018, 30 a\u00f1os en funcionamiento. La pasi\u00f3n de Maider y Gorka, sus responsables, por las sillas viene de familia, ya que su madre, Isabel Zuzuarregui trabaj\u00f3 primero, durante a\u00f1os, como dependienta en la tienda y fue posteriormente en 1988 cuando adquiri\u00f3 el traspaso del negocio que ahora regentan sus","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/05\/LASILLA_MG_995.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"70990","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 13:08:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:00:30","updated":"2025-08-25 13:08:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"La Silla cumplir\u00e1 30 a\u00f1os de funcionamiento dedicados a la venta de sillas y mesas de gran calidad","link":"https:\/\/candas365.es\/noticias\/la-silla-cumplira-30-anos-de-funcionamiento-dedicados-a-la-venta-de-sillas-y-mesas-de-gran-calidad\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/70990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=70990"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/70990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/70991"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=70990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=70990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=70990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}