{"id":5836,"date":"2014-12-07T18:03:44","date_gmt":"2014-12-07T20:03:44","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5836"},"modified":"2014-12-07T18:03:44","modified_gmt":"2014-12-07T20:03:44","slug":"el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/","title":{"rendered":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-4890\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg\" alt=\"mar-lluvia\" width=\"360\" height=\"269\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia-150x112.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia-90x67.jpg 90w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas y por el viento, variable con componente Sudoeste durante la madrugada, Noroeste durante las horas centrales del dia y Norte en las \u00faltimas horas.<\/p>\n<p>Las temperaturas ser\u00e1n bajas con siete u ocho grados de m\u00ednima y se podr\u00edan alcanzar los catorce grados en el momento m\u00e1s c\u00e1lido, la probabilidad de lluvias ser\u00e1n muy altas desde las ocho de la ma\u00f1ana hasta las doce de la noche.<\/p>\n<p>Por su parte el litoral asturiano estar\u00e1 ma\u00f1ana en alerta amarilla por fen\u00f3menos costeros, seg\u00fan informa la Agencia Estatal de Meteorolog\u00eda en su p\u00e1gina web.<\/p>\n<p>La costa occidental se ver\u00e1 afectada a partir de las 11:00 horas del lunes hasta las 00:00 horas de martes por olas de hasta cuatro metros<\/p>\n<p>En el litoral oriental se prev\u00e9 que el aumento del oleaje comience sobre las 13:00 horas de ma\u00f1ana hasta las 00:00 horas del martes.<\/p>\n<p>En ambos casos se presenta una mar combinada del noroeste con olas hasta los cuatro metros, con una probabilidad de entre el 40 y el 70 por ciento.<\/p>\n<p>Les seguiremos informando<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas<\/p>\n","protected":false},"author":1,"featured_media":4890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-5836","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-agenda"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-07T20:03:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-07T20:03:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#listItem\",\"name\":\"El Tiempo en el Concejo de Carre\\u00f1o, lunes 8 Diciembre del 2014\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#listItem\",\"position\":3,\"name\":\"El Tiempo en el Concejo de Carre\\u00f1o, lunes 8 Diciembre del 2014\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#newsarticle\",\"name\":\"El Tiempo en el Concejo de Carre\\u00f1o, lunes 8 Diciembre del 2014 | Cand\\u00e1s 365\",\"headline\":\"El Tiempo en el Concejo de Carre\\u00f1o, lunes 8 Diciembre del 2014\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/mar-lluvia.jpg\",\"width\":360,\"height\":269},\"datePublished\":\"2014-12-07T18:03:44+01:00\",\"dateModified\":\"2014-12-07T18:03:44+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el diciembre 7, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/\",\"name\":\"El Tiempo en el Concejo de Carre\\u00f1o, lunes 8 Diciembre del 2014 | Cand\\u00e1s 365\",\"description\":\"Lunes e inicio de semana en el Concejo de Carre\\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\\u00f3menos costeros ser\\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\\u00edtima, el d\\u00eda tambi\\u00e9n estar\\u00e1 marcado por las lluvias que ser\\u00e1n bastante intensas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/mar-lluvia.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#mainImage\",\"width\":360,\"height\":269},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\\\/#mainImage\"},\"datePublished\":\"2014-12-07T18:03:44+01:00\",\"dateModified\":\"2014-12-07T18:03:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365","description":"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas","canonical_url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#listItem","name":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#listItem","position":3,"name":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#newsarticle","name":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365","headline":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg","width":360,"height":269},"datePublished":"2014-12-07T18:03:44+01:00","dateModified":"2014-12-07T18:03:44+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el diciembre 7, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/","name":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365","description":"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#mainImage","width":360,"height":269},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/#mainImage"},"datePublished":"2014-12-07T18:03:44+01:00","dateModified":"2014-12-07T18:03:44+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365","og:description":"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas","og:url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg","og:image:width":360,"og:image:height":269,"article:published_time":"2014-12-07T20:03:44+00:00","article:modified_time":"2014-12-07T20:03:44+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014 | Cand\u00e1s 365","twitter:description":"Lunes e inicio de semana en el Concejo de Carre\u00f1o con los ojos puestos en la mar, con una jornada en la que los fen\u00f3menos costeros ser\u00e1n importantes y en el que se esperan olas de hasta cuatro metros en la fachada mar\u00edtima, el d\u00eda tambi\u00e9n estar\u00e1 marcado por las lluvias que ser\u00e1n bastante intensas","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/mar-lluvia.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"5836","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:28:31","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:31","updated":"2026-05-13 11:28:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"El Tiempo en el Concejo de Carre\u00f1o, lunes 8 Diciembre del 2014","link":"https:\/\/candas365.es\/noticias\/el-tiempo-en-el-concejo-de-carreno-lunes-8-diciembre-del-2014\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5836"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/4890"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}