{"id":5801,"date":"2014-12-06T01:13:33","date_gmt":"2014-12-06T03:13:33","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5801"},"modified":"2014-12-06T01:13:33","modified_gmt":"2014-12-06T03:13:33","slug":"el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/","title":{"rendered":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-355\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/gijon2-360x270.jpg\" alt=\"gijon2\" width=\"360\" height=\"270\" \/>Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda:<\/p>\n<p>En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde se preve\u00eda destinar 6.525.000\u20ac para el pago de las nominas de los diferentes planes de empleo existentes. Finalmente este presupuesto no fue aprobado por el Pleno del Ayuntamiento debido al voto en contra, entre otros, del propio Partido Socialista con lo que la pr\u00f3rroga autom\u00e1tica redujo esta cantidad a solamente 1.262.000\u20ac a inicios de 2014.<\/p>\n<p>A pesar de esto, el Gobierno Municipal ha propuesto durante el ejercicio numerosas modificaciones presupuestarias que han elevado esta cantidad en 4.510.291\u20ac adicionales fijando el presupuesto final a fecha 5 de diciembre en 5.772.291\u20ac.<\/p>\n<p>De esa cantidad total el Ayuntamiento de Gij\u00f3n lleva ejecutados 5.500.777,72\u20ac (95,30% del total). Adem\u00e1s es previsible que se deba de realizar otra modificaci\u00f3n presupuestaria para hacerse cargo de la nomina de diciembre y de la paga extra de navidad con lo que el presupuesto total y su ejecuci\u00f3n rondaran los 6 millones al final de a\u00f1o.<\/p>\n<p>Otros Gastos<\/p>\n<p>Tambi\u00e9n hay que recordar que el Ayuntamiento de Gij\u00f3n no solo destina recursos propios para el pago de las nominas de los beneficiarios de los Planes de Empleo sino que tambi\u00e9n se hace cargo, de manera exclusiva y a trav\u00e9s de las diferentes \u00e1reas municipales donde se encuentran trabajando los beneficiarios, de los costes de Ropa de Trabajo, EPIS, Transporte y otros gastos corrientes como herramientas e instrumentos de trabajo as\u00ed como los costes en los proyectos de inversi\u00f3n vinculados a dicho plan.<\/p>\n<p>Plan de Empleo de 201 personas.<\/p>\n<p>Adicionalmente a esta cantidad el Ayuntamiento de Gij\u00f3n, una vez que el Principado autoriz\u00f3 a que el Ayuntamiento desarrollase planes de empleo propios, puso en marcha una nueva convocatoria para la contrataci\u00f3n de 201 personas por un coste de 2,7 millones de euros. Los ex\u00e1menes para este proceso de selecci\u00f3n comenzaran el 11 de diciembre.<\/p>\n<p>Retraso en las Convocatorias<\/p>\n<p>Por otro lado el Sr. Mart\u00ednez Arguelles ha vuelto a culpar del retraso en la puesta en marcha de varios programas municipales como el 11&#215;12.<\/p>\n<p>El Ayuntamiento debe de volver a recordar que la entrada en vigor de la Reforma de la Administraci\u00f3n Local (Ley 27\/2013, de 27 de diciembre, de racionalizaci\u00f3n y sostenibilidad de la Administraci\u00f3n Local.) ha obligado a que el Principado de Asturias se posicionase al respecto y que emitiese informes de \u201cNo Duplicidad\u201d sobre ciertas actividades y servicios que lleva a cabo el Ayuntamiento.<\/p>\n<p>Estos informes comenzaron a llegar a partir del mes de Agosto y los \u00faltimos llegaron la semana pasada con lo que la responsabilidad en el retraso de actividades como el 11&#215;12 o el pago tard\u00edo a asociaciones como Mar de Niebla o la Asociaci\u00f3n de J\u00f3venes Empresarios, ha quedado muy esclarecida y sorprende que el Sr. Mart\u00ednez Arguelles se reitere en sus afirmaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-5801","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-06T03:13:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-06T03:13:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#listItem\",\"name\":\"El Ayuntamiento de Gij\\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento de Gij\\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#newsarticle\",\"name\":\"El Ayuntamiento de Gij\\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\\u00e1s 365\",\"headline\":\"El Ayuntamiento de Gij\\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/gijon2-360x270.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#articleImage\"},\"datePublished\":\"2014-12-06T01:13:33+01:00\",\"dateModified\":\"2014-12-06T01:13:33+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el diciembre 6, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/\",\"name\":\"El Ayuntamiento de Gij\\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\\u00e1s 365\",\"description\":\"Ante las declaraciones aparecidas en los medio de comunicaci\\u00f3n realizadas por el Sr. Mart\\u00ednez Arguelles, l\\u00edder del Grupo Socialista en el Ayuntamiento de Gij\\u00f3n, que reprochaba al Ayuntamiento \\u201cno haber gastado un duro en Planes de Empleo\\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\\u00f3 a Junta de Gobierno un presupuesto donde\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2014-12-06T01:13:33+01:00\",\"dateModified\":\"2014-12-06T01:13:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365","description":"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde","canonical_url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#listItem","name":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#listItem","position":3,"name":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#newsarticle","name":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365","headline":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/gijon2-360x270.jpg","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#articleImage"},"datePublished":"2014-12-06T01:13:33+01:00","dateModified":"2014-12-06T01:13:33+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el diciembre 6, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/","name":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365","description":"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"datePublished":"2014-12-06T01:13:33+01:00","dateModified":"2014-12-06T01:13:33+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365","og:description":"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde","og:url":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","og:image:width":1152,"og:image:height":864,"article:published_time":"2014-12-06T03:13:33+00:00","article:modified_time":"2014-12-06T03:13:33+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo | Cand\u00e1s 365","twitter:description":"Ante las declaraciones aparecidas en los medio de comunicaci\u00f3n realizadas por el Sr. Mart\u00ednez Arguelles, l\u00edder del Grupo Socialista en el Ayuntamiento de Gij\u00f3n, que reprochaba al Ayuntamiento \u201cno haber gastado un duro en Planes de Empleo\u201d en 2014 el Ayuntamiento recuerda: En Diciembre de 2013 se llev\u00f3 a Junta de Gobierno un presupuesto donde","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"5801","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:22:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:30","updated":"2026-05-13 11:22:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Ayuntamiento de Gij\u00f3n lleva gastados 5.500.777 euros en Planes de Empleo","link":"https:\/\/candas365.es\/noticias\/el-ayuntamiento-de-gijon-lleva-gastados-5-500-777-euros-en-planes-de-empleo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5801"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5801\/revisions"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}