{"id":5782,"date":"2014-12-06T00:34:43","date_gmt":"2014-12-06T02:34:43","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5782"},"modified":"2014-12-06T09:42:10","modified_gmt":"2014-12-06T11:42:10","slug":"mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/","title":{"rendered":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4765\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/Amelia-199x300.jpg\" alt=\"Amelia\" width=\"199\" height=\"300\" \/>El pr\u00f3ximo jueves\u00a0d\u00eda 11\u00a0(17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda \u00abRecursos para personas con diversidad funcional\u00bb, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en el municipio, A\u00fapa Asistencia.<\/p>\n<p>En el acto se prev\u00e9 la participaci\u00f3n de un representante de la Consejer\u00eda de Bienestar Social as\u00ed como de Amelia Fern\u00e1ndez L\u00f3pez, Vicealcaldesa del Ayto. de Carre\u00f1o, Teresa Alvarez, Concejala de Bienestar Social del citado Ayuntamiento .<\/p>\n<p>En la mesa redonda compartir\u00e1n sus experiencias:<\/p>\n<p>\u00b7 un representante de la asociaci\u00f3n de lesionados medulares y grandes discapacitados f\u00edsicos de ASPAYM.<\/p>\n<p>\u00b7 Marisol Delgado Artime, Psic\u00f3loga y psicoterapeuta.<\/p>\n<p>\u00b7 Domingo Mart\u00ednez Sola, Licenciado en diversidad funcional f\u00edsica.<\/p>\n<p>\u00b7 Susana Prieto, representando al C.P. Poeta Anto\u0301n dar\u00e1 su testimonio familiar.<\/p>\n<p>\u00b7 Teresa Gonza\u0301lez y Mari\u0301a del Mar Gonza\u0301lez, emprendedoras de la comarca del Cabo Pe\u00f1es y autoras del proyecto Au\u0301pa Asistencia. Esta empresa est\u00e1 instalada en la Residencia Empresarial de Prendes.<\/p>\n<p>La mesa estar\u00e1 moderada por V\u00edctor Cabal, profesor de la Facultad de Turismo de Oviedo.<\/p>\n<p>\u201c En el marco de la estrategia municipal de atenci\u00f3n a la diversidad vemos como mucho inter\u00e9s que surjan en Cand\u00e1s foros de debate como esta mesa d\u00f3nde tendremos la oportunidad de enriquecernos de la experiencia y conocimiento de todas las personas que participan\u201d \u2013 explic\u00f3 Amelia Fern\u00e1ndez.<\/p>\n<p>\u201c El Ayuntamiento de Carre\u00f1o est\u00e1 desarrollando actualmente un proyecto de taller de empleo que contempla el dotar de accesibilidad a la v\u00eda verde que se est\u00e1 construyendo sobre el antiguo trazado del ferrocarril Estrat\u00e9gico en el tramo de Tam\u00f3n al Valle de Carre\u00f1o. A tal fin, a final de a\u00f1o presentar\u00e1n la propuesta de actuaciones a realizar en dicha senda contando con la colaboraci\u00f3n y asistencia de t\u00e9cnica de ASPAYM \u201d \u2013 prosigui\u00f3 Fern\u00e1ndez.<\/p>\n<p>\u201c Intercambiar impresiones y conocer de primera mano las inquietudes de los colectivos y empresas que trabajan en la atenci\u00f3n de las personas con diversidad funcional es una oportunidad \u00fanica que hay que agradecer a las promotoras del encuentro\u201d \u2013 concluy\u00f3 la Vicealcaldesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo jueves\u00a0d\u00eda 11\u00a0(17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda \u00abRecursos para personas con diversidad funcional\u00bb, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-5782","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias-carreno"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda &quot;Recursos para personas con diversidad funcional&quot;, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"noticias carre\u00f1o\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda &quot;Recursos para personas con diversidad funcional&quot;, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-06T02:34:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-06T11:42:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda &quot;Recursos para personas con diversidad funcional&quot;, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"name\":\"Noticias Carre\\u00f1o\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"position\":2,\"name\":\"Noticias Carre\\u00f1o\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#listItem\",\"name\":\"Mesa Redonda \\u00abRecursos para personas con diversidad funcional\\u201d en Cand\\u00e1s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#listItem\",\"position\":3,\"name\":\"Mesa Redonda \\u00abRecursos para personas con diversidad funcional\\u201d en Cand\\u00e1s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"name\":\"Noticias Carre\\u00f1o\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#newsarticle\",\"name\":\"Mesa Redonda \\u00abRecursos para personas con diversidad funcional\\u201d en Cand\\u00e1s | Cand\\u00e1s 365\",\"headline\":\"Mesa Redonda \\u00abRecursos para personas con diversidad funcional\\u201d en Cand\\u00e1s\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Amelia-199x300.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#articleImage\"},\"datePublished\":\"2014-12-06T00:34:43+01:00\",\"dateModified\":\"2014-12-06T09:42:10+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#webpage\"},\"articleSection\":\"Noticias Carre\\u00f1o\",\"dateline\":\"Publicado el diciembre 6, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/\",\"name\":\"Mesa Redonda \\u00abRecursos para personas con diversidad funcional\\u201d en Cand\\u00e1s | Cand\\u00e1s 365\",\"description\":\"El pr\\u00f3ximo jueves d\\u00eda 11 (17:30) tendr\\u00e1 lugar en la Casa de la Cultura de Cand\\u00e1s la Mesa Redonda \\\"Recursos para personas con diversidad funcional\\\", que se convoca con motivo del D\\u00eda de Mundial de las Personas con Discapacidad y que servir\\u00e1 igualmente como presentaci\\u00f3n p\\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2014-12-06T00:34:43+01:00\",\"dateModified\":\"2014-12-06T09:42:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365","description":"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda \"Recursos para personas con diversidad funcional\", que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en","canonical_url":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/","robots":"max-image-preview:large","keywords":"noticias carre\u00f1o","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","name":"Noticias Carre\u00f1o"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","position":2,"name":"Noticias Carre\u00f1o","item":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#listItem","name":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#listItem","position":3,"name":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","name":"Noticias Carre\u00f1o"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#newsarticle","name":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365","headline":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/Amelia-199x300.jpg","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#articleImage"},"datePublished":"2014-12-06T00:34:43+01:00","dateModified":"2014-12-06T09:42:10+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#webpage"},"articleSection":"Noticias Carre\u00f1o","dateline":"Publicado el diciembre 6, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#webpage","url":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/","name":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365","description":"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda \"Recursos para personas con diversidad funcional\", que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"datePublished":"2014-12-06T00:34:43+01:00","dateModified":"2014-12-06T09:42:10+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365","og:description":"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda &quot;Recursos para personas con diversidad funcional&quot;, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en","og:url":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","og:image:width":1152,"og:image:height":864,"article:published_time":"2014-12-06T02:34:43+00:00","article:modified_time":"2014-12-06T11:42:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s | Cand\u00e1s 365","twitter:description":"El pr\u00f3ximo jueves d\u00eda 11 (17:30) tendr\u00e1 lugar en la Casa de la Cultura de Cand\u00e1s la Mesa Redonda &quot;Recursos para personas con diversidad funcional&quot;, que se convoca con motivo del D\u00eda de Mundial de las Personas con Discapacidad y que servir\u00e1 igualmente como presentaci\u00f3n p\u00fablica de la nueva y novedosa empresa de servicios asistenciales fundada en","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"5782","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:20:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:11","updated":"2026-05-13 11:20:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/\" title=\"Noticias Carre\u00f1o\">Noticias Carre\u00f1o<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Noticias Carre\u00f1o","link":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/"},{"label":"Mesa Redonda \u00abRecursos para personas con diversidad funcional\u201d en Cand\u00e1s","link":"https:\/\/candas365.es\/noticias\/mesa-redonda-recursos-para-personas-con-diversidad-funcional-en-candas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5782"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5782\/revisions"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}