{"id":5725,"date":"2014-12-04T08:46:40","date_gmt":"2014-12-04T10:46:40","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5725"},"modified":"2014-12-04T08:46:55","modified_gmt":"2014-12-04T10:46:55","slug":"la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/","title":{"rendered":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-5726\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-360x249.jpg\" alt=\"2014_12_04 Faustino Blanco Presupuestos 2015 Sanidad 2\" width=\"360\" height=\"249\" \/>El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.<\/p>\n<p>Adem\u00e1s, las cuentas para el pr\u00f3ximo a\u00f1o fortalecen la investigaci\u00f3n en Asturias a trav\u00e9s de la Fundaci\u00f3n para la Investigaci\u00f3n e Innovaci\u00f3n Sanitaria (Finba) y de la Ficyt con un presupuesto conjunto pr\u00f3ximo al mill\u00f3n de euros, mantienen el despliegue de las inversiones en TIC para seguir modernizando la asistencia sanitaria y garantizan los recursos necesarios para poner en marcha uno de los proyectos m\u00e1s importantes de la consejer\u00eda, una vez culminada la apertura de los dos nuevos hospitales, como es la ampliaci\u00f3n y reforma del Hospital de Cabue\u00f1es, que cuenta con 290.000 euros.<\/p>\n<p>El departamento de Faustino Blanco ha elaborado unos presupuestos para el a\u00f1o que viene destinados a continuar reduciendo las inequidades en salud y preservar la cohesi\u00f3n social, que permiten dar continuidad a proyectos estrat\u00e9gicos como el plan de cronicidad, el proceso de integraci\u00f3n funcional de las \u00e1reas sanitarias, la mejora de la resoluci\u00f3n en los servicios de atenci\u00f3n primaria y el compromiso con la sanidad integrada en red, a la vez que mantiene intacta la cartera de servicios y la red asistencial actualmente en funcionamiento.<\/p>\n<p>El presupuesto de la consejer\u00eda supone el 38% de la partida global del Principado para el pr\u00f3ximo ejercicio y el 56,3% de su gasto en pol\u00edticas sociales. El 96% (1.433,8 millones) ser\u00e1 ejecutado por el Servicio de Salud del Principado de Asturias (Sespa), el 51,05% se destina a personal y el resto al gasto corriente y al pago de la factura de farmacia.<\/p>\n<p>Seg\u00fan ha se\u00f1alado hoy el consejero de Sanidad Faustino Blanco, en la presentaci\u00f3n de las cuentas en la Junta General del Principado, el Gobierno asturiano ha elaborado un proyecto de presupuesto austero y exigente, dise\u00f1ado como una oportunidad de seguir mejorando en la atenci\u00f3n a los ciudadanos y que refuerza su compromiso con el mantenimiento de un servicio p\u00fablico, accesible, equitativo y de calidad para todos.<\/p>\n<p>El presupuesto total destinado al \u00e1mbito de la salud p\u00fablica es de 14,9 millones, que se distribuyen en la defensa de los consumidores, la protecci\u00f3n de la salud ambiental y alimentaria y en la vigilancia promoci\u00f3n y prevenci\u00f3n de la salud.<\/p>\n<p>Los objetivos econ\u00f3micos de la consejer\u00eda incluyen tres grandes l\u00edneas de actuaci\u00f3n: dar continuidad al desarrollo de las pol\u00edticas aguas arriba, de promoci\u00f3n y prevenci\u00f3n de la salud; asegurar la protecci\u00f3n de la salud derivada de los riesgos del medio ambiente, la alimentaci\u00f3n y el consumo, y defender al consumidor, formando, informando y arbitrando en el control del mercado.<\/p>\n<p>Sus l\u00edneas directrices ser\u00e1n la promoci\u00f3n de la salud, la implantaci\u00f3n de la estrategia para la atenci\u00f3n a los pacientes cr\u00f3nicos Personas sanas, poblaciones sanas y dar soporte al desarrollo de los planes drogas y de los servicios de salud mental.<\/p>\n<p>Adem\u00e1s, introducir\u00e1 cambios en el modelo de vigilancia epidemiol\u00f3gica, que incorporar\u00e1 paulatinamente 60 nuevas enfermedades a vigilar y pautas de actuaci\u00f3n m\u00e1s exigentes, pondr\u00e1 en marcha los nuevos programas de cribado neonatal, y desarrollar\u00e1 el programa piloto de cribado universal de c\u00e1ncer de colon. Todo ello, sin dejar de cumplir con el objetivo estrat\u00e9gico de la legislatura de consolidar, reforzar y estimular los recursos civiles, asociaciones y ONGs, que prestan una intensa labor de prevenci\u00f3n y promoci\u00f3n de la salud.<\/p>\n<p>El presupuesto de la Direcci\u00f3n General de Planificaci\u00f3n, Ordenaci\u00f3n e Innovaci\u00f3n Sanitaria se centra en los objetivos del contrato programa que la Consejer\u00eda de Sanidad y el Sespa acordar\u00e1n para el a\u00f1o 2015 y que est\u00e1n orientados a proporcionar a la ciudadan\u00eda la mejor atenci\u00f3n sanitaria posible, con una garant\u00eda de tiempo de espera asumible para el paciente y sostenible para la organizaci\u00f3n, favorecer el uso \u00f3ptimo y eficiente de los recursos, y avanzar en nuevas f\u00f3rmulas de organizaci\u00f3n sanitaria que permitan una mayor participaci\u00f3n de los profesionales y los ciudadanos en la toma de decisiones.<\/p>\n<p>En el \u00e1mbito de la innovaci\u00f3n, las cuentas de 2015 consignan las cantidades necesarias para continuar el proceso de informatizaci\u00f3n del Hospital Universitario Central de Asturias (HUCA) y del Hospital de Cabue\u00f1es, y el mantenimiento de la receta electr\u00f3nica y su extensi\u00f3n al \u00e1mbito de la atenci\u00f3n hospitalaria.<\/p>\n<p>El fortalecimiento de la investigaci\u00f3n excelente en la Finba, para la que se consigna una cantidad de 300.000 euros, y de la Ficyt, con otros 600.000, es uno de los compromisos del Gobierno que tienen un fiel reflejo en las cuentas de 2015.<\/p>\n<p>El cap\u00edtulo de inversiones crece significativamente con respecto a la pr\u00f3rroga del ejercicio 2014, al pasar de 750.000 euros a 1.970.178 euros<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.<\/p>\n","protected":false},"author":1,"featured_media":5726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-5725","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1776\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-04T10:46:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-04T10:46:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#listItem\",\"name\":\"La consejer\\u00eda de Sanidad de Asturias dispondr\\u00e1 de 1.492,5 millones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#listItem\",\"position\":3,\"name\":\"La consejer\\u00eda de Sanidad de Asturias dispondr\\u00e1 de 1.492,5 millones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#newsarticle\",\"name\":\"La consejer\\u00eda de Sanidad de Asturias dispondr\\u00e1 de 1.492,5 millones | Cand\\u00e1s 365\",\"headline\":\"La consejer\\u00eda de Sanidad de Asturias dispondr\\u00e1 de 1.492,5 millones\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg\",\"width\":2560,\"height\":1776},\"datePublished\":\"2014-12-04T08:46:40+01:00\",\"dateModified\":\"2014-12-04T08:46:55+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el diciembre 4, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/\",\"name\":\"La consejer\\u00eda de Sanidad de Asturias dispondr\\u00e1 de 1.492,5 millones | Cand\\u00e1s 365\",\"description\":\"El presupuesto de la Consejer\\u00eda de Sanidad del Principado para el a\\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\\u00edtulos que m\\u00e1s se hab\\u00eda visto afectado por la pr\\u00f3rroga del pasado a\\u00f1o y por los ajustes del anterior.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#mainImage\",\"width\":2560,\"height\":1776},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\\\/#mainImage\"},\"datePublished\":\"2014-12-04T08:46:40+01:00\",\"dateModified\":\"2014-12-04T08:46:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365","description":"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.","canonical_url":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#listItem","name":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#listItem","position":3,"name":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#newsarticle","name":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365","headline":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg","width":2560,"height":1776},"datePublished":"2014-12-04T08:46:40+01:00","dateModified":"2014-12-04T08:46:55+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el diciembre 4, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/","name":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365","description":"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg","@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#mainImage","width":2560,"height":1776},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/#mainImage"},"datePublished":"2014-12-04T08:46:40+01:00","dateModified":"2014-12-04T08:46:55+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365","og:description":"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.","og:url":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg","og:image:width":2560,"og:image:height":1776,"article:published_time":"2014-12-04T10:46:40+00:00","article:modified_time":"2014-12-04T10:46:55+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones | Cand\u00e1s 365","twitter:description":"El presupuesto de la Consejer\u00eda de Sanidad del Principado para el a\u00f1o 2015, que alcanza los 1.492,5 millones de euros, incrementa en un 162% las inversiones en la mejora de la red asistencial, uno de los cap\u00edtulos que m\u00e1s se hab\u00eda visto afectado por la pr\u00f3rroga del pasado a\u00f1o y por los ajustes del anterior.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/12\/2014_12_04-Faustino-Blanco-Presupuestos-2015-Sanidad-2-scaled.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"5725","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:10:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:10","updated":"2026-05-13 11:10:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"La consejer\u00eda de Sanidad de Asturias dispondr\u00e1 de 1.492,5 millones","link":"https:\/\/candas365.es\/noticias\/la-consejeria-de-sanidad-de-asturias-dispondra-de-1-4925-millones\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5725"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/5726"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}