{"id":5709,"date":"2014-12-04T00:06:17","date_gmt":"2014-12-04T02:06:17","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5709"},"modified":"2014-12-04T00:06:17","modified_gmt":"2014-12-04T02:06:17","slug":"iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/","title":{"rendered":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-2948\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares11.jpg\" alt=\"llamazares1\" width=\"360\" height=\"252\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares11.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares11-150x105.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares11-100x70.jpg 100w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las el\u00e9ctricas: \u201cla pregunta es \u00bfpor qu\u00e9 acepta los chantajes del sector el\u00e9ctrico que en este pa\u00eds tiene unos beneficios que duplican a los del sector europeo, a costa de la competitividad de las empresas y de unas tarifas para los consumidores muy altas en relaci\u00f3n a la media de la Uni\u00f3n Europea? \u00bfPor qu\u00e9 acepta unos chantajes y se niega a aceptar otros? En nuestra opini\u00f3n no hay que aceptar ninguno. No hay que aceptar el chantaje del sector el\u00e9ctrico ni hay que aceptar el chantaje de la direcci\u00f3n de Alcoa\u201d.<\/p>\n<p>Llamazares pidi\u00f3 que el Gobierno rechace el expediente de extinci\u00f3n de empleo y adopte un modelo estable de tarifa que no solamente vaya en bien de Alcoa, sino de la industria espa\u00f1ola y de los consumidores. \u201cLlevamos 13 modificaciones legales en materia energ\u00e9tica que son, para los ciudadanos, m\u00e1s costosas que las anteriores\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las<\/p>\n","protected":false},"author":1,"featured_media":2945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-5709","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"252\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-04T02:06:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-04T02:06:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#listItem\",\"name\":\"IU pide al Gobierno que rechace el expediente de extinci\\u00f3n de empleo de Alcoa\\u200f\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#listItem\",\"position\":3,\"name\":\"IU pide al Gobierno que rechace el expediente de extinci\\u00f3n de empleo de Alcoa\\u200f\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#newsarticle\",\"name\":\"IU pide al Gobierno que rechace el expediente de extinci\\u00f3n de empleo de Alcoa\\u200f | Cand\\u00e1s 365\",\"headline\":\"IU pide al Gobierno que rechace el expediente de extinci\\u00f3n de empleo de Alcoa\\u200f\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/llamazares1.jpg\",\"width\":360,\"height\":252},\"datePublished\":\"2014-12-04T00:06:17+01:00\",\"dateModified\":\"2014-12-04T00:06:17+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el diciembre 4, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/\",\"name\":\"IU pide al Gobierno que rechace el expediente de extinci\\u00f3n de empleo de Alcoa\\u200f | Cand\\u00e1s 365\",\"description\":\"Izquierda Unida exigir\\u00e1 una soluci\\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\\u00f3n el\\u00e9ctrico espa\\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\\u00f3 hoy al ministro de Industria \\u201cpor mirar a otro lado\\u201d y reclam\\u00f3 que explique por qu\\u00e9 se pliega a los intereses de las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/llamazares1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#mainImage\",\"width\":360,\"height\":252},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\\\/#mainImage\"},\"datePublished\":\"2014-12-04T00:06:17+01:00\",\"dateModified\":\"2014-12-04T00:06:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365","description":"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las","canonical_url":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#listItem","name":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#listItem","position":3,"name":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#newsarticle","name":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365","headline":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg","width":360,"height":252},"datePublished":"2014-12-04T00:06:17+01:00","dateModified":"2014-12-04T00:06:17+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el diciembre 4, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#webpage","url":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/","name":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365","description":"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg","@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#mainImage","width":360,"height":252},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/#mainImage"},"datePublished":"2014-12-04T00:06:17+01:00","dateModified":"2014-12-04T00:06:17+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365","og:description":"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las","og:url":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg","og:image:width":360,"og:image:height":252,"article:published_time":"2014-12-04T02:06:17+00:00","article:modified_time":"2014-12-04T02:06:17+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f | Cand\u00e1s 365","twitter:description":"Izquierda Unida exigir\u00e1 una soluci\u00f3n urgente para evitar el cierre de Alcoa y medidas estructurales en el modelo de gesti\u00f3n el\u00e9ctrico espa\u00f1ol. El diputado nacional de IU por Asturias, Gaspar Llamazares, critic\u00f3 hoy al ministro de Industria \u201cpor mirar a otro lado\u201d y reclam\u00f3 que explique por qu\u00e9 se pliega a los intereses de las","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/llamazares1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"5709","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:08:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:09","updated":"2026-05-13 11:08:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tIU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"IU pide al Gobierno que rechace el expediente de extinci\u00f3n de empleo de Alcoa\u200f","link":"https:\/\/candas365.es\/noticias\/iu-pide-al-gobierno-que-rechace-el-expediente-de-extincion-de-empleo-de-alcoa%e2%80%8f\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5709"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/2945"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}