{"id":5663,"date":"2014-12-01T17:29:16","date_gmt":"2014-12-01T19:29:16","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5663"},"modified":"2014-12-01T17:29:16","modified_gmt":"2014-12-01T19:29:16","slug":"pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/","title":{"rendered":"Pulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-190\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg\" alt=\"palamento\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento-84x55.jpg 84w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d.<\/p>\n<p>A juicio de la diputada de IU, en este presupuesto de Presidencia y de la Consejer\u00eda de Presidencia, se constata que se trata de un proyecto continuista, sin novedades. Marta Pulgar apunt\u00f3 que nada nuevo existe por ejemplo en la unificaci\u00f3n de las sedes judiciales de Oviedo, que no tiene constataci\u00f3n presupuestaria; tampoco menciona las reparaciones en los juzgados, \u201cdonde las necesidades siguen siendo muchas y pocas las dotaciones econ\u00f3micas\u201d; en materia de seguridad, el organismo SEPA consolida la din\u00e1mica de entender estos servicios de emergencia y seguridad desde lo p\u00fablico \u2013con lo que IU est\u00e1 de acuerdo-, pero esa consolidaci\u00f3n pasa a su juicio \u201cpor ampliarlo y dotarlo de personal de manera suficiente\u201d, como reivindicaci\u00f3n el personal y como \u201cacabar\u00e1n demandando los ciudadanos como una necesidad\u201d. La diputada puso en duda de que se pueda hablar de funcionarizaci\u00f3n y de mejoras en el SEPA, sin tener aprobada la Ley de Emergencias en esta legislatura.<\/p>\n<p>Del mismo modo, la diputada ech\u00f3 en falta las partidas para cumplir con la reclasificaci\u00f3n de los polic\u00edas locales fruto de la Ley de Coordinaci\u00f3n y la eliminaci\u00f3n de las tasas de la escuela de Seguridad P\u00fablica a las corporaciones locales. Pulgar denunci\u00f3 la \u201cprecarizaci\u00f3n\u201d de los trabajadores de la seguridad privada y exigi\u00f3 negociaci\u00f3n pol\u00edtica para frenar el empeoramiento de sus condiciones laborales.<\/p>\n<p>Por \u00faltimo, denunci\u00f3 que el presupuesto recorta a dos colectivos vulnerables, \u201ccomo las mujeres y los j\u00f3venes\u201d, que son los que a su forma de entender, \u201cpagan\u201d la rebaja presupuestaria en esta Consejer\u00eda. \u201cMirar a otras comunidades aut\u00f3nomas puede ser \u00fatil, pero no una excusa para no cumplir su propio programa de legislatura en dos asuntos que son totalmente simb\u00f3licos\u201d, advirti\u00f3 la diputada de IU.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la<\/p>\n","protected":false},"author":1,"featured_media":190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-5663","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-01T19:29:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-01T19:29:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#listItem\",\"name\":\"Pulgar demanda ideas e iniciativas ante el  presupuesto \\u201cgris\\u201d de la Consejer\\u00eda de Presidencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#listItem\",\"position\":3,\"name\":\"Pulgar demanda ideas e iniciativas ante el  presupuesto \\u201cgris\\u201d de la Consejer\\u00eda de Presidencia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#newsarticle\",\"name\":\"Pulgar demanda ideas e iniciativas ante el presupuesto \\u201cgris\\u201d de la Consejer\\u00eda de Presidencia | Cand\\u00e1s 365\",\"headline\":\"Pulgar demanda ideas e iniciativas ante el  presupuesto \\u201cgris\\u201d de la Consejer\\u00eda de Presidencia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/palamento.jpg\",\"width\":360,\"height\":240},\"datePublished\":\"2014-12-01T17:29:16+01:00\",\"dateModified\":\"2014-12-01T17:29:16+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el diciembre 1, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/\",\"name\":\"Pulgar demanda ideas e iniciativas ante el presupuesto \\u201cgris\\u201d de la Consejer\\u00eda de Presidencia | Cand\\u00e1s 365\",\"description\":\"Para la diputada de IU, el presupuesto debe ser una herramienta \\u00fatil para la sociedad asturiana manteniendo los servicios p\\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\\u00e1s castigadas por la crisis y la \\u201crealidad social de los nuevos pobres, los trabajadores\\u201d, aunque \\u00e9ste \\u201cdesgraciadamente no es ese presupuesto\\u201d. A juicio de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/palamento.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#mainImage\",\"width\":360,\"height\":240},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\\\/#mainImage\"},\"datePublished\":\"2014-12-01T17:29:16+01:00\",\"dateModified\":\"2014-12-01T17:29:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365","description":"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la","canonical_url":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#listItem","name":"Pulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#listItem","position":3,"name":"Pulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#newsarticle","name":"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365","headline":"Pulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg","width":360,"height":240},"datePublished":"2014-12-01T17:29:16+01:00","dateModified":"2014-12-01T17:29:16+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el diciembre 1, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#webpage","url":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/","name":"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365","description":"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg","@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#mainImage","width":360,"height":240},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/#mainImage"},"datePublished":"2014-12-01T17:29:16+01:00","dateModified":"2014-12-01T17:29:16+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365","og:description":"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la","og:url":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg","og:image:width":360,"og:image:height":240,"article:published_time":"2014-12-01T19:29:16+00:00","article:modified_time":"2014-12-01T19:29:16+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Pulgar demanda ideas e iniciativas ante el presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia | Cand\u00e1s 365","twitter:description":"Para la diputada de IU, el presupuesto debe ser una herramienta \u00fatil para la sociedad asturiana manteniendo los servicios p\u00fablicos esenciales, abordando muy especialmente las necesidades da las personas m\u00e1s castigadas por la crisis y la \u201crealidad social de los nuevos pobres, los trabajadores\u201d, aunque \u00e9ste \u201cdesgraciadamente no es ese presupuesto\u201d. A juicio de la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/palamento.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"5663","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 11:02:43","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:56","updated":"2026-05-13 11:02:43"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Pulgar demanda ideas e iniciativas ante el  presupuesto \u201cgris\u201d de la Consejer\u00eda de Presidencia","link":"https:\/\/candas365.es\/noticias\/pulgar-demanda-ideas-e-iniciativas-ante-el-presupuesto-gris-de-la-consejeria-de-presidencia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5663"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/190"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}