{"id":5454,"date":"2014-11-23T16:31:03","date_gmt":"2014-11-23T18:31:03","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5454"},"modified":"2014-11-23T16:31:03","modified_gmt":"2014-11-23T18:31:03","slug":"paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/","title":{"rendered":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-270\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda-360x238.jpg\" alt=\"agenda\" width=\"360\" height=\"238\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda-360x238.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda-150x99.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda-450x298.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg 500w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Las Jornadas de Piano \u00abLuis G. Iberni\u00bb ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa centrado en la m\u00fasica de L. v. Beethoven, a trav\u00e9s de sus tres \u00faltimas sonatas (n\u00fameros 30, 31 y 32), consideradas como tres de las grandes obras maestras de la literatura pian\u00edstica universal.<\/p>\n<p>Lewis est\u00e1 considerado por la cr\u00edtica internacional como uno de los pianistas m\u00e1s relevantes de su generaci\u00f3n y, de hecho, ha recibido numerosos premios que avalan su trayectoria, entre ellos por su interpretaci\u00f3n de la integral de las sonatas de Schubert y de Beethoven, de quienes est\u00e1 considerado un m\u00e1ximo especialista.<\/p>\n<p>Paul Lewis trabaja regularmente con las m\u00e1s prestigiosas orquestas del mundo y es invitado a las grandes salas de conciertos como el Royal Festival Hall de Londres, Carnegie y Alice Tully Hall de Nueva York, Musikverein y el Konzerthaus de Viena, Tonhalle de Zurich, o Sydney Opera House. Tambi\u00e9n trabaja en los festivales m\u00e1s prestigiosos del mundo, como Lucerna, Mostly Mozart en Nueva York, Tanglewood, Schubertiade, Salzburgo, Edimburgo, La Roque d\u2019Anth\u00e9ron, Rheingau, Festival de Piano del Ruhr, y BBC Proms de Londres, donde en 2010 se convirti\u00f3 en el primer pianista en la historia en tocar los cinco conciertos de Beethoven en una misma temporada. Tambi\u00e9n su trabajo discogr\u00e1fico ha sido merecedor de galardones, entre ellos su trabajo para Harmonia Mundi que incluye las sonatas completas para piano de Beethoven, conciertos, las \u00abVariaciones Diabelli\u00bb o la \u00abSonata en si menor\u00bb de Liszt, entre otras obras.<\/p>\n<p>A\u00fan quedan localidades disponibles al precio de 20 \u20ac y 16 \u20ac. Descuentos del 20% el mismo d\u00eda del concierto para estudiantes universitarios y grupos organizados de alumnos. Los pensionistas podr\u00e1n obtener un descuento del 10% sobre el precio de las localidades adquiridas el mismo d\u00eda de la funci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Jornadas de Piano \u00abLuis G. Iberni\u00bb ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa<\/p>\n","protected":false},"author":1,"featured_media":270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5454","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las Jornadas de Piano &quot;Luis G. Iberni&quot; ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Las Jornadas de Piano &quot;Luis G. Iberni&quot; ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-23T18:31:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-23T18:31:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las Jornadas de Piano &quot;Luis G. Iberni&quot; ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#listItem\",\"name\":\"Paul Lewis debuta en las Jornadas de Piano con un monogr\\u00e1fico Beethoven\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#listItem\",\"position\":3,\"name\":\"Paul Lewis debuta en las Jornadas de Piano con un monogr\\u00e1fico Beethoven\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#newsarticle\",\"name\":\"Paul Lewis debuta en las Jornadas de Piano con un monogr\\u00e1fico Beethoven | Cand\\u00e1s 365\",\"headline\":\"Paul Lewis debuta en las Jornadas de Piano con un monogr\\u00e1fico Beethoven\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"width\":500,\"height\":331},\"datePublished\":\"2014-11-23T16:31:03+01:00\",\"dateModified\":\"2014-11-23T16:31:03+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el noviembre 23, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/\",\"name\":\"Paul Lewis debuta en las Jornadas de Piano con un monogr\\u00e1fico Beethoven | Cand\\u00e1s 365\",\"description\":\"Las Jornadas de Piano \\\"Luis G. Iberni\\\" ofrecen, el pr\\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\\u00e1s prestigiosos de la actualidad, el ingl\\u00e9s Paul Lewis que ofrecer\\u00e1 un programa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#mainImage\",\"width\":500,\"height\":331},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\\\/#mainImage\"},\"datePublished\":\"2014-11-23T16:31:03+01:00\",\"dateModified\":\"2014-11-23T16:31:03+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365","description":"Las Jornadas de Piano \"Luis G. Iberni\" ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa","canonical_url":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#listItem","name":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#listItem","position":3,"name":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#newsarticle","name":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365","headline":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","width":500,"height":331},"datePublished":"2014-11-23T16:31:03+01:00","dateModified":"2014-11-23T16:31:03+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el noviembre 23, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#webpage","url":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/","name":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365","description":"Las Jornadas de Piano \"Luis G. Iberni\" ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#mainImage","width":500,"height":331},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/#mainImage"},"datePublished":"2014-11-23T16:31:03+01:00","dateModified":"2014-11-23T16:31:03+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365","og:description":"Las Jornadas de Piano &quot;Luis G. Iberni&quot; ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa","og:url":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:width":500,"og:image:height":331,"article:published_time":"2014-11-23T18:31:03+00:00","article:modified_time":"2014-11-23T18:31:03+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven | Cand\u00e1s 365","twitter:description":"Las Jornadas de Piano &quot;Luis G. Iberni&quot; ofrecen, el pr\u00f3ximo martes 25 de noviembre a partir de las ocho de la tarde, el primero de los recitales previstos para esta temporada con el debut en el ciclo de uno de los pianistas m\u00e1s prestigiosos de la actualidad, el ingl\u00e9s Paul Lewis que ofrecer\u00e1 un programa","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"5454","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 10:32:05","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:38","updated":"2026-05-13 10:32:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPaul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"Paul Lewis debuta en las Jornadas de Piano con un monogr\u00e1fico Beethoven","link":"https:\/\/candas365.es\/noticias\/paul-lewis-debuta-en-las-jornadas-de-piano-con-un-monografico-beethoven\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5454"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}