{"id":5349,"date":"2014-11-18T17:59:29","date_gmt":"2014-11-18T19:59:29","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5349"},"modified":"2014-11-18T17:59:29","modified_gmt":"2014-11-18T19:59:29","slug":"rachid-preparado-para-sustituir-a-sergio-alvarez","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/","title":{"rendered":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-5232\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg\" alt=\"DEPORTES\" width=\"336\" height=\"280\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg 336w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES-150x125.jpg 150w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/>BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino.<\/p>\n<p>De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n porque \u201chay m\u00e1s compa\u00f1eros que pueden actuar en mi puesto\u201d. No obstante se siente \u201cpreparado\u201d para asumir la batuta del centro del campo con Nacho Cases.<\/p>\n<p>Se declara un gran aficionado al f\u00fatbol, por eso no le molest\u00f3 jugar el pasado fin de semana con el Sporting. \u201cPido que me dejen hacerlo en el filial si no lo hago con el primer equipo\u201d. En todo momento se siente respaldado por el vestuario y encuentra un buen ejemplo en Lora, que tambi\u00e9n se incorpor\u00f3 en su d\u00eda para jugar en el filial y hoy es el capit\u00e1n del equipo.<\/p>\n<p>Abelardo, tal y como reconoce el propio futbolista, quiere que haga las cosas de una manera sencilla. \u201cJugar f\u00e1cil, con dos toques y a banda\u201d, aseguraba hoy en rueda de prensa. Respecto al rival del s\u00e1bado es consciente de que el \u201cLlagostera no ser\u00e1 un rival f\u00e1cil\u201d porque en Segunda Divisi\u00f3n todos los encuentros son complicados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n<\/p>\n","protected":false},"author":1,"featured_media":5232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":["post-5349","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"336\" \/>\n\t\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-18T19:59:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-18T19:59:29+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#listItem\",\"name\":\"Rachid \\u201cpreparado\\u201d para sustituir a Sergio \\u00c1lvarez\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#listItem\",\"position\":3,\"name\":\"Rachid \\u201cpreparado\\u201d para sustituir a Sergio \\u00c1lvarez\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#newsarticle\",\"name\":\"Rachid \\u201cpreparado\\u201d para sustituir a Sergio \\u00c1lvarez | Cand\\u00e1s 365\",\"headline\":\"Rachid \\u201cpreparado\\u201d para sustituir a Sergio \\u00c1lvarez\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/DEPORTES.jpg\",\"width\":336,\"height\":280},\"datePublished\":\"2014-11-18T17:59:29+01:00\",\"dateModified\":\"2014-11-18T17:59:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el noviembre 18, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/\",\"name\":\"Rachid \\u201cpreparado\\u201d para sustituir a Sergio \\u00c1lvarez | Cand\\u00e1s 365\",\"description\":\"BercodiPress: Todo apunta a que el franc\\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \\u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\\u00e1 como titular ante el conjunto catal\\u00e1n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/DEPORTES.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#mainImage\",\"width\":336,\"height\":280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/rachid-preparado-para-sustituir-a-sergio-alvarez\\\/#mainImage\"},\"datePublished\":\"2014-11-18T17:59:29+01:00\",\"dateModified\":\"2014-11-18T17:59:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365","description":"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n","canonical_url":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#listItem","name":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#listItem","position":3,"name":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#newsarticle","name":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365","headline":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg","width":336,"height":280},"datePublished":"2014-11-18T17:59:29+01:00","dateModified":"2014-11-18T17:59:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el noviembre 18, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#webpage","url":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/","name":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365","description":"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg","@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#mainImage","width":336,"height":280},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/#mainImage"},"datePublished":"2014-11-18T17:59:29+01:00","dateModified":"2014-11-18T17:59:29+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365","og:description":"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n","og:url":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg","og:image:width":336,"og:image:height":280,"article:published_time":"2014-11-18T19:59:29+00:00","article:modified_time":"2014-11-18T19:59:29+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez | Cand\u00e1s 365","twitter:description":"BercodiPress: Todo apunta a que el franc\u00e9s de origen argelino Rachid se ocupe de reemplazar a Sergio \u00c1lvarez en el encuentro ante el Llagostera. De momento en los cinco partidos en los que ha entrado en juego ha sido siempre en lugar del avilesino. De momento desconoce si debutar\u00e1 como titular ante el conjunto catal\u00e1n","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/DEPORTES.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"5349","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 10:15:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:23","updated":"2026-05-13 10:15:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tRachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Rachid \u201cpreparado\u201d para sustituir a Sergio \u00c1lvarez","link":"https:\/\/candas365.es\/noticias\/rachid-preparado-para-sustituir-a-sergio-alvarez\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5349"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/5232"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}