{"id":5237,"date":"2014-11-14T14:23:27","date_gmt":"2014-11-14T16:23:27","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5237"},"modified":"2014-11-14T14:23:50","modified_gmt":"2014-11-14T16:23:50","slug":"david-villa-ya-luce-la-camiseta-del-new-york-city","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/","title":{"rendered":"David Villa ya luce la camiseta del New York City"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-5238\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa-360x225.jpg\" alt=\"villa\" width=\"360\" height=\"225\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa-360x225.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa-150x94.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa-450x281.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa-279x173.jpg 279w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg 560w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club.<\/p>\n<p>El acto tuvo lugar en un complejo que celebra conciertos en Manhattan, con la presencia de un buen n\u00famero de seguidores que no quisieron perderse esta presentaci\u00f3n por todo lo alto. El ex delantero del Sporting, Valencia, Barcelona y Atl\u00e9tico de Madrid, entre otros, reconoci\u00f3 que \u00e9ste va a ser un \u201cproyecto ganador desde el primer momento. Estoy feliz aqu\u00ed\u201d.<\/p>\n<p>El nuevo club de El guaje se estrena en principal liga de f\u00fatbol profesional estadounidense, la MLS. La camiseta que vestir\u00e1 en Nueva York ser\u00e1 muy similar a la indumentaria que utiliza el Manchester City, con un azul claro. Dijo de la equipaci\u00f3n que era \u201cperfecta para el inicio de este nuevo proyecto y ojal\u00e1 nos de muchas alegr\u00edas y victorias.<\/p>\n<p>Villa tendr\u00e1 la oportunidad de compartir vestuario con otro ilustre jugador del f\u00fatbol europeo como es Frank Lampard, que dej\u00f3 la disciplina del Chelsea. Est\u00e1 previsto que se incorpore en enero a los entrenamientos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar<\/p>\n","protected":false},"author":1,"featured_media":5238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":["post-5237","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-14T16:23:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-14T16:23:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#listItem\",\"name\":\"David Villa ya luce la camiseta del New York City\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#listItem\",\"position\":3,\"name\":\"David Villa ya luce la camiseta del New York City\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#newsarticle\",\"name\":\"David Villa ya luce la camiseta del New York City | Cand\\u00e1s 365\",\"headline\":\"David Villa ya luce la camiseta del New York City\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/villa.jpg\",\"width\":560,\"height\":350},\"datePublished\":\"2014-11-14T14:23:27+01:00\",\"dateModified\":\"2014-11-14T14:23:50+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el noviembre 14, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/\",\"name\":\"David Villa ya luce la camiseta del New York City | Cand\\u00e1s 365\",\"description\":\"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\\u00f3 la nueva equipaci\\u00f3n del que ser\\u00e1 su equipo para los pr\\u00f3ximos tres a\\u00f1os, el New York City Football Club. El acto tuvo lugar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/villa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#mainImage\",\"width\":560,\"height\":350},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/david-villa-ya-luce-la-camiseta-del-new-york-city\\\/#mainImage\"},\"datePublished\":\"2014-11-14T14:23:27+01:00\",\"dateModified\":\"2014-11-14T14:23:50+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>David Villa ya luce la camiseta del New York City | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365","description":"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar","canonical_url":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#listItem","name":"David Villa ya luce la camiseta del New York City"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#listItem","position":3,"name":"David Villa ya luce la camiseta del New York City","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#newsarticle","name":"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365","headline":"David Villa ya luce la camiseta del New York City","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg","width":560,"height":350},"datePublished":"2014-11-14T14:23:27+01:00","dateModified":"2014-11-14T14:23:50+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el noviembre 14, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#webpage","url":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/","name":"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365","description":"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg","@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#mainImage","width":560,"height":350},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/#mainImage"},"datePublished":"2014-11-14T14:23:27+01:00","dateModified":"2014-11-14T14:23:50+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365","og:description":"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar","og:url":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg","og:image:width":560,"og:image:height":350,"article:published_time":"2014-11-14T16:23:27+00:00","article:modified_time":"2014-11-14T16:23:50+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"David Villa ya luce la camiseta del New York City | Cand\u00e1s 365","twitter:description":"BercodiPress: Los aficionados del Melbourne se quedaron con las ganas de ver a David Villa en m\u00e1s encuentros, pero ahora comienza para el asturiano una nueva etapa en Estados Unidos. Ayer estren\u00f3 la nueva equipaci\u00f3n del que ser\u00e1 su equipo para los pr\u00f3ximos tres a\u00f1os, el New York City Football Club. El acto tuvo lugar","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/villa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"5237","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 09:59:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:08","updated":"2026-05-13 09:59:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDavid Villa ya luce la camiseta del New York City\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"David Villa ya luce la camiseta del New York City","link":"https:\/\/candas365.es\/noticias\/david-villa-ya-luce-la-camiseta-del-new-york-city\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5237"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/5238"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}