{"id":5189,"date":"2014-11-13T17:24:11","date_gmt":"2014-11-13T19:24:11","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5189"},"modified":"2014-11-13T17:24:11","modified_gmt":"2014-11-13T19:24:11","slug":"el-tiempo-en-carreno-viernes-14-noviembre-2014","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/","title":{"rendered":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-225\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-360x270.jpg\" alt=\"NUBOSO\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-150x113.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-450x338.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO-90x67.jpg 90w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente Sudoeste variando a Este en las \u00faltimas horas del dia.<\/p>\n<p>En los pr\u00f3ximos d\u00edas, fin de semana, la posibilidad de lluvias ira en aumento y las temperaturas pueden ir en descenso.<\/p>\n<p>Les seguiremos informando.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente<\/p>\n","protected":false},"author":1,"featured_media":225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5189","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-13T19:24:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-13T19:24:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#listItem\",\"name\":\"El Tiempo en Carre\\u00f1o, viernes 14 Noviembre 2014\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#listItem\",\"position\":3,\"name\":\"El Tiempo en Carre\\u00f1o, viernes 14 Noviembre 2014\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#newsarticle\",\"name\":\"El Tiempo en Carre\\u00f1o, viernes 14 Noviembre 2014 | Cand\\u00e1s 365\",\"headline\":\"El Tiempo en Carre\\u00f1o, viernes 14 Noviembre 2014\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/NUBOSO.jpg\",\"width\":640,\"height\":480},\"datePublished\":\"2014-11-13T17:24:11+01:00\",\"dateModified\":\"2014-11-13T17:24:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el noviembre 13, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/\",\"name\":\"El Tiempo en Carre\\u00f1o, viernes 14 Noviembre 2014 | Cand\\u00e1s 365\",\"description\":\"Jornada de viernes en el Concejo de Carre\\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\\u00e1 superior al 20% a lo largo del d\\u00eda, las temperaturas ser\\u00e1n de 9 grados de m\\u00ednima media y unos 18 de m\\u00e1xima, con vientos de componente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/NUBOSO.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#mainImage\",\"width\":640,\"height\":480},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-tiempo-en-carreno-viernes-14-noviembre-2014\\\/#mainImage\"},\"datePublished\":\"2014-11-13T17:24:11+01:00\",\"dateModified\":\"2014-11-13T17:24:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365","description":"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente","canonical_url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#listItem","name":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#listItem","position":3,"name":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#newsarticle","name":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365","headline":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg","width":640,"height":480},"datePublished":"2014-11-13T17:24:11+01:00","dateModified":"2014-11-13T17:24:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el noviembre 13, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/","name":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365","description":"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg","@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#mainImage","width":640,"height":480},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/#mainImage"},"datePublished":"2014-11-13T17:24:11+01:00","dateModified":"2014-11-13T17:24:11+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365","og:description":"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente","og:url":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg","og:image:width":640,"og:image:height":480,"article:published_time":"2014-11-13T19:24:11+00:00","article:modified_time":"2014-11-13T19:24:11+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014 | Cand\u00e1s 365","twitter:description":"Jornada de viernes en el Concejo de Carre\u00f1o en la que se esperan nubes y claros y en la que la posibilidad de lluvias en un principio no ser\u00e1 superior al 20% a lo largo del d\u00eda, las temperaturas ser\u00e1n de 9 grados de m\u00ednima media y unos 18 de m\u00e1xima, con vientos de componente","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/NUBOSO.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365"},"aioseo_meta_data":{"post_id":"5189","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 09:53:08","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:07","updated":"2026-05-13 09:53:08","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"El Tiempo en Carre\u00f1o, viernes 14 Noviembre 2014","link":"https:\/\/candas365.es\/noticias\/el-tiempo-en-carreno-viernes-14-noviembre-2014\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5189"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/225"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}