{"id":5156,"date":"2014-11-12T17:45:38","date_gmt":"2014-11-12T19:45:38","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=5156"},"modified":"2014-11-12T17:45:38","modified_gmt":"2014-11-12T19:45:38","slug":"la-dieta-mediterranea-tambien-mejora-el-medio-ambiente","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/","title":{"rendered":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-5157\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380-360x240.jpg\" alt=\"Greek salad\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg 570w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>SINC &#8211; En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria.<\/p>\n<p>Un nuevo estudio liderado por David Tilman, ec\u00f3logo de la Universidad de Minnesota (EE UU), revela que un cambio de tendencia en el consumo actual y el seguimiento de una dieta m\u00e1s saludable \u2013mediterr\u00e1nea, vegetariana o basada en el pescado\u2013, podr\u00eda no solo aumentar la esperanza y la calidad de vida, sino tambi\u00e9n reducir las emisiones de gas de efecto invernadero y preservar el h\u00e1bitat de las especies en peligro de extinci\u00f3n.<\/p>\n<p>\u201cCambiar la dieta puede aumentar nuestra esperanza de vida una d\u00e9cada a la vez que se puede prevenir el masivo da\u00f1o medioambiental\u201d, explica Tilman.<\/p>\n<p>Los resultados, publicados esta semana en Nature, sugieren que la modificaci\u00f3n de las dietas pod\u00eda reducir no solo la incidencia de la diabetes tipo II, las enfermedades coronarias y otras enfermedades cr\u00f3nicas, sino tambi\u00e9n las emisiones de gas de efecto invernadero en la agricultura global y la degradaci\u00f3n del h\u00e1bitat.<\/p>\n<p>\u201cLas emisiones globales de gas de efecto invernadero ser\u00edan reducidas por una cantidad equivalente a las emisiones actuales de todos los coches, camiones, trenes, barcos y aviones. Adem\u00e1s, este cambio en la dieta podr\u00eda evitar la destrucci\u00f3n de bosques tropicales y sabanas de un tama\u00f1o equivalente a la mitad de los EE UU\u00bb, a\u00f1ade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SINC &#8211; En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por<\/p>\n","protected":false},"author":1,"featured_media":5157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5156","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-12T19:45:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-12T19:45:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#listItem\",\"name\":\"La dieta mediterr\\u00e1nea tambi\\u00e9n mejora el medio ambiente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#listItem\",\"position\":3,\"name\":\"La dieta mediterr\\u00e1nea tambi\\u00e9n mejora el medio ambiente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#newsarticle\",\"name\":\"La dieta mediterr\\u00e1nea tambi\\u00e9n mejora el medio ambiente | Cand\\u00e1s 365\",\"headline\":\"La dieta mediterr\\u00e1nea tambi\\u00e9n mejora el medio ambiente\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg\",\"width\":570,\"height\":380},\"datePublished\":\"2014-11-12T17:45:38+01:00\",\"dateModified\":\"2014-11-12T17:45:38+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el noviembre 12, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/\",\"name\":\"La dieta mediterr\\u00e1nea tambi\\u00e9n mejora el medio ambiente | Cand\\u00e1s 365\",\"description\":\"SINC - En medio siglo, la poblaci\\u00f3n mundial ha evolucionado en sus h\\u00e1bitos alimentarios. La globalizaci\\u00f3n del consumo de az\\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\\u00f1o medioambiental producido por la alta producci\\u00f3n alimentaria. Un nuevo estudio liderado por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#mainImage\",\"width\":570,\"height\":380},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\\\/#mainImage\"},\"datePublished\":\"2014-11-12T17:45:38+01:00\",\"dateModified\":\"2014-11-12T17:45:38+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365","description":"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por","canonical_url":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#listItem","name":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#listItem","position":3,"name":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#newsarticle","name":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365","headline":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg","width":570,"height":380},"datePublished":"2014-11-12T17:45:38+01:00","dateModified":"2014-11-12T17:45:38+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el noviembre 12, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/","name":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365","description":"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg","@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#mainImage","width":570,"height":380},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/#mainImage"},"datePublished":"2014-11-12T17:45:38+01:00","dateModified":"2014-11-12T17:45:38+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365","og:description":"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por","og:url":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg","og:image:width":570,"og:image:height":380,"article:published_time":"2014-11-12T19:45:38+00:00","article:modified_time":"2014-11-12T19:45:38+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente | Cand\u00e1s 365","twitter:description":"SINC - En medio siglo, la poblaci\u00f3n mundial ha evolucionado en sus h\u00e1bitos alimentarios. La globalizaci\u00f3n del consumo de az\u00facares refinados, grasas saturadas, aceite y alimentos como la carne ha generado la aparici\u00f3n y aumento de enfermedades cardiovasculares, y ha agravado el da\u00f1o medioambiental producido por la alta producci\u00f3n alimentaria. Un nuevo estudio liderado por","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/La-dieta-mediterranea-tambien-mejora-el-medio-ambiente_image_380.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"5156","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 09:47:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:50:06","updated":"2026-05-13 09:47:19","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"La dieta mediterr\u00e1nea tambi\u00e9n mejora el medio ambiente","link":"https:\/\/candas365.es\/noticias\/la-dieta-mediterranea-tambien-mejora-el-medio-ambiente\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=5156"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/5156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/5157"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=5156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=5156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=5156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}