{"id":4927,"date":"2014-11-04T16:22:13","date_gmt":"2014-11-04T18:22:13","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=4927"},"modified":"2014-11-04T16:22:13","modified_gmt":"2014-11-04T18:22:13","slug":"laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/","title":{"rendered":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-4928\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg\" alt=\"Laboral\" width=\"360\" height=\"269\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral-150x112.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral-90x67.jpg 90w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra.<\/p>\n<p>El programa tiene dos modalidades: las Residencias de Producci\u00f3n y las Residencias T\u00e9cnicas. Las primeras, con una duraci\u00f3n de cuatro semanas, tendr\u00e1n por objeto la producci\u00f3n de una nueva obra de acuerdo con el proyecto presentando, para lo que se dispondr\u00e1 durante tres semanas de espacios correspondientes a salas de ensayos y durante una semana del espacio esc\u00e9nico del Teatro de la Laboral. Las Residencias de Producci\u00f3n estar\u00e1n dotadas de una ayuda econ\u00f3mica de un m\u00e1ximo de 4.000 euros y de un m\u00ednimo de 1.000 euros por proyecto, adem\u00e1s de disponer de los medios t\u00e9cnicos del Teatro durante toda la residencia.<\/p>\n<p>Las Residencias T\u00e9cnicas tendr\u00e1n una duraci\u00f3n de una o dos semanas y su objetivo es ofrecer un espacio de concepci\u00f3n, remate o reflexi\u00f3n de un proyecto esc\u00e9nico, sin que tenga que desembocar en un nuevo resultado art\u00edstico, para lo que se pondr\u00e1 a su disposici\u00f3n las salas de ensayo del Teatro de la Laboral.<\/p>\n<p>Las solicitudes para participar en este programa se podr\u00e1n presentar hasta el 4 de diciembre. Se puede consultar la documentaci\u00f3n necesaria y descargarse el impreso de solicitud a cumplimentar en la web de Laboral Ciudad de la Cultura (www.laboralciudaddelacultura.com) y de la Sociedad P\u00fablica de Promoci\u00f3n Tur\u00edstica y Cultural del Principado de Asturias (www.recrea.asturias.es).<\/p>\n<p>La valoraci\u00f3n de las ofertas se realizar\u00e1 por una Comisi\u00f3n integrada por profesionales de la creaci\u00f3n, gesti\u00f3n y producci\u00f3n de artes esc\u00e9nicas, que seleccionar\u00e1 un m\u00e1ximo de un proyecto por persona f\u00edsica o jur\u00eddica atendiendo a la calidad y valor art\u00edstico del proyecto, la viabilidad t\u00e9cnica y art\u00edstica del proyecto en relaci\u00f3n a los medios disponibles y la propuesta formativa complementaria que acompa\u00f1a al proyecto presentado.<\/p>\n<p>Una vez estudiadas todas las solicitudes, la Comisi\u00f3n de Valoraci\u00f3n emitir\u00e1 un informe en el que se ordenar\u00e1n los proyectos seleccionados, concret\u00e1ndose con posterioridad las fechas de cada residencia en funci\u00f3n del orden de los proyectos y disponibilidad. El periodo de este programa de residencias es el comprendido entre el 1 de enero y el 30 de junio de 2015.<\/p>\n<p>El programa de Artes Esc\u00e9nicas en Residencia se enmarca en la actividad del Centro de Recursos Esc\u00e9nicos, un proyecto con sede en Laboral Ciudad de la Cultura que ofrecer\u00e1 apoyo a la creaci\u00f3n art\u00edstica y a la producci\u00f3n de las compa\u00f1\u00edas profesionales asturianas. As\u00ed, se pone a disposici\u00f3n de los creadores recursos econ\u00f3micos, instalaciones y medios t\u00e9cnicos que impulsen la creaci\u00f3n esc\u00e9nica y faciliten la consecuci\u00f3n de proyectos art\u00edsticos de profesionales de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias<\/p>\n","protected":false},"author":1,"featured_media":4928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4927","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-11-04T18:22:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-11-04T18:22:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#listItem\",\"name\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9ncias en Residencia\\u200f\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#listItem\",\"position\":3,\"name\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9ncias en Residencia\\u200f\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#newsarticle\",\"name\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9ncias en Residencia\\u200f | Cand\\u00e1s 365\",\"headline\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9ncias en Residencia\\u200f\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Laboral.jpg\",\"width\":360,\"height\":269},\"datePublished\":\"2014-11-04T16:22:13+01:00\",\"dateModified\":\"2014-11-04T16:22:13+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el noviembre 4, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/\",\"name\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9ncias en Residencia\\u200f | Cand\\u00e1s 365\",\"description\":\"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\\u00e9nicos de compa\\u00f1\\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\\u00f3n, creaci\\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Laboral.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#mainImage\",\"width\":360,\"height\":269},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\\\/#mainImage\"},\"datePublished\":\"2014-11-04T16:22:13+01:00\",\"dateModified\":\"2014-11-04T16:22:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365","description":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias","canonical_url":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#listItem","name":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#listItem","position":3,"name":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#newsarticle","name":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365","headline":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg","width":360,"height":269},"datePublished":"2014-11-04T16:22:13+01:00","dateModified":"2014-11-04T16:22:13+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el noviembre 4, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#webpage","url":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/","name":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365","description":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg","@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#mainImage","width":360,"height":269},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/#mainImage"},"datePublished":"2014-11-04T16:22:13+01:00","dateModified":"2014-11-04T16:22:13+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365","og:description":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias","og:url":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg","og:image:width":360,"og:image:height":269,"article:published_time":"2014-11-04T18:22:13+00:00","article:modified_time":"2014-11-04T18:22:13+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f | Cand\u00e1s 365","twitter:description":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9nicas en Residencia con el objetivo de apoyar el desarrollo de proyectos esc\u00e9nicos de compa\u00f1\u00edas profesionales asturianas, aportando los recursos del Teatro de la Laboral para la concepci\u00f3n, creaci\u00f3n y puesta en escena de la obra. El programa tiene dos modalidades: las Residencias","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/11\/Laboral.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"4927","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 09:12:29","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:31","updated":"2026-05-13 09:12:29","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLaboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"Laboral Ciudad de la Cultura pone en marcha el Programa de Artes Esc\u00e9ncias en Residencia\u200f","link":"https:\/\/candas365.es\/noticias\/laboral-ciudad-de-la-cultura-pone-en-marcha-el-programa-de-artes-escencias-en-residencia%e2%80%8f\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=4927"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/4928"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=4927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=4927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=4927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}