{"id":4761,"date":"2014-10-30T18:00:23","date_gmt":"2014-10-30T20:00:23","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=4761"},"modified":"2014-10-30T18:00:23","modified_gmt":"2014-10-30T20:00:23","slug":"encuentran-nuevos-genes-implicados-en-el-autismo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/","title":{"rendered":"Encuentran nuevos genes implicados en el autismo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4762\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo-360x240.jpg\" alt=\"Cute 6 years old boy looking through the window\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo-450x301.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg 569w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>SINC &#8211; El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora solo se conoc\u00edan 9, adem\u00e1s de haber identificados otros 74 que probablemente tambi\u00e9n est\u00e1n implicados.<\/p>\n<p>Explican los investigadores que cada uno de estos genes est\u00e1 mutado en m\u00e1s del 5% de los pacientes con autismo, \u201clo que significa una relativamente importante contribuci\u00f3n al riesgo de padecer el trastorno\u201d. En total, se ha analizado todo el ADN codificante del genoma (exoma) en m\u00e1s de 15.000 muestras de padres, ni\u00f1os afectados y individuos sanos no relacionados.<\/p>\n<p>El desarrollo del estudio lo asumi\u00f3 un equipo internacional de 37 instituciones liderado por Joseph D. Buxbaum, del Hospital Mount Sinai (EE UU). La participaci\u00f3n espa\u00f1ola se concentra en los grupos liderados por \u00c1ngel Carracedo, profesor de la Universidad de Santiago (USC), y en el de Mara Paralleda, del Hospital Gregorio Mara\u00f1\u00f3n de Madrid.<\/p>\n<p>\u201cCreo que es el estudio m\u00e1s importante en el que hemos participado hasta la fecha, junto con el de la esquizofrenia, pero a\u00fan queda mucho por hacer\u201d, asegura Carracedo. Los investigadores secuenciaron el exoma y analizaron datos de 3.871 casos de autismo, 2.270 conjuntos de madres, padres e hijos afectados y muestras de control adicionales compilados por el Autism Sequencing Consortium (ASC).<\/p>\n<p>En el an\u00e1lisis de los datos pudieron apreciar cambios heredados y muchos otros que suceden espont\u00e1neamente en los hijos. Los autores tambi\u00e9n comprobaron que mientras que diferencias gen\u00e9ticas raras y muy peque\u00f1as en 103 genes confieren un riesgo relativamente grande de autismo, muchos otros cambios en otros genes a\u00f1aden una cantidad menor de riesgo.<\/p>\n<p><strong><em>Rutas de riesgo<\/em><\/strong><\/p>\n<p>El trabajo, recogido en el \u00faltimo n\u00famero de Nature, se\u00f1ala tres rutas en las que mutaciones en genes confieren riesgo de autismo. Carracedo muestra su sorpresa porque \u201cuna de esas rutas es la que controla el remodelado de la cromatina\u201d, en el proceso de organizaci\u00f3n del material gen\u00e9tico dentro del n\u00facleo de las c\u00e9lulas, el ADN forma un complejo con unas prote\u00ednas llamadas histonas (lo que acaba formando la cromatina).<\/p>\n<p>Otra de las rutas que estar\u00edan ligadas al TEA son los genes que gobiernan la sinapsis, los espacios entre c\u00e9lulas nerviosas, y un tercero ser\u00eda el de aquellos que regulan las etapas b\u00e1sicas que transforman los genes en prote\u00ednas.<\/p>\n<p>Seg\u00fan este nuevo trabajo, las alteraciones en los genes que causan una enfermedad pueden ser heredados o aparecer por primera vez en los hijos (mutaciones de novo), aunque tambi\u00e9n pueden originar una p\u00e9rdida de funci\u00f3n de la prote\u00edna que codifican o producir cambios m\u00e1s peque\u00f1os.<\/p>\n<p>Los estudios anteriores de autismo se hab\u00edan centrado solo en mutaciones de novo que originan p\u00e9rdida de funci\u00f3n, pero aqu\u00ed se han analizado todas \u201cgracias a un gran esfuerzo de an\u00e1lisis bioinform\u00e1tico que permiti\u00f3 ver que las mutaciones m\u00e1s sutiles contribuyen de forma muy importante al autismo\u201d.<\/p>\n<p>El estudio tambi\u00e9n permiti\u00f3 comparar diferencias entre personas de distinto sexo, ya que la gen\u00e9tica femenina \u201cprotege de alguna forma\u201d a las mujeres para padecer TEA. Adem\u00e1s, ha supuesto consecuencias importantes para el diagn\u00f3stico gen\u00e9tico, ya que con el an\u00e1lisis de los genes descubiertos o de todo el exoma se podr\u00e1n diagnosticar muchos m\u00e1s y realizar un asesoramiento gen\u00e9tico a los padres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SINC &#8211; El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora<\/p>\n","protected":false},"author":1,"featured_media":4762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4761","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"569\" \/>\n\t\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-30T20:00:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-30T20:00:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#listItem\",\"name\":\"Encuentran nuevos genes implicados en el autismo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#listItem\",\"position\":3,\"name\":\"Encuentran nuevos genes implicados en el autismo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#newsarticle\",\"name\":\"Encuentran nuevos genes implicados en el autismo | Cand\\u00e1s 365\",\"headline\":\"Encuentran nuevos genes implicados en el autismo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/autimo.jpg\",\"width\":569,\"height\":380},\"datePublished\":\"2014-10-30T18:00:23+01:00\",\"dateModified\":\"2014-10-30T18:00:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el octubre 30, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/\",\"name\":\"Encuentran nuevos genes implicados en el autismo | Cand\\u00e1s 365\",\"description\":\"SINC - El mayor trabajo jam\\u00e1s realizado sobre el autismo desde el punto de vista gen\\u00e9tico permite aumentar de forma extraordinaria, seg\\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\\u00famero de los genes relacionados con este s\\u00edndrome a 33, de los que hasta ahora\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/autimo.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#mainImage\",\"width\":569,\"height\":380},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentran-nuevos-genes-implicados-en-el-autismo\\\/#mainImage\"},\"datePublished\":\"2014-10-30T18:00:23+01:00\",\"dateModified\":\"2014-10-30T18:00:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365","description":"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora","canonical_url":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#listItem","name":"Encuentran nuevos genes implicados en el autismo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#listItem","position":3,"name":"Encuentran nuevos genes implicados en el autismo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#newsarticle","name":"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365","headline":"Encuentran nuevos genes implicados en el autismo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg","width":569,"height":380},"datePublished":"2014-10-30T18:00:23+01:00","dateModified":"2014-10-30T18:00:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el octubre 30, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#webpage","url":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/","name":"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365","description":"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg","@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#mainImage","width":569,"height":380},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/#mainImage"},"datePublished":"2014-10-30T18:00:23+01:00","dateModified":"2014-10-30T18:00:23+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365","og:description":"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora","og:url":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg","og:image:width":569,"og:image:height":380,"article:published_time":"2014-10-30T20:00:23+00:00","article:modified_time":"2014-10-30T20:00:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Encuentran nuevos genes implicados en el autismo | Cand\u00e1s 365","twitter:description":"SINC - El mayor trabajo jam\u00e1s realizado sobre el autismo desde el punto de vista gen\u00e9tico permite aumentar de forma extraordinaria, seg\u00fan sus promotores, la lista de genes relacionados con el trastorno del espectro autista (TEA). El estudio aumenta el n\u00famero de los genes relacionados con este s\u00edndrome a 33, de los que hasta ahora","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/10\/autimo.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"4761","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 08:48:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:14","updated":"2026-05-13 08:48:24","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEncuentran nuevos genes implicados en el autismo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"Encuentran nuevos genes implicados en el autismo","link":"https:\/\/candas365.es\/noticias\/encuentran-nuevos-genes-implicados-en-el-autismo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=4761"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/4762"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=4761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=4761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=4761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}