{"id":46537,"date":"2017-04-13T21:11:21","date_gmt":"2017-04-13T21:11:21","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=46537"},"modified":"2017-04-14T10:20:50","modified_gmt":"2017-04-14T10:20:50","slug":"gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/","title":{"rendered":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-46538\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-321x300.jpg\" alt=\"\" width=\"321\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-321x300.jpg 321w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-514x480.jpg 514w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-768x717.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-1536x1434.jpg 1536w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-150x140.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-450x420.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-1200x1120.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-696x650.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone-1068x997.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg 1656w\" sizes=\"(max-width: 321px) 100vw, 321px\" \/>Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc.<\/p>\n<p>Por ello, \u00abGremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad\u00bb, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto lo saben bien en Caterpillar, empresa de maquinaria de construcci\u00f3n que adem\u00e1s tiene una l\u00ednea de smartphones ideados para que aguanten las condiciones de trabajo m\u00e1s duras: golpes, altas temperaturas, salpicaduras, inmersiones, etc.<\/p>\n<p>En concreto, se usa el modelo CAT S60, un tel\u00e9fono m\u00f3vil que, adem\u00e1s de un dise\u00f1o y construcci\u00f3n muy particulares, posee un certificado de impermeabilidad a 5 metros y es el \u00fanico que incluye una c\u00e1mara t\u00e9rmica fabricada por Flir, compa\u00f1\u00eda reconocida en este tipo de c\u00e1maras y como fabricante en sistemas de termograf\u00eda, visi\u00f3n nocturna y c\u00e1maras de infrarrojos.<\/p>\n<p>Estos dispositivos son muy robustos, de hecho, aqu\u00ed nos hemos de olvidar de las modas en dise\u00f1o, de la delgadez, de metales con colores y pulidos para ser m\u00e1s un reclamo a nivel visual. Estos m\u00f3viles tienen en cuenta la construcci\u00f3n y la resistencia. El CAT S60 es un terminal fabricado para aguantar golpes, altas temperaturas e inmersiones, nada de s\u00f3lo salpicaduras.<\/p>\n<p>Sobre algunas dudas sobre este smartphone, responde Javier Valenzuela, director este de Gremisa asistencia<\/p>\n<p><strong>\u00bfC\u00f3mo es usar un tel\u00e9fono todoterreno con c\u00e1mara t\u00e9rmica?<\/strong><\/p>\n<p>Para nosotros es una gran ayuda. Permite aislar e identificar humedades, condensaciones y fugas potenciales en techos, paredes y suelos sin necesidad de descubrir. Tambi\u00e9n se pueden detectar conexiones el\u00e9ctricas con sobrecarga<\/p>\n<p><strong>\u00bfEs de uso frecuente?<\/strong><\/p>\n<p>Lo cierto es que se usa a diario multitud de veces. Al principio, sobre todo en las fontaner\u00edas. Pero en la actualidad en todas las actividades, su resistencia a los impactos y las ca\u00eddas lo hacen id\u00f3neo para nuestra actividad.<\/p>\n<p>Podemos tomar fotos bajo el agua. Su visi\u00f3n nocturna tiene 13 mega p\u00edxeles de calidad, algo que tiene multitud de utilidades en nuestros trabajos; desde detectar tuber\u00edas detr\u00e1s de una pared hasta ver m\u00e1s all\u00e1 de nubes de humo.<\/p>\n<p><strong>\u00bfQu\u00e9 sistema operativo incorpora?<\/strong><\/p>\n<p>Se maneja como un m\u00f3vil m\u00e1s. Incorpora Android y pantalla t\u00e1ctil. Nuestros programas funcionan con normalidad. Su principal ventaja es que es casi irrompible y capaz de ver en la oscuridad total.<\/p>\n<p>En Gremisa Asistencia, llevamos m\u00e1s de 16 a\u00f1os en el sector del seguro como empresa reparadora. Damos servicio y atendemos siniestros del hogar, comunidades y comercios en Zaragoza, Huesca, Teruel, Tarragona y M\u00e1laga, tanto en las capitales como en toda la provincia. Queremos ser una compa\u00f1\u00eda l\u00edder en la prestaci\u00f3n y gesti\u00f3n de servicios de reparaci\u00f3n. 24 horas al d\u00eda y 365 d\u00eda al a\u00f1o. Y este tipo de herramienta hace mucho m\u00e1s f\u00e1cil nuestro trabajo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, \u00abGremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad\u00bb, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto<\/p>\n","protected":false},"author":1,"featured_media":46538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-46537","1":"post","2":"type-post","3":"status-publish","4":"format-gallery","5":"has-post-thumbnail","7":"category-canal-empresas","8":"post_format-post-format-gallery"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, &quot;Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad&quot;, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, &quot;Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad&quot;, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1656\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1546\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-13T21:11:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-04-14T10:20:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, &quot;Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad&quot;, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#listItem\",\"name\":\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\\u00eda de \\u00faltima generaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#listItem\",\"position\":3,\"name\":\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\\u00eda de \\u00faltima generaci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#newsarticle\",\"name\":\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\\u00eda de \\u00faltima generaci\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\\u00eda de \\u00faltima generaci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491907935_gremisa_phone.jpg\",\"width\":1656,\"height\":1546},\"datePublished\":\"2017-04-13T21:11:21+02:00\",\"dateModified\":\"2017-04-14T10:20:50+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#webpage\"},\"articleSection\":\"Canal Empresas, Galer\\u00eda\",\"dateline\":\"Publicado el abril 13, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/\",\"name\":\"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\\u00eda de \\u00faltima generaci\\u00f3n | Cand\\u00e1s 365\",\"description\":\"Quedarse sin esta herramienta no es una opci\\u00f3n y es un gran problema. Por el tipo de actividad, estos m\\u00f3viles est\\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\\u00eddas, etc. Por ello, \\\"Gremisa Asistencia est\\u00e1 incorporando m\\u00f3viles que por sus caracter\\u00edsticas encajan mejor en su actividad\\\", excplica Jos\\u00e9 Mar\\u00eda Amoedo, director general de la empresa. Esto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491907935_gremisa_phone.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#mainImage\",\"width\":1656,\"height\":1546},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\\\/#mainImage\"},\"datePublished\":\"2017-04-13T21:11:21+02:00\",\"dateModified\":\"2017-04-14T10:20:50+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365","description":"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, \"Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad\", excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto","canonical_url":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#listItem","name":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#listItem","position":3,"name":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#newsarticle","name":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365","headline":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg","width":1656,"height":1546},"datePublished":"2017-04-13T21:11:21+02:00","dateModified":"2017-04-14T10:20:50+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#webpage"},"articleSection":"Canal Empresas, Galer\u00eda","dateline":"Publicado el abril 13, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#webpage","url":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/","name":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365","description":"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, \"Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad\", excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg","@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#mainImage","width":1656,"height":1546},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/#mainImage"},"datePublished":"2017-04-13T21:11:21+02:00","dateModified":"2017-04-14T10:20:50+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365","og:description":"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, &quot;Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad&quot;, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto","og:url":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg","og:image:width":1656,"og:image:height":1546,"article:published_time":"2017-04-13T21:11:21+00:00","article:modified_time":"2017-04-14T10:20:50+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n | Cand\u00e1s 365","twitter:description":"Quedarse sin esta herramienta no es una opci\u00f3n y es un gran problema. Por el tipo de actividad, estos m\u00f3viles est\u00e1n expuestos a golpes, humedades, sustancias corrosivas, ca\u00eddas, etc. Por ello, &quot;Gremisa Asistencia est\u00e1 incorporando m\u00f3viles que por sus caracter\u00edsticas encajan mejor en su actividad&quot;, excplica Jos\u00e9 Mar\u00eda Amoedo, director general de la empresa. Esto","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491907935_gremisa_phone.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"46537","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 10:56:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:01:40","updated":"2025-08-25 10:56:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tGremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Gremisa Asistencia refuerza el mundo asegurador con el uso de la telefon\u00eda de \u00faltima generaci\u00f3n","link":"https:\/\/candas365.es\/noticias\/gremisa-asistencia-refuerza-el-mundo-asegurador-con-el-uso-de-la-telefonia-de-ultima-generacion\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=46537"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/46538"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=46537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=46537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=46537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}