{"id":46528,"date":"2017-04-13T21:05:17","date_gmt":"2017-04-13T21:05:17","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=46528"},"modified":"2017-04-13T21:05:17","modified_gmt":"2017-04-13T21:05:17","slug":"jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/","title":{"rendered":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-46529\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex-360x113.jpg\" alt=\"\" width=\"360\" height=\"113\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex-360x113.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex-150x47.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg 380w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Jabonex es una tienda online con certificado de seguridad otorgado por &#8216;Confianza Online&#8217; que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha, colonias, insecticidas y desinfectantes, detergentes l\u00edquido y en polvo para lavander\u00edas, productos de limpieza para coches, limpieza ecol\u00f3gica, limpiadores espec\u00edficos, limpiadores generales, limpieza de graffitis, limpiadores multiusos industriales, productos para el mantenimiento de piscinas, tratamiento de suelos y gama econ\u00f3mica. Categor\u00edas que tienen, cada una de ellas, productos espec\u00edficos y una oferta global que no dejar\u00e1 a nadie indiferente.<\/p>\n<p>Todos estos productos pueden comprarse online, l\u00f3gicamente desde cualquier lugar, con cualquier dispositivo conectado a Internet, y en cualquier momento. Las caracter\u00edsticas de la compra online son muy valoradas por cada vez m\u00e1s profesionales, que adecuan el momento de compra y los siempre atractivos precios de la compra a partir de Internet con sus jornadas laborales y recursos.<\/p>\n<p>La empresa de servicios de venta de productos de limpieza ofrece adem\u00e1s una m\u00e1s que destacable promoci\u00f3n de un descuento del 15% en todos los productos, v\u00e1lido hasta el 30 de abril de 2017 por un pedido m\u00ednimo de 50\u20ac +IVA. Para acceder a este atractivo descuento, solo hay que visitar su p\u00e1gina web y adquirir los productos deseados a partir de su plataforma de pagos seguros, y as\u00ed se recibir\u00e1 en la empresa -o en el punto deseado- los productos adquiridos en tan solo unos d\u00edas.<\/p>\n<p>Cabe recordar utilizar este c\u00f3digo cup\u00f3n: clientenuevo para disfrutar de este s\u00faper descuento en jabonex.com<\/p>\n<p><strong>Sobre Jabonex<\/strong><\/p>\n<p>Jabonex es una tienda online gestionada por Lavander\u00eda Autoservicio Rapiddo, sita en Campanar, 2, 46920-Mislata (Valencia) en Espa\u00f1a, autosevicio de lavander\u00eda express y venta de productos de limpieza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jabonex es una tienda online con certificado de seguridad otorgado por &#8216;Confianza Online&#8217; que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,<\/p>\n","protected":false},"author":1,"featured_media":46529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-46528","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Jabonex es una tienda online con certificado de seguridad otorgado por &#039;Confianza Online&#039; que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Jabonex es una tienda online con certificado de seguridad otorgado por &#039;Confianza Online&#039; que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t\t<meta property=\"og:image:height\" content=\"119\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-13T21:05:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-04-13T21:05:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Jabonex es una tienda online con certificado de seguridad otorgado por &#039;Confianza Online&#039; que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#listItem\",\"name\":\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#listItem\",\"position\":3,\"name\":\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#newsarticle\",\"name\":\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\\u00e1s 365\",\"headline\":\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491937308_jabonex.jpg\",\"width\":380,\"height\":119},\"datePublished\":\"2017-04-13T21:05:17+02:00\",\"dateModified\":\"2017-04-13T21:05:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el abril 13, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/\",\"name\":\"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\\u00e1s 365\",\"description\":\"Jabonex es una tienda online con certificado de seguridad otorgado por 'Confianza Online' que ofrece una amplia y completa selecci\\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\\u00f1o y ducha,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491937308_jabonex.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#mainImage\",\"width\":380,\"height\":119},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\\\/#mainImage\"},\"datePublished\":\"2017-04-13T21:05:17+02:00\",\"dateModified\":\"2017-04-13T21:05:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365","description":"Jabonex es una tienda online con certificado de seguridad otorgado por 'Confianza Online' que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,","canonical_url":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#listItem","name":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#listItem","position":3,"name":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#newsarticle","name":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365","headline":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg","width":380,"height":119},"datePublished":"2017-04-13T21:05:17+02:00","dateModified":"2017-04-13T21:05:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el abril 13, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#webpage","url":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/","name":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365","description":"Jabonex es una tienda online con certificado de seguridad otorgado por 'Confianza Online' que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg","@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#mainImage","width":380,"height":119},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/#mainImage"},"datePublished":"2017-04-13T21:05:17+02:00","dateModified":"2017-04-13T21:05:17+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365","og:description":"Jabonex es una tienda online con certificado de seguridad otorgado por 'Confianza Online' que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,","og:url":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg","og:image:width":380,"og:image:height":119,"article:published_time":"2017-04-13T21:05:17+00:00","article:modified_time":"2017-04-13T21:05:17+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online | Cand\u00e1s 365","twitter:description":"Jabonex es una tienda online con certificado de seguridad otorgado por 'Confianza Online' que ofrece una amplia y completa selecci\u00f3n de productos de limpieza industrial de calidad a buen precio, cuya oferta se compone b\u00e1sicamente de: ambientadores profesionales, desengrasantes para cocina, desincrustantes industriales, c\u00e1psulas hidrosolubles, higiene alimentaria, higiene personal, limpieza de manos, ba\u00f1o y ducha,","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491937308_jabonex.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"46528","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 10:56:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:01:40","updated":"2025-08-25 10:56:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tJabonex, la tienda online de productos de limpieza profesional, lanza una promo online\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Jabonex, la tienda online de productos de limpieza profesional, lanza una promo online","link":"https:\/\/candas365.es\/noticias\/jabonex-la-tienda-online-de-productos-de-limpieza-profesional-lanza-una-promo-online\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=46528"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/46529"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=46528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=46528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=46528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}