{"id":46285,"date":"2017-04-08T21:27:53","date_gmt":"2017-04-08T21:27:53","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=46285"},"modified":"2017-04-08T21:27:53","modified_gmt":"2017-04-08T21:27:53","slug":"due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/","title":{"rendered":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-46286\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-360x163.jpg\" alt=\"\" width=\"360\" height=\"163\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-360x163.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-650x295.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-768x349.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-1536x697.jpg 1536w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-150x68.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-450x204.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-1200x545.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-1920x872.jpg 1920w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-655x297.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-696x316.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-1068x485.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender-925x420.jpg 925w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg 2000w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles<\/p>\n<p>El \u00e9xito de Due Home le ha llevado a ir batiendo a\u00f1o tras a\u00f1o sus r\u00e9cords de facturaci\u00f3n. En 2016 llegaron a los 7 millones y las previsiones para 2017 son a\u00fan mejores: estiman que alcanzar\u00e1n la impresionante cantidad de 10 millones.<\/p>\n<p>Este crecimiento en cifras ha llevado aparejadas nuevas necesidades desde el punto de vista de personal e infraestructuras. El equipo ha crecido hasta los 11 integrantes y las oficinas se han quedado peque\u00f1as, con lo que ya est\u00e1n ultimando su traslado a un nuevo &#8216;cuartel general&#8217; mucho m\u00e1s amplio y mejor preparado para los nuevos retos.<\/p>\n<p>Due Home ha sabido entender muy bien lo que es el nuevo paradigma del negocio online y, no es que hayan sufrido una transformaci\u00f3n digital, es que son un comercio nativo digital que surgi\u00f3 pensado directamente para Internet.<\/p>\n<p>La web de Due Home en la que se han volcado desde el inicio es todo un ejemplo de lo que es optimizar a todos los niveles, se preocupan por tener un software s\u00f3lido que soporte la p\u00e1gina, una usabilidad muy depurada y una versi\u00f3n adaptada a m\u00f3viles que les ayuda a explotar la pr\u00f3xima frontera del comercio electr\u00f3nico, lo que se ha dado en llamar el mCommerce o comercio m\u00f3vil.<\/p>\n<p>Pero no todo es la web cuando hablamos de Internet, esta marca catalana tambi\u00e9n ha visto la oportunidad en los diferentes marketplaces y ha entrado en algunos de los m\u00e1s importantes como Amazon, Ebay o Privalia. Esta estrategia amplifica su alcance y, l\u00f3gicamente, tambi\u00e9n su conversi\u00f3n online.<\/p>\n<p>Otro de los pilares sobre los que se cimenta el \u00e9xito es el marketing online. Trabajan la captaci\u00f3n de tr\u00e1fico a trav\u00e9s de las principales plataformas, un blog en el que aportan contenido inspiracional, pr\u00e1ctico y ameno sin olvidarse de una presencia en redes sociales muy activa y participativa.<\/p>\n<p>Due Home ha demostrado que se sigue pudiendo triunfar en Internet siempre que se conozcan el producto, el mercado y el p\u00fablico (y se trabaje duro). Seguro que se esta tienda de muebles seguir\u00e1 dando mucho que hablar y que leer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito<\/p>\n","protected":false},"author":1,"featured_media":46286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-46285","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-08T21:27:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-04-08T21:27:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#listItem\",\"name\":\"Due Home: el crecimiento del mueble de dise\\u00f1o viene apoyado en la venta online\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#listItem\",\"position\":3,\"name\":\"Due Home: el crecimiento del mueble de dise\\u00f1o viene apoyado en la venta online\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#newsarticle\",\"name\":\"Due Home: el crecimiento del mueble de dise\\u00f1o viene apoyado en la venta online | Cand\\u00e1s 365\",\"headline\":\"Due Home: el crecimiento del mueble de dise\\u00f1o viene apoyado en la venta online\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491494820_FullSizeRender.jpg\",\"width\":2000,\"height\":908},\"datePublished\":\"2017-04-08T21:27:53+02:00\",\"dateModified\":\"2017-04-08T21:27:53+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el abril 8, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/\",\"name\":\"Due Home: el crecimiento del mueble de dise\\u00f1o viene apoyado en la venta online | Cand\\u00e1s 365\",\"description\":\"La marca Due Home no es precisamente una reci\\u00e9n llegada al mercado, de hecho lleva bastantes a\\u00f1os haci\\u00e9ndose un hueco cada vez m\\u00e1s importante. Xavi y Estefan\\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \\u00e9xito\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491494820_FullSizeRender.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#mainImage\",\"width\":2000,\"height\":908},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\\\/#mainImage\"},\"datePublished\":\"2017-04-08T21:27:53+02:00\",\"dateModified\":\"2017-04-08T21:27:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365","description":"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito","canonical_url":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#listItem","name":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#listItem","position":3,"name":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#newsarticle","name":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365","headline":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg","width":2000,"height":908},"datePublished":"2017-04-08T21:27:53+02:00","dateModified":"2017-04-08T21:27:53+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el abril 8, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#webpage","url":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/","name":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365","description":"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg","@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#mainImage","width":2000,"height":908},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/#mainImage"},"datePublished":"2017-04-08T21:27:53+02:00","dateModified":"2017-04-08T21:27:53+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365","og:description":"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito","og:url":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg","og:image:width":2000,"og:image:height":908,"article:published_time":"2017-04-08T21:27:53+00:00","article:modified_time":"2017-04-08T21:27:53+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online | Cand\u00e1s 365","twitter:description":"La marca Due Home no es precisamente una reci\u00e9n llegada al mercado, de hecho lleva bastantes a\u00f1os haci\u00e9ndose un hueco cada vez m\u00e1s importante. Xavi y Estefan\u00eda son la cara visible del proyecto y cuentan con el inestimable bagaje que supone pertenecer a una saga compuesta por tres generaciones de especialistas en muebles El \u00e9xito","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491494820_FullSizeRender.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"46285","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 10:36:02","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 11:52:32","updated":"2025-08-25 10:36:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDue Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Due Home: el crecimiento del mueble de dise\u00f1o viene apoyado en la venta online","link":"https:\/\/candas365.es\/noticias\/due-home-el-crecimiento-del-mueble-de-diseno-viene-apoyado-en-la-venta-online\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=46285"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/46286"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=46285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=46285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=46285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}