{"id":46233,"date":"2017-04-07T20:39:58","date_gmt":"2017-04-07T20:39:58","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=46233"},"modified":"2017-04-07T20:39:58","modified_gmt":"2017-04-07T20:39:58","slug":"masterd-lanza-el-curso-de-piloto-de-drones","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/","title":{"rendered":"MasterD lanza el Curso de Piloto de Drones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-46234\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg 640w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada.<\/p>\n<p>Cada d\u00eda, aparecen nuevas oportunidades laborales en este campo y, por ende, hay un mayor n\u00famero de personas interesadas en el mundo de los drones. Por ello, el centro de formaci\u00f3n MasterD ha desarrollado, junto a profesionales del sector altamente cualificados como la ATO Condor Pilot, un completo curso de piloto de drones para poder desarrollar profesionalmente la labor de piloto y operador de drones.<\/p>\n<p>MasterD se diferencia de otros centros de formaci\u00f3n por apostar fuertemente por la innovaci\u00f3n y \u00faltimas tecnolog\u00edas disponibles en el mercado profesional. Todo ello orientado hacia una preparaci\u00f3n basada en el trabajo de conocimientos y habilidades, las cuales permiten a sus alumnos acceder con garant\u00edas a un mercado laboral muy competitivo y en constante evoluci\u00f3n.<\/p>\n<p>Todo piloto y operador de drones debe adquirir los conocimientos y habilidades necesarias para el desempe\u00f1o profesional. Por este motivo, el plan de estudios del curso de piloto de drones de MasterD se divide en cuatro m\u00f3dulos.<\/p>\n<p>El primero de ellos forma al alumno como piloto avanzado de drones. En este m\u00f3dulo, se adquieren los conocimientos te\u00f3ricos y el Certificado de Piloto oficial por la Agencia Estatal de Seguridad A\u00e9rea (AESA), necesario para poder volar drones de hasta 150 Kg de peso, seg\u00fan la ley vigente en nuestro pa\u00eds.<\/p>\n<p>Los alumnos del curso de MasterD tienen la posibilidad de obtener una orientaci\u00f3n personalizada para convertirse en operador de drones, lo que le permitir\u00e1 ejercer las labores de piloto por su cuenta, sin supervisi\u00f3n de terceros. Adem\u00e1s, el curso incluye un dron DJI Phantom 3 Std.<\/p>\n<p>En el m\u00f3dulo de mec\u00e1nica de drones se adquiere la base necesaria para poder realizar reparaciones sencillas o modificaciones de mejora a nuestros drones, sean o no profesionales. Esto incluye tanto el recambio y sustituci\u00f3n de piezas, como la modificaci\u00f3n y mejora de componentes cr\u00edticos.<\/p>\n<p>Un m\u00f3dulo tambi\u00e9n muy importante es el de recursos audiovisuales con drones. Donde se ense\u00f1an nociones b\u00e1sicas para la planificaci\u00f3n y toma de fotograf\u00eda y v\u00eddeo. Algo muy valorado en el sector audiovisual, pues una buena calidad de imagen es indispensable en capturas a\u00e9reas. Por ello, los alumnos de MasterD estudian las principales t\u00e9cnicas y m\u00e9todos para conseguir los mejores resultados.<\/p>\n<p>La parte final del curso trata sobre el an\u00e1lisis de im\u00e1genes con drones para usos industriales, agr\u00edcolas y civiles, as\u00ed como sobre los diferentes tipos de c\u00e1maras que podemos utilizar en cada caso. Pues las posibilidades en el campo del an\u00e1lisis son ilimitadas.<\/p>\n<p>MasterD, por medio de su novedoso Instituto Tecnol\u00f3gico, ha decidido apostar claramente por una profesi\u00f3n de futuro que ha llegado para quedarse y que, sin ninguna duda, proveer\u00e1 de trabajo a todas aquellas personas que cuenten con la cualificaci\u00f3n necesaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen<\/p>\n","protected":false},"author":1,"featured_media":46234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":{"0":"post-46233","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-07T20:39:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-04-07T20:39:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#listItem\",\"name\":\"MasterD lanza el Curso de Piloto de Drones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#listItem\",\"position\":3,\"name\":\"MasterD lanza el Curso de Piloto de Drones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#newsarticle\",\"name\":\"MasterD lanza el Curso de Piloto de Drones | Cand\\u00e1s 365\",\"headline\":\"MasterD lanza el Curso de Piloto de Drones\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491483557_curso_drones_masterd.jpg\",\"width\":640,\"height\":427},\"datePublished\":\"2017-04-07T20:39:58+02:00\",\"dateModified\":\"2017-04-07T20:39:58+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#webpage\"},\"articleSection\":\"Canal Empresas\",\"dateline\":\"Publicado el abril 7, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/\",\"name\":\"MasterD lanza el Curso de Piloto de Drones | Cand\\u00e1s 365\",\"description\":\"La actual revoluci\\u00f3n electr\\u00f3nica y las nuevas tecnolog\\u00edas han irrumpido con fuerza en el mundo de la aviaci\\u00f3n y m\\u00e1s en concreto en el de los drones. Hoy en d\\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\\u00edan de maquinaria pesada o especializada. Cada d\\u00eda, aparecen\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/1491483557_curso_drones_masterd.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#mainImage\",\"width\":640,\"height\":427},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/masterd-lanza-el-curso-de-piloto-de-drones\\\/#mainImage\"},\"datePublished\":\"2017-04-07T20:39:58+02:00\",\"dateModified\":\"2017-04-07T20:39:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365","description":"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen","canonical_url":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#listItem","name":"MasterD lanza el Curso de Piloto de Drones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#listItem","position":3,"name":"MasterD lanza el Curso de Piloto de Drones","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#newsarticle","name":"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365","headline":"MasterD lanza el Curso de Piloto de Drones","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg","width":640,"height":427},"datePublished":"2017-04-07T20:39:58+02:00","dateModified":"2017-04-07T20:39:58+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#webpage"},"articleSection":"Canal Empresas","dateline":"Publicado el abril 7, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#webpage","url":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/","name":"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365","description":"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg","@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#mainImage","width":640,"height":427},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/#mainImage"},"datePublished":"2017-04-07T20:39:58+02:00","dateModified":"2017-04-07T20:39:58+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365","og:description":"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen","og:url":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg","og:image:width":640,"og:image:height":427,"article:published_time":"2017-04-07T20:39:58+00:00","article:modified_time":"2017-04-07T20:39:58+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"MasterD lanza el Curso de Piloto de Drones | Cand\u00e1s 365","twitter:description":"La actual revoluci\u00f3n electr\u00f3nica y las nuevas tecnolog\u00edas han irrumpido con fuerza en el mundo de la aviaci\u00f3n y m\u00e1s en concreto en el de los drones. Hoy en d\u00eda, estas aeronaves no tripuladas han mejorado numerosos procesos de trabajo, los cuales eran muy costosos y requer\u00edan de maquinaria pesada o especializada. Cada d\u00eda, aparecen","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/04\/1491483557_curso_drones_masterd.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"46233","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-25 10:32:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:01:48","updated":"2025-08-25 10:32:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMasterD lanza el Curso de Piloto de Drones\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"MasterD lanza el Curso de Piloto de Drones","link":"https:\/\/candas365.es\/noticias\/masterd-lanza-el-curso-de-piloto-de-drones\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=46233"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/46233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/46234"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=46233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=46233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=46233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}