{"id":4380,"date":"2014-10-26T12:00:52","date_gmt":"2014-10-26T14:00:52","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=4380"},"modified":"2014-10-26T12:00:52","modified_gmt":"2014-10-26T14:00:52","slug":"la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/","title":{"rendered":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s"},"content":{"rendered":"<p>(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas.<\/p>\n<p>Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en la Universidad de Sevilla, abordar\u00e1 los procesos educativos de las mujeres bajo el t\u00edtulo: \u00abEducadas o instruidas: un dilema en la historia de las mujeres\u00bb.<\/p>\n<p>De este modo, el Ayuntamiento busca dar continuidad a las jornadas celebradas en diciembre de 2013 y en mayo de este a\u00f1o, en las que participaron 200 personas, seg\u00fan informaci\u00f3n municipal.<\/p>\n<p>El objetivo de las jornadas feministas es profundizar en el feminismo y reflexionar sobre el papel de la mujer en la actualidad, sobre la historia del movimiento feminista y sus logros, y sobre los retos pendientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en<\/p>\n","protected":false},"author":1,"featured_media":270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4380","post","type-post","status-publish","format-standard","has-post-thumbnail","category-agenda"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"agenda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-26T14:00:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-26T14:00:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#listItem\",\"name\":\"La catedr\\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#listItem\",\"position\":3,\"name\":\"La catedr\\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#newsarticle\",\"name\":\"La catedr\\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\\u00e9s | Cand\\u00e1s 365\",\"headline\":\"La catedr\\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\\u00e9s\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"width\":500,\"height\":331},\"datePublished\":\"2014-10-26T12:00:52+01:00\",\"dateModified\":\"2014-10-26T12:00:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#webpage\"},\"articleSection\":\"Agenda\",\"dateline\":\"Publicado el octubre 26, 2014.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/\",\"name\":\"La catedr\\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\\u00e9s | Cand\\u00e1s 365\",\"description\":\"(EUROPA PRESS) La Concejal\\u00eda de Igualdad del Ayuntamiento de Avil\\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\\u00e1n este pr\\u00f3ximo jueves en el Palacio de Valdecarzana y contar\\u00e1n con la catedr\\u00e1tica Consuelo Flecha que ofrecer\\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\\u00eda, catedr\\u00e1tica de historia de la educaci\\u00f3n en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/agenda.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#mainImage\",\"width\":500,\"height\":331},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\\\/#mainImage\"},\"datePublished\":\"2014-10-26T12:00:52+01:00\",\"dateModified\":\"2014-10-26T12:00:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365","description":"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en","canonical_url":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/","robots":"max-image-preview:large","keywords":"agenda","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/candas365.es\/noticias\/category\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#listItem","name":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#listItem","position":3,"name":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#newsarticle","name":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365","headline":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","width":500,"height":331},"datePublished":"2014-10-26T12:00:52+01:00","dateModified":"2014-10-26T12:00:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#webpage"},"articleSection":"Agenda","dateline":"Publicado el octubre 26, 2014."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/","name":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365","description":"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#mainImage","width":500,"height":331},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/#mainImage"},"datePublished":"2014-10-26T12:00:52+01:00","dateModified":"2014-10-26T12:00:52+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365","og:description":"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en","og:url":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","og:image:width":500,"og:image:height":331,"article:published_time":"2014-10-26T14:00:52+00:00","article:modified_time":"2014-10-26T14:00:52+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s | Cand\u00e1s 365","twitter:description":"(EUROPA PRESS) La Concejal\u00eda de Igualdad del Ayuntamiento de Avil\u00e9s pone en marcha la III Jornada Feminista, que se celebrar\u00e1n este pr\u00f3ximo jueves en el Palacio de Valdecarzana y contar\u00e1n con la catedr\u00e1tica Consuelo Flecha que ofrecer\u00e1 una ponencia a partir de las 18.30 horas. Consuelo Flecha Garc\u00eda, catedr\u00e1tica de historia de la educaci\u00f3n en","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2014\/09\/agenda.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"4380","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 07:49:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:24","updated":"2026-05-13 07:49:28","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Agenda","link":"https:\/\/candas365.es\/noticias\/category\/agenda\/"},{"label":"La catedr\u00e1tica Consuelo Flecha participa como ponente en la III Jornada Feminista de Avil\u00e9s","link":"https:\/\/candas365.es\/noticias\/la-catedratica-consuelo-flecha-participa-como-ponente-en-la-iii-jornada-feminista-de-aviles\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=4380"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/4380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=4380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=4380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=4380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}