{"id":40546,"date":"2017-01-15T20:47:27","date_gmt":"2017-01-15T20:47:27","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=40546"},"modified":"2017-01-15T20:47:27","modified_gmt":"2017-01-15T20:47:27","slug":"horoscopo-de-acuario-lunes-16-de-enero-2017","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/","title":{"rendered":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017"},"content":{"rendered":"<p><span style=\"line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-40524\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\" alt=\"\" width=\"360\" height=\"219\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017-150x91.jpg 150w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas<\/span><\/span><\/p>\n<p><span style=\"line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">La vida siempre nos aporta \u201cvariedad\u201d cuando nosotros la buscamos, en casa y sentados frente a una pantalla es dif\u00edcil sentir y tocar al resto del mundo, hoy es un buen lunes para relacionarse, para estar con alguien y para hablar con otros<\/span><\/span><\/p>\n<p><span style=\"line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">Tus planes los decides tu, y t\u00fa ser\u00e1s quien al final tenga la \u00faltima palabra, recuerda que en la vida siempre es bueno saber ceder o saber sumar, no todo tiene que ser \u201cvaso medio lleno o medio vac\u00edo\u201d, mira a la vida con optimismo.<\/span><\/span><\/p>\n<p><span style=\"line-height: 115%; font-family: 'Arial','sans-serif'; font-size: 12pt;\"><span style=\"color: #000000;\">N\u00famero diario de la suerte el 9<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La<\/p>\n","protected":false},"author":1,"featured_media":40524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-40546","post","type-post","status-publish","format-standard","has-post-thumbnail","category-horoscopo-diario"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"hor\u00f3scopo diario\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t\t<meta property=\"og:image:height\" content=\"219\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-01-15T20:47:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-01-15T20:47:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"position\":2,\"name\":\"Hor\\u00f3scopo diario\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#listItem\",\"name\":\"Hor\\u00f3scopo de Acuario lunes 16 de enero 2017\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#listItem\",\"position\":3,\"name\":\"Hor\\u00f3scopo de Acuario lunes 16 de enero 2017\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/horoscopo-diario\\\/#listItem\",\"name\":\"Hor\\u00f3scopo diario\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#newsarticle\",\"name\":\"Hor\\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\\u00e1s 365\",\"headline\":\"Hor\\u00f3scopo de Acuario lunes 16 de enero 2017\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\",\"width\":360,\"height\":219},\"datePublished\":\"2017-01-15T20:47:27+01:00\",\"dateModified\":\"2017-01-15T20:47:27+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#webpage\"},\"articleSection\":\"Hor\\u00f3scopo diario\",\"dateline\":\"Publicado el enero 15, 2017.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/\",\"name\":\"Hor\\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\\u00e1s 365\",\"description\":\"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\\u00edan dejado inquieta, en este nuevo d\\u00eda tendr\\u00e1s imaginaci\\u00f3n, buenas ideas y el apoyo de personas con las que podr\\u00e1s hacer mucho m\\u00e1s de lo que imaginas La\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#mainImage\",\"width\":360,\"height\":219},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/horoscopo-de-acuario-lunes-16-de-enero-2017\\\/#mainImage\"},\"datePublished\":\"2017-01-15T20:47:27+01:00\",\"dateModified\":\"2017-01-15T20:47:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365","description":"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La","canonical_url":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/","robots":"max-image-preview:large","keywords":"hor\u00f3scopo diario","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","position":2,"name":"Hor\u00f3scopo diario","item":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#listItem","name":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#listItem","position":3,"name":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/#listItem","name":"Hor\u00f3scopo diario"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#newsarticle","name":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365","headline":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg","width":360,"height":219},"datePublished":"2017-01-15T20:47:27+01:00","dateModified":"2017-01-15T20:47:27+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#webpage"},"articleSection":"Hor\u00f3scopo diario","dateline":"Publicado el enero 15, 2017."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#webpage","url":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/","name":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365","description":"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg","@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#mainImage","width":360,"height":219},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/#mainImage"},"datePublished":"2017-01-15T20:47:27+01:00","dateModified":"2017-01-15T20:47:27+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365","og:description":"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La","og:url":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg","og:image:width":360,"og:image:height":219,"article:published_time":"2017-01-15T20:47:27+00:00","article:modified_time":"2017-01-15T20:47:27+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017 | Cand\u00e1s 365","twitter:description":"Lunes e inicio de semana, tienes todo a tu favor para darle la vuelta a las tareas que dejaste pendientes o para resolver las situaciones que te hab\u00edan dejado inquieta, en este nuevo d\u00eda tendr\u00e1s imaginaci\u00f3n, buenas ideas y el apoyo de personas con las que podr\u00e1s hacer mucho m\u00e1s de lo que imaginas La","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/01\/HOROSCOPO-MEYRISA-16-ENERO-2017.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"40546","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-17 03:17:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:06:42","updated":"2026-05-17 03:17:20","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/\" title=\"Hor\u00f3scopo diario\">Hor\u00f3scopo diario<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tHor\u00f3scopo de Acuario lunes 16 de enero 2017\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Hor\u00f3scopo diario","link":"https:\/\/candas365.es\/noticias\/category\/horoscopo-diario\/"},{"label":"Hor\u00f3scopo de Acuario lunes 16 de enero 2017","link":"https:\/\/candas365.es\/noticias\/horoscopo-de-acuario-lunes-16-de-enero-2017\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/40546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=40546"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/40546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/40524"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=40546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=40546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=40546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}