{"id":37325,"date":"2016-12-01T00:53:26","date_gmt":"2016-12-01T00:53:26","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=37325"},"modified":"2016-12-01T00:53:26","modified_gmt":"2016-12-01T00:53:26","slug":"el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/","title":{"rendered":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-7008\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-360x240.jpg\" alt=\"2015_02_10 RP consejero fondos mineros 1\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-650x433.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-1536x1024.jpg 1536w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-2048x1365.jpg 2048w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-1200x800.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-1920x1280.jpg 1920w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/02\/2015_02_10-RP-consejero-fondos-mineros-1-84x55.jpg 84w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en los curr\u00edculos.<\/p>\n<p>La iniciativa, que se dirige a todos los centros de Educaci\u00f3n Secundaria, permitir\u00e1 reforzar la habilidad de los estudiantes para utilizar el lenguaje, expresar ideas e interactuar. Tambi\u00e9n fomentar\u00e1 el uso de las tecnolog\u00edas en el intercambio de informaci\u00f3n y mejorar\u00e1 la capacidad del alumnado para relacionarse de manera democr\u00e1tica en la vida social.<\/p>\n<p>El programa nace con el objetivo de fomentar la participaci\u00f3n en todo el territorio de forma plural y tambi\u00e9n de acercar a los m\u00e1s j\u00f3venes las funciones y el sentido de la acci\u00f3n parlamentaria. La liga tendr\u00e1 una primera fase local y una segunda regional, con participantes individuales o colectivos. Adem\u00e1s, fomentar\u00e1 la presencia de las comunidades educativas del occidente y el oriente de la comunidad. El Parlamento asumir\u00e1 la financiaci\u00f3n del programa con una aportaci\u00f3n anual de 14.000 euros.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en<\/p>\n","protected":false},"author":1,"featured_media":19522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-37325","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1718\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-12-01T00:53:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-12-01T00:53:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#listItem\",\"name\":\"El Principado y la Junta General pondr\\u00e1n en marcha el programa \\u201cLa liga de debates\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#listItem\",\"position\":3,\"name\":\"El Principado y la Junta General pondr\\u00e1n en marcha el programa \\u201cLa liga de debates\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#newsarticle\",\"name\":\"El Principado y la Junta General pondr\\u00e1n en marcha el programa \\u201cLa liga de debates\\u201d | Cand\\u00e1s 365\",\"headline\":\"El Principado y la Junta General pondr\\u00e1n en marcha el programa \\u201cLa liga de debates\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/2015_11_11-consejo-gobierno-1-scaled.jpg\",\"width\":2560,\"height\":1718},\"datePublished\":\"2016-12-01T00:53:26+01:00\",\"dateModified\":\"2016-12-01T00:53:26+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el diciembre 1, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/\",\"name\":\"El Principado y la Junta General pondr\\u00e1n en marcha el programa \\u201cLa liga de debates\\u201d | Cand\\u00e1s 365\",\"description\":\"El Principado y la Junta General suscribir\\u00e1n un convenio de colaboraci\\u00f3n para poner en marcha el programa La liga de debates, que permitir\\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\\u00f3n ling\\u00fc\\u00edstica, la competencia digital y las competencias sociales y c\\u00edvicas, adem\\u00e1s de potenciar los valores democr\\u00e1ticos en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/2015_11_11-consejo-gobierno-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#mainImage\",\"width\":2560,\"height\":1718},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\\\/#mainImage\"},\"datePublished\":\"2016-12-01T00:53:26+01:00\",\"dateModified\":\"2016-12-01T00:53:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365","description":"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#listItem","name":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#listItem","position":3,"name":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#newsarticle","name":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365","headline":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg","width":2560,"height":1718},"datePublished":"2016-12-01T00:53:26+01:00","dateModified":"2016-12-01T00:53:26+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el diciembre 1, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/","name":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365","description":"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#mainImage","width":2560,"height":1718},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/#mainImage"},"datePublished":"2016-12-01T00:53:26+01:00","dateModified":"2016-12-01T00:53:26+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365","og:description":"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en","og:url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg","og:image:width":2560,"og:image:height":1718,"article:published_time":"2016-12-01T00:53:26+00:00","article:modified_time":"2016-12-01T00:53:26+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d | Cand\u00e1s 365","twitter:description":"El Principado y la Junta General suscribir\u00e1n un convenio de colaboraci\u00f3n para poner en marcha el programa La liga de debates, que permitir\u00e1 al alumnado desarrollar, por medio del debate entre centros educativos, tres competencias clave: la comunicaci\u00f3n ling\u00fc\u00edstica, la competencia digital y las competencias sociales y c\u00edvicas, adem\u00e1s de potenciar los valores democr\u00e1ticos en","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/11\/2015_11_11-consejo-gobierno-1-scaled.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"37325","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 17:57:56","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:09:05","updated":"2026-05-16 17:57:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Principado y la Junta General pondr\u00e1n en marcha el programa \u201cLa liga de debates\u201d","link":"https:\/\/candas365.es\/noticias\/el-principado-y-la-junta-general-pondran-en-marcha-el-programa-la-liga-de-debates\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/37325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=37325"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/37325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/19522"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=37325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=37325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=37325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}