{"id":36962,"date":"2016-11-25T21:49:05","date_gmt":"2016-11-25T21:49:05","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=36962"},"modified":"2016-11-25T21:49:05","modified_gmt":"2016-11-25T21:49:05","slug":"el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/","title":{"rendered":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-36963\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-360x240.jpg\" alt=\"visita\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-650x433.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-1200x800.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg 1280w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por parte de la entidad financiera de 60.228 euros, de los que 30.228 se destinaron al espacio protegido de las Ubi\u00f1as-La Mesa y 30.000 al de Ponga.<\/p>\n<p>Los trabajos han sido ejecutados por la empresa Tragsa, que contrat\u00f3 para este fin a diez personas en riesgo de exclusi\u00f3n social.<\/p>\n<p>La consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez; el director de Instituciones de CaixaBank en Asturias, Iv\u00e1n Ardura, y el director general de Recursos Naturales, Manuel Calvo, han visitado esta ma\u00f1ana algunas de las obras realizadas en el Parque Natural Las Ubi\u00f1as-La Mesa y zonas aleda\u00f1as, concretamente en las localidades de Santa Marina, en el concejo de Lena, y Villanueva, en Santo Adriano.<\/p>\n<p>En Las Ubi\u00f1as-La Mesa se estableci\u00f3 un \u00e1rea cortafuegos que impide el avance del fuego en caso de incendio forestal, adem\u00e1s de evitar su propagaci\u00f3n a los n\u00facleos rurales. Las labores consistieron en la limpieza de la vegetaci\u00f3n arbustiva y de matorral y la poda de vegetaci\u00f3n arb\u00f3rea en una franja perimetral de 20 metros en los alrededores de los pueblos, principalmente de las siguientes especies: casta\u00f1o (Castanea sativa), rebollo (Quercus pyrenaica), avellano (Corylus avellana) y tojo (Ulex sp.). Asimismo, en Villanueva de Santo Adriano se realiz\u00f3 una faja auxiliar para preservar del fuego una de las mejores representaciones de encinares orocant\u00e1bricos del Principado. Un equipo de cinco trabajadores, supervisados por Tragsa, se encarg\u00f3 de estas labores.<\/p>\n<p>En el Parque Natural de Ponga se limpi\u00f3 la vegetaci\u00f3n arbustiva y de matorral y se pod\u00f3 la vegetaci\u00f3n arb\u00f3rea en una franja perimetral de 20 metros alrededor de los n\u00facleos de poblaci\u00f3n del concejo, compuesta tambi\u00e9n por casta\u00f1o, avellano y tojo, principalmente. La actuaci\u00f3n la ejecutaron cinco trabajadores bajo la supervisi\u00f3n t\u00e9cnica de un capataz. Adem\u00e1s, se llevaron a cabo labores de reparaci\u00f3n de infraestructuras de uso p\u00fablico para dotar de mejor accesibilidad al espacio protegido.<\/p>\n<p>La Consejer\u00eda de Desarrollo Rural y Recursos Naturales pretende con estas iniciativas evitar que se repitan los incendios registrados el pasado mes de diciembre, poco habituales en estas \u00e1reas protegidas, salvaguardando as\u00ed tanto las zonas naturales como las \u00e1reas habitadas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por<\/p>\n","protected":false},"author":1,"featured_media":36963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-36962","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-11-25T21:49:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-25T21:49:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#listItem\",\"name\":\"El Principado y la Obra Social \\u2018la Caixa\\u2019 presentan las labores de prevenci\\u00f3n de incendios realizadas en Las Ubi\\u00f1as-La Mesa y Ponga\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#listItem\",\"position\":3,\"name\":\"El Principado y la Obra Social \\u2018la Caixa\\u2019 presentan las labores de prevenci\\u00f3n de incendios realizadas en Las Ubi\\u00f1as-La Mesa y Ponga\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#newsarticle\",\"name\":\"El Principado y la Obra Social \\u2018la Caixa\\u2019 presentan las labores de prevenci\\u00f3n de incendios realizadas en Las Ubi\\u00f1as-La Mesa y Ponga | Cand\\u00e1s 365\",\"headline\":\"El Principado y la Obra Social \\u2018la Caixa\\u2019 presentan las labores de prevenci\\u00f3n de incendios realizadas en Las Ubi\\u00f1as-La Mesa y Ponga\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Visita.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2016-11-25T21:49:05+01:00\",\"dateModified\":\"2016-11-25T21:49:05+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el noviembre 25, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/\",\"name\":\"El Principado y la Obra Social \\u2018la Caixa\\u2019 presentan las labores de prevenci\\u00f3n de incendios realizadas en Las Ubi\\u00f1as-La Mesa y Ponga | Cand\\u00e1s 365\",\"description\":\"La Consejer\\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\\u00f3n de incendios realizadas este a\\u00f1o en los parques naturales de Las Ubi\\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\\u00f3n entre la Obra Social \\u2018la Caixa\\u2019 y el Gobierno de Asturias, han supuesto una inversi\\u00f3n por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Visita.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\\\/#mainImage\"},\"datePublished\":\"2016-11-25T21:49:05+01:00\",\"dateModified\":\"2016-11-25T21:49:05+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365","description":"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#listItem","name":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#listItem","position":3,"name":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#newsarticle","name":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365","headline":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg","width":1280,"height":853},"datePublished":"2016-11-25T21:49:05+01:00","dateModified":"2016-11-25T21:49:05+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el noviembre 25, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/","name":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365","description":"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/#mainImage"},"datePublished":"2016-11-25T21:49:05+01:00","dateModified":"2016-11-25T21:49:05+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365","og:description":"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por","og:url":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2016-11-25T21:49:05+00:00","article:modified_time":"2016-11-25T21:49:05+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga | Cand\u00e1s 365","twitter:description":"La Consejer\u00eda de Desarrollo Rural y Recursos Naturales ha concluido las actuaciones de prevenci\u00f3n de incendios realizadas este a\u00f1o en los parques naturales de Las Ubi\u00f1as-La Mesa y Ponga. Estas iniciativas, que se enmarcan en el convenio de colaboraci\u00f3n entre la Obra Social \u2018la Caixa\u2019 y el Gobierno de Asturias, han supuesto una inversi\u00f3n por","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/Visita.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"36962","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 16:55:37","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:09:22","updated":"2026-05-16 16:55:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Principado y la Obra Social \u2018la Caixa\u2019 presentan las labores de prevenci\u00f3n de incendios realizadas en Las Ubi\u00f1as-La Mesa y Ponga","link":"https:\/\/candas365.es\/noticias\/el-principado-y-la-obra-social-la-caixa-presentan-las-labores-de-prevencion-de-incendios-realizadas-en-las-ubinas-la-mesa-y-ponga\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/36962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=36962"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/36962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/36963"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=36962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=36962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=36962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}