{"id":36466,"date":"2016-11-20T18:15:23","date_gmt":"2016-11-20T18:15:23","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=36466"},"modified":"2016-11-20T18:15:23","modified_gmt":"2016-11-20T18:15:23","slug":"el-principado-mejorara-el-abastecimiento-de-agua-en-norena","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/","title":{"rendered":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-36467\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360-360x198.jpg\" alt=\"visita-norena-655x360\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo de ejecuci\u00f3n de tres meses, permitir\u00e1n evitar desprendimientos y mejorar, por tanto, la seguridad de los usuarios de la v\u00eda.<\/p>\n<p>La responsable de Infraestructuras, que ha visitado el concejo acompa\u00f1ada por los directores generales de Infraestructuras y Transportes, Jos\u00e9 Mar\u00eda Pertierra, y de Calidad Ambiental, Manuel Guti\u00e9rrez, ha anunciado tambi\u00e9n que, en cumplimiento de los compromisos contra\u00eddos con la alcaldesa, Amparo Antu\u00f1a, el lunes, d\u00eda 21, se firmar\u00e1 el contrato que permitir\u00e1 que m\u00e1s de 5.300 vecinos experimenten mejoras sustanciales en el servicio de abastecimiento de agua.<\/p>\n<p>Con respecto al primer proyecto, ha precisado que los trabajos incluyen la limpieza de los taludes, eliminando los sistemas actuales y cualquier elemento de sujeci\u00f3n existente, as\u00ed como el reperfilado de los mismos, para a continuaci\u00f3n proceder a la instalaci\u00f3n del sistema de estabilizaci\u00f3n propiamente dicho. Las obras se completar\u00e1n con la limpieza de la zona y la reposici\u00f3n de cualquier elemento o servicio afectado.<\/p>\n<p>Por su parte, la obra de abastecimiento consiste en la reposici\u00f3n de cuatro tramos de tuber\u00edas de m\u00e1s de un kil\u00f3metro de longitud de la red principal en mal estado, dentro del casco urbano, y la colocaci\u00f3n de un grupo de presi\u00f3n a la salida del dep\u00f3sito de agua, en Ecce Homo. La actuaci\u00f3n, que finalizar\u00e1 antes de la pr\u00f3xima primavera, ha sido adjudicada en 146.977,22 euros a la empresa ASTURAGUA SAU.<\/p>\n<p>Los trabajos en el viario p\u00fablico y en el dep\u00f3sito municipal se coordinar\u00e1n con el Ayuntamiento de Nore\u00f1a al objeto de generar los menores trastornos posibles a sus habitantes.<\/p>\n<p>Esta obra completa la finalizada por la consejer\u00eda en diciembre de 2014, que con un importe de m\u00e1s de 132.000 euros se realiz\u00f3 en la conducci\u00f3n general de abastecimiento a Nore\u00f1a, desde las captaciones de La Santa y El Vino.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo<\/p>\n","protected":false},"author":1,"featured_media":36467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-36466","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-11-20T18:15:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-20T18:15:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#listItem\",\"name\":\"El Principado mejorar\\u00e1 el abastecimiento de agua en Nore\\u00f1a\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#listItem\",\"position\":3,\"name\":\"El Principado mejorar\\u00e1 el abastecimiento de agua en Nore\\u00f1a\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#newsarticle\",\"name\":\"El Principado mejorar\\u00e1 el abastecimiento de agua en Nore\\u00f1a | Cand\\u00e1s 365\",\"headline\":\"El Principado mejorar\\u00e1 el abastecimiento de agua en Nore\\u00f1a\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/visita-Nore\\u00f1a-655x360.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-11-20T18:15:23+01:00\",\"dateModified\":\"2016-11-20T18:15:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el noviembre 20, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/\",\"name\":\"El Principado mejorar\\u00e1 el abastecimiento de agua en Nore\\u00f1a | Cand\\u00e1s 365\",\"description\":\"La consejera de Infraestructuras, Ordenaci\\u00f3n del Territorio y Medio Ambiente, Bel\\u00e9n Fern\\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\\u00f3n-Langreo, a la altura de los puntos kilom\\u00e9tricos 18+200 y 18+780 en sentido Gij\\u00f3n, en el municipio de Nore\\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/visita-Nore\\u00f1a-655x360.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\\\/#mainImage\"},\"datePublished\":\"2016-11-20T18:15:23+01:00\",\"dateModified\":\"2016-11-20T18:15:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365","description":"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo","canonical_url":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#listItem","name":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#listItem","position":3,"name":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#newsarticle","name":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365","headline":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg","width":655,"height":360},"datePublished":"2016-11-20T18:15:23+01:00","dateModified":"2016-11-20T18:15:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el noviembre 20, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/","name":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365","description":"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg","@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/#mainImage"},"datePublished":"2016-11-20T18:15:23+01:00","dateModified":"2016-11-20T18:15:23+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365","og:description":"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo","og:url":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-11-20T18:15:23+00:00","article:modified_time":"2016-11-20T18:15:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a | Cand\u00e1s 365","twitter:description":"La consejera de Infraestructuras, Ordenaci\u00f3n del Territorio y Medio Ambiente, Bel\u00e9n Fern\u00e1ndez, ha presentado el proyecto para estabilizar dos taludes de desmonte en la carretera AS-246, Gij\u00f3n-Langreo, a la altura de los puntos kilom\u00e9tricos 18+200 y 18+780 en sentido Gij\u00f3n, en el municipio de Nore\u00f1a. Los trabajos, presupuestados en 210.210 euros y con un plazo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/visita-Nore\u00f1a-655x360.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"36466","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 15:26:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:09:48","updated":"2026-05-16 15:26:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Principado mejorar\u00e1 el abastecimiento de agua en Nore\u00f1a","link":"https:\/\/candas365.es\/noticias\/el-principado-mejorara-el-abastecimiento-de-agua-en-norena\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/36466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=36466"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/36466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/36467"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=36466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=36466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=36466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}