{"id":35557,"date":"2016-11-05T21:05:44","date_gmt":"2016-11-05T21:05:44","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=35557"},"modified":"2016-11-05T21:06:09","modified_gmt":"2016-11-05T21:06:09","slug":"el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/","title":{"rendered":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio"},"content":{"rendered":"<p class=\"x_MsoNormal\"><span style=\"font-family: Arial;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-35558\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-360x207.jpg\" alt=\"apertura-centro-de-dia\" width=\"360\" height=\"207\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-360x207.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-650x373.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-768x441.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-150x86.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-450x258.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-655x376.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-696x400.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-1068x613.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-732x420.jpg 732w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA-172x100.jpg 172w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg 1094w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del que tambi\u00e9n pueden beneficiarse los mayores del concejo, a trav\u00e9s de los servicios sociales municipales.\u00a0<\/span><span style=\"font-family: Arial;\">\u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span style=\"font-family: Arial;\">La consejera de Servicios y Derechos Sociales, Pilar Varela, acompa\u00f1ada por la alcaldesa de Muros de Nal\u00f3n, Carmen Arango, y personal t\u00e9cnico del Equipo Territorial de Servicios Sociales del \u00c1rea III, han visitado hoy estas instalaciones, que se vienen utilizando desde el verano para desarrollar actividades que favorecen el envejecimiento activo de los mayores de la zona. Varela ha celebrado la entrada en servicio del equipamiento municipal, cuya rehabilitaci\u00f3n financi\u00f3 el Gobierno de Asturias en 2010, y que no se hab\u00edan puesto en funcionamiento hasta ahora por falta de demanda.\u00a0<\/span><span style=\"font-family: Arial;\">\u00a0<\/span><\/p>\n<p class=\"x_MsoNormal\"><span style=\"font-family: Arial;\">La titular de Servicios Sociales ha se\u00f1alado que el Principado, a trav\u00e9s del Plan Concertado, aporta a la Mancomunidad de las Cinco Villas, integrada por los municipios de Muros de Nal\u00f3n, Pravia y Soto del Barco, \u00a0un total de 620.673 euros, con los que se sufragan, entre otros, estos servicios de atenci\u00f3n a mayores. Tambi\u00e9n financia con 36.400 euros la concesi\u00f3n de ayudas a familias con menores a cargo.<\/span><span style=\"font-family: Arial;\">\u00a0<\/span><\/p>\n<p>Tras la puesta en servicio del centro de Muros de Nal\u00f3n, Asturias cuenta con 16 CRAD o centros gerontol\u00f3gicos de car\u00e1cter preventivo y asistencial, en los que se presta atenci\u00f3n diurna a personas mayores que viven en zonas rurales para promover su autonom\u00eda personal y facilitar a la vez un respiro a las familias, con el objetivo de lograr que permanezcan en su entorno. Este recurso, de gesti\u00f3n municipal, se financia con cargo al Plan Concertado de Servicios Sociales.<\/p>\n<p>El Principado dedic\u00f3 en 2015 en torno a un mill\u00f3n de euros para la gesti\u00f3n de estos centros, en los que se atendi\u00f3 a 258 personas. Por \u00e1reas, se distribuyen de la siguiente forma:<\/p>\n<p class=\"x_Tabulaciones1\">&#8211;<span style=\"font: 7pt\/normal 'Times New Roman'; font-size-adjust: none; font-stretch: normal;\">\u00a0\u00a0 <\/span><span style=\"font-family: Arial;\">\u00c1rea I: Tapia de Casariego, El Franco, Castropol, Villay\u00f3n y Taramundi.<\/span><\/p>\n<p class=\"x_Tabulaciones1\">&#8211;<span style=\"font: 7pt\/normal 'Times New Roman'; font-size-adjust: none; font-stretch: normal;\">\u00a0\u00a0 <\/span><span style=\"font-family: Arial;\">\u00c1rea II: Allande.<\/span><\/p>\n<p class=\"x_Tabulaciones1\">&#8211;<span style=\"font: 7pt\/normal 'Times New Roman'; font-size-adjust: none; font-stretch: normal;\">\u00a0\u00a0 <\/span><span style=\"font-family: Arial;\">\u00c1rea III: Illas.<\/span><\/p>\n<p class=\"x_Tabulaciones1\">&#8211;<span style=\"font: 7pt\/normal 'Times New Roman'; font-size-adjust: none; font-stretch: normal;\">\u00a0\u00a0 <\/span><span style=\"font-family: Arial;\">\u00c1rea IV: Las Regueras, Bimenes, Morc\u00edn y Cabranes.<\/span><\/p>\n<p class=\"x_Tabulaciones1\">&#8211;<span style=\"font: 7pt\/normal 'Times New Roman'; font-size-adjust: none; font-stretch: normal;\">\u00a0\u00a0 <\/span><span style=\"font-family: Arial;\">\u00c1rea VI: Colunga, Caravia, Ribadesella y Benia.<\/span><\/p>\n<p class=\"x_Tabulaciones1\">\n","protected":false},"excerpt":{"rendered":"<p>El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del<\/p>\n","protected":false},"author":1,"featured_media":35558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-35557","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1094\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-11-05T21:05:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-11-05T21:06:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#listItem\",\"name\":\"El Centro Rural de Apoyo Diurno de Muros de Nal\\u00f3n entra en servicio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#listItem\",\"position\":3,\"name\":\"El Centro Rural de Apoyo Diurno de Muros de Nal\\u00f3n entra en servicio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#newsarticle\",\"name\":\"El Centro Rural de Apoyo Diurno de Muros de Nal\\u00f3n entra en servicio | Cand\\u00e1s 365\",\"headline\":\"El Centro Rural de Apoyo Diurno de Muros de Nal\\u00f3n entra en servicio\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/APERTURA-CENTRO-DE-DIA.jpg\",\"width\":1094,\"height\":628},\"datePublished\":\"2016-11-05T21:05:44+01:00\",\"dateModified\":\"2016-11-05T21:06:09+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el noviembre 5, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/\",\"name\":\"El Centro Rural de Apoyo Diurno de Muros de Nal\\u00f3n entra en servicio | Cand\\u00e1s 365\",\"description\":\"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\\u00e1n con atenci\\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\\u00e1s, se ha puesto en marcha un servicio de comidas del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/APERTURA-CENTRO-DE-DIA.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#mainImage\",\"width\":1094,\"height\":628},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\\\/#mainImage\"},\"datePublished\":\"2016-11-05T21:05:44+01:00\",\"dateModified\":\"2016-11-05T21:06:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365","description":"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del","canonical_url":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#listItem","name":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#listItem","position":3,"name":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#newsarticle","name":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365","headline":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg","width":1094,"height":628},"datePublished":"2016-11-05T21:05:44+01:00","dateModified":"2016-11-05T21:06:09+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el noviembre 5, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/","name":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365","description":"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg","@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#mainImage","width":1094,"height":628},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/#mainImage"},"datePublished":"2016-11-05T21:05:44+01:00","dateModified":"2016-11-05T21:06:09+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365","og:description":"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del","og:url":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg","og:image:width":1094,"og:image:height":628,"article:published_time":"2016-11-05T21:05:44+00:00","article:modified_time":"2016-11-05T21:06:09+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio | Cand\u00e1s 365","twitter:description":"El Centro Rural de Apoyo Diurno (CRAD) de San Esteban de Pravia, en Muros de Nal\u00f3n, ha entrado en funcionamiento con los primeros cuatro usuarios, que contar\u00e1n con atenci\u00f3n diaria, de lunes a viernes, en horario flexible, desde las 09:00 hasta las 17:00 horas. Adem\u00e1s, se ha puesto en marcha un servicio de comidas del","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/11\/APERTURA-CENTRO-DE-DIA.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"35557","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 12:47:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:10:35","updated":"2026-05-16 12:47:22"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Centro Rural de Apoyo Diurno de Muros de Nal\u00f3n entra en servicio","link":"https:\/\/candas365.es\/noticias\/el-centro-rural-de-apoyo-diurno-de-muros-de-nalon-entra-en-servicio\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/35557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=35557"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/35557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/35558"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=35557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=35557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=35557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}