{"id":31968,"date":"2016-07-13T22:27:47","date_gmt":"2016-07-13T20:57:47","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=31968"},"modified":"2016-07-13T22:27:47","modified_gmt":"2016-07-13T20:57:47","slug":"el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/","title":{"rendered":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-31969\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-360x240.jpg\" alt=\"2016_07_12 consejera area recreativa Sobrescobio\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-650x434.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-1536x1025.jpg 1536w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-450x300.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-1200x800.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-1068x712.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg 1880w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone de una superficie de 37.736 hect\u00e1reas distribuidas entre los concejos de Caso (81,6%) y Sobrescobio (18,4%), donde viven 2.518 personas (1.663 en el primer concejo y 855 en el segundo).<\/p>\n<p>La consejer\u00eda ha ejecutado durante este periodo cerca de 8,5 millones. El resto ha sido sufragado por otros departamentos de la Administraci\u00f3n auton\u00f3mica. La inversi\u00f3n directa para Redes por su condici\u00f3n de parque natural ha ascendido a 2,4 millones, el 13,2 por ciento del total. En t\u00e9rminos relativos, la media de inversi\u00f3n por habitante supera los 1.700 euros (117 por hect\u00e1rea).<\/p>\n<p>Los \u00f3rganos de gesti\u00f3n, que se han reunido en Campo de Caso, han aprobado las memorias de 2013, 2014 y 2015, ejercicios en los que el Ejecutivo regional destin\u00f3 al parque 5,5, 4,3 y 2,5 millones, respectivamente. En cuanto a la afluencia de visitantes, 27.926 personas han pasado por el centro de interpretaci\u00f3n para solicitar informaci\u00f3n.<\/p>\n<p>Por otra parte, los responsables de la consejer\u00eda han informado a la junta gestora de que este a\u00f1o se mantiene la partida de 200.000 euros para los proyectos que presenten los ayuntamientos y las parroquias rurales de los parques naturales, y habr\u00e1 otros 38.000 para la mejora de rutas. Los ayuntamientos podr\u00e1n presentar un m\u00e1ximo de dos proyectos por un valor no superior a los 20.000 euros y las parroquias, por un montante de hasta 5.000.<\/p>\n<p>Adem\u00e1s, la junta rectora ha ratificado el nombramiento del nuevo director-conservador del parque, Rub\u00e9n Rodr\u00edguez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone<\/p>\n","protected":false},"author":1,"featured_media":31969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-31968","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1880\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1254\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-07-13T20:57:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-07-13T20:57:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#listItem\",\"name\":\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \\u00faltimos tres a\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#listItem\",\"position\":3,\"name\":\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \\u00faltimos tres a\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#newsarticle\",\"name\":\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \\u00faltimos tres a\\u00f1os | Cand\\u00e1s 365\",\"headline\":\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \\u00faltimos tres a\\u00f1os\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg\",\"width\":1880,\"height\":1254},\"datePublished\":\"2016-07-13T22:27:47+02:00\",\"dateModified\":\"2016-07-13T22:27:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el julio 13, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/\",\"name\":\"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \\u00faltimos tres a\\u00f1os | Cand\\u00e1s 365\",\"description\":\"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \\u00faltimos tres a\\u00f1os, seg\\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\\u00eda Jes\\u00fas \\u00c1lvarez, durante las reuniones de la junta y la comisi\\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#mainImage\",\"width\":1880,\"height\":1254},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\\\/#mainImage\"},\"datePublished\":\"2016-07-13T22:27:47+02:00\",\"dateModified\":\"2016-07-13T22:27:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365","description":"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone","canonical_url":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#listItem","name":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#listItem","position":3,"name":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#newsarticle","name":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365","headline":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg","width":1880,"height":1254},"datePublished":"2016-07-13T22:27:47+02:00","dateModified":"2016-07-13T22:27:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el julio 13, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/","name":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365","description":"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg","@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#mainImage","width":1880,"height":1254},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/#mainImage"},"datePublished":"2016-07-13T22:27:47+02:00","dateModified":"2016-07-13T22:27:47+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365","og:description":"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone","og:url":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg","og:image:width":1880,"og:image:height":1254,"article:published_time":"2016-07-13T20:57:47+00:00","article:modified_time":"2016-07-13T20:57:47+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os | Cand\u00e1s 365","twitter:description":"El Gobierno de Asturias ha destinado 13,4 millones al territorio del Parque Natural de Redes durante los \u00faltimos tres a\u00f1os, seg\u00fan ha informado hoy la consejera de Desarrollo Rural y Recursos Naturales, Mar\u00eda Jes\u00fas \u00c1lvarez, durante las reuniones de la junta y la comisi\u00f3n rectora de este espacio protegido, creado en 1996. El parque dispone","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/07\/2016_07_12-consejera-area-recreativa-Sobrescobio.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"31968","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 02:56:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:02:21","updated":"2026-05-16 02:56:17"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"El Gobierno de Asturias ha destinado 13,4 millones al Parque Natural de Redes en los \u00faltimos tres a\u00f1os","link":"https:\/\/candas365.es\/noticias\/el-gobierno-de-asturias-ha-destinado-134-millones-al-parque-natural-de-redes-en-los-ultimos-tres-anos\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/31968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=31968"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/31968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/31969"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=31968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=31968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=31968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}