{"id":31050,"date":"2016-06-23T00:45:05","date_gmt":"2016-06-22T23:15:05","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=31050"},"modified":"2016-06-23T00:45:05","modified_gmt":"2016-06-22T23:15:05","slug":"llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/","title":{"rendered":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-31051\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-360x239.jpg\" alt=\"fotonoticia_20160622154338_800\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-650x432.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-768x511.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-450x299.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-696x463.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-632x420.jpg 632w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a 10 refugiados desde Turqu\u00eda en el marco del programa de reasentamiento.<\/p>\n<p>En concreto, los 37 solicitantes de asilo llegados este mi\u00e9rcoles desde Grecia son todos sirios excepto un inraqu\u00ed y se trata de 13 hombres, 7 mujeres y 17 ni\u00f1os. Ser\u00e1n acogidos en Guadalajara (2), Barcelona (4), Madrid (7), Vizcaya (6), Valencia (11) y Asturias (7).<\/p>\n<p>Con esta nueva llegada son ya 121 las personas trasladadas desde Grecia, a quien Espa\u00f1a ha ofrecido 150 plazas, y 40 desde Italia, con cuyas autoridades existe el compromiso de acoger a 50 refugiados. En total, la Administraci\u00f3n espa\u00f1ola debe reubicar en su territorio a 9.323 personas desde ambos pa\u00edses antes de septiembre de 2017.<\/p>\n<p>Por otra parte, este martes por la noche han llegado tambi\u00e9n a Madrid 10 refugiados desde Turqu\u00eda. Se trata de las primeras personas que llegan por reasentamiento (traslado desde el pa\u00eds de primera acogida), para el que Espa\u00f1a ha aprobado un cupo de 854 personas de las 1.400 que se ha comprometido con la UE a acoger hasta septiembre del a\u00f1o que viene.<\/p>\n<p>Estas diez personas aterrizaron en el Aeropuerto de Barajas a las 22.55 horas en un vuelo procedente de Estambul. De los 10 demandantes de protecci\u00f3n internacional, cuatro fueron trasladados a Tarragona (un hombre, una mujer y dos menores) y seis a Navarra (cuatro hombres, una mujer y un menor).<\/p>\n<p>La previsi\u00f3n del Gobierno es que entre ambos programas, hayan llegado a Espa\u00f1a al final de este mes 586 personas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a<\/p>\n","protected":false},"author":1,"featured_media":31051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-31050","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-22T23:15:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-22T23:15:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#listItem\",\"name\":\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#listItem\",\"position\":3,\"name\":\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#newsarticle\",\"name\":\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\\u00e1s 365\",\"headline\":\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160622154338_800.jpg\",\"width\":800,\"height\":532},\"datePublished\":\"2016-06-23T00:45:05+02:00\",\"dateModified\":\"2016-06-23T00:45:05+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el junio 23, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/\",\"name\":\"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\\u00e1s 365\",\"description\":\"El Ministerio del Interior ha anunciado este mi\\u00e9rcoles la llegada al Aeropuerto Adolfo Su\\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\\u00f1a por esta v\\u00eda. Ha recibido asimismo a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160622154338_800.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#mainImage\",\"width\":800,\"height\":532},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\\\/#mainImage\"},\"datePublished\":\"2016-06-23T00:45:05+02:00\",\"dateModified\":\"2016-06-23T00:45:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365","description":"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a","canonical_url":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#listItem","name":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#listItem","position":3,"name":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#newsarticle","name":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365","headline":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg","width":800,"height":532},"datePublished":"2016-06-23T00:45:05+02:00","dateModified":"2016-06-23T00:45:05+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el junio 23, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#webpage","url":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/","name":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365","description":"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg","@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#mainImage","width":800,"height":532},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/#mainImage"},"datePublished":"2016-06-23T00:45:05+02:00","dateModified":"2016-06-23T00:45:05+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365","og:description":"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a","og:url":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg","og:image:width":800,"og:image:height":532,"article:published_time":"2016-06-22T23:15:05+00:00","article:modified_time":"2016-06-22T23:15:05+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia | Cand\u00e1s 365","twitter:description":"El Ministerio del Interior ha anunciado este mi\u00e9rcoles la llegada al Aeropuerto Adolfo Su\u00e1rez Madrid Barajas de 37 refugiados reubicados desde Grecia por el mecanismo europeo de reparto de solicitantes de asilo que ya se encuentran en territorio comunitario y suman ya 171 las personas acogidas por Espa\u00f1a por esta v\u00eda. Ha recibido asimismo a","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160622154338_800.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"31050","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-16 00:12:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 13:00:00","updated":"2026-05-16 00:12:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLlegan a Asturias siete nuevos refugiados reasentados desde Grecia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Llegan a Asturias siete nuevos refugiados reasentados desde Grecia","link":"https:\/\/candas365.es\/noticias\/llegan-a-asturias-siete-nuevos-refugiados-reasentados-desde-grecia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/31050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=31050"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/31050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/31051"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=31050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=31050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=31050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}