{"id":30127,"date":"2016-06-13T02:12:30","date_gmt":"2016-06-13T00:42:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=30127"},"modified":"2016-06-13T02:12:30","modified_gmt":"2016-06-13T00:42:30","slug":"la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/","title":{"rendered":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-30128\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-360x270.jpg\" alt=\"fotonoticia_20160612173627_800\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-150x113.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-450x338.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800-90x67.jpg 90w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las cinco formaciones finalistas del certamen. La banda que ha obtenido el primer puesto representar\u00e1 a Asturias en el certamen interuniversitario del Grupo G9 de universidades, que se celebrar\u00e1 en septiembre en Cantabria.<\/p>\n<p>La Kashmir es un grupo de rock formado en Gij\u00f3n en 2008, con influencias anglosajonas de grupos como Van Halen, y espa\u00f1olas, como H\u00e9roes del Silencio. Dos de sus l\u00edderes: Alejandro Parada, voz y guitarra, es estudiante de doctorado; y Germ\u00e1n G\u00f3mez, guitarra solista, cursa un m\u00e1ster universitario de ingenier\u00eda en la Universidad de Oviedo. Omar Rendueles (Bater\u00eda), Alex Pa\u00f1os (bajista) y Nicol\u00e1s Fern\u00e1ndez (guitarra) son los otros dos componentes de la banda. En 2013, el grupo grab\u00f3 un primer EP titulado El rinc\u00f3n de mis dudas, y tras una parada, han vuelto a reunirse este mismo a\u00f1o, iniciando una gira por locales de Asturias.<\/p>\n<p>El segundo clasificado ha sido Supermarket, una banda de punk rock y hardcore, con tres de sus miembros*estudiantes de la Universidad de Oviedo. El primer premio est\u00e1 dotado con 1.000 euros y el segundo, con 500 euros.<\/p>\n<p>El jurado estuvo presidido por Francisco Jos\u00e9 Borge L\u00f3pez, vicerrector de Extensi\u00f3n Universitaria y Proyecci\u00f3n Internacional, y formado tambi\u00e9n por m\u00fasicos, profesores y especialistas del panorama musical asturiano: Mar\u00eda del Mar Fern\u00e1ndez, Sara Mu\u00f1iz, Xabel Vegas, Roberto Nicieza, Eduardo Garc\u00eda Salue\u00f1a y Eduardo Vi\u00f1uela. A la final de esta tercera edici\u00f3n del Certamen Musical de la Universidad de Oviedo tambi\u00e9n llegaron las bandas Nairobi, Ruta on the road, y The hidden road.<\/p>\n<p>Para la selecci\u00f3n de los grupos ganadores, el tribunal valor\u00f3 especialmente la calidad del sonido de los instrumentos y la interpretaci\u00f3n dentro de cada estilo musical, la puesta en escena y la aptitud art\u00edstica de los solistas o grupos, y la creatividad art\u00edstica de las bandas, que actuaron ante cerca de 300 personas que acudieron a la final del certamen en el Teatro de la Laboral. Durante las deliberaciones del jurado, se proyecto la grabaci\u00f3n del concierto homenaje a \u00c1ngel Gonz\u00e1lez, Entre el amor y la sombra, de Pablo Moro y Alfredo Gonz\u00e1lez.<\/p>\n<p>La Kashmir representar\u00e1 a la Universidad de Oviedo en el IV Certamen Musical Interuniversitario del Grupo G-9 de Universidades, organizado por la Universidad de Cantabria, que se celebrar\u00e1 septiembre en Santander. El*Grupo 9 de Universidades*es una red universitaria integrada por las universidades de*Oviedo, Cantabria, Pa\u00eds Vasco, La Rioja, P\u00fablica de Navarra, Zaragoza, Islas Baleares, Castilla-La Mancha y Extremadura.<\/p>\n<p>El certamen, impulsado desde el vicerrectorado de Extensi\u00f3n Universitaria y Proyecci\u00f3n Internacional, trata de promover la creaci\u00f3n musical en la Universidad de Oviedo, impulsando y promocionando la actividad de grupos y solistas con miembros vinculados a la instituci\u00f3n (estudiantes, profesorado y personal de administraci\u00f3n y servicios). Los maliayos Alienda Folk fueron los ganadores de la primera edici\u00f3n del certamen, mientras que en la segunda convocatoria, en 2015, resultaron vencedores los componentes de la banda gijonesa Blue Dog Avenue (BDA).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las<\/p>\n","protected":false},"author":1,"featured_media":30128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-30127","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-13T00:42:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-13T00:42:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#listItem\",\"name\":\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#listItem\",\"position\":3,\"name\":\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#newsarticle\",\"name\":\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\\u00e1s 365\",\"headline\":\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160612173627_800.jpg\",\"width\":800,\"height\":600},\"datePublished\":\"2016-06-13T02:12:30+02:00\",\"dateModified\":\"2016-06-13T02:12:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 13, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/\",\"name\":\"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\\u00e1s 365\",\"description\":\"El grupo gijon\\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \\u00e1mbito musical asturiano, decidi\\u00f3 entre las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160612173627_800.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#mainImage\",\"width\":800,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\\\/#mainImage\"},\"datePublished\":\"2016-06-13T02:12:30+02:00\",\"dateModified\":\"2016-06-13T02:12:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365","description":"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las","canonical_url":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#listItem","name":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#listItem","position":3,"name":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#newsarticle","name":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365","headline":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg","width":800,"height":600},"datePublished":"2016-06-13T02:12:30+02:00","dateModified":"2016-06-13T02:12:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 13, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/","name":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365","description":"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg","@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#mainImage","width":800,"height":600},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/#mainImage"},"datePublished":"2016-06-13T02:12:30+02:00","dateModified":"2016-06-13T02:12:30+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365","og:description":"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las","og:url":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg","og:image:width":800,"og:image:height":600,"article:published_time":"2016-06-13T00:42:30+00:00","article:modified_time":"2016-06-13T00:42:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo | Cand\u00e1s 365","twitter:description":"El grupo gijon\u00e9s La Kashmir ha sido el ganador del III Certamen Musical de la Universidad de Oviedo en la fase final celebrada anoche en el Teatro de Laboral Ciudad de la Cultura, en la que el segundo puesto fue para Supermarket. Un jurado, compuesto por destacados representantes del \u00e1mbito musical asturiano, decidi\u00f3 entre las","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160612173627_800.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"30127","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:48:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:57:01","updated":"2026-05-15 21:48:22","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa Kashmir gana el III Certamen Musical de la Universidad de Oviedo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La Kashmir gana el III Certamen Musical de la Universidad de Oviedo","link":"https:\/\/candas365.es\/noticias\/la-kashmir-gana-el-iii-certamen-musical-de-la-universidad-de-oviedo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/30127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=30127"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/30127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/30128"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=30127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=30127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=30127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}