{"id":29934,"date":"2016-06-10T10:14:08","date_gmt":"2016-06-10T08:44:08","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29934"},"modified":"2016-06-10T10:14:08","modified_gmt":"2016-06-10T08:44:08","slug":"las-exportaciones-alemanas-se-estancan-en-abril","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/","title":{"rendered":"Las exportaciones alemanas se estancan en abril"},"content":{"rendered":"<p>Wiesbaden (Alemania), 9 jun (dpa) &#8211; Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o.<\/p>\n<p>Las ventas de productos germanos al exterior, uno de los pilares de la mayor econom\u00eda de Europa, se mantuvieron invariables en abril respecto de marzo, cuando registraron un s\u00f3lido incremento de 1,9 por ciento tras un aumento de 1,4 por ciento en febrero, se\u00f1alan las cifras divulgadas hoy por la Oficina Federal de Estad\u00edsticas (Destatis).<\/p>\n<p>A\u00fan as\u00ed, los n\u00fameros de abril fueron mejores que los esperados por los analistas bancarios, que hab\u00edan pronosticado una ca\u00edda de 0,8 por ciento. <\/p>\n<p>Las importaciones cedieron un 0,2 por ciento y encandenaron la segunda ca\u00edda consecutiva tras una contracci\u00f3n de 2,3 por ciento en marzo. Los analistas esperaban en abril un avance de 1,3 por ciento.<\/p>\n<p>Respecto a abril de 2015, las exportaciones aumentaron un 3,8 por ciento, mientras que las importaciones se mantuvieron casi invariables.<\/p>\n<p>El comercio exterior con pa\u00edses de fuera de la Uni\u00f3n Europea se debilit\u00f3 al tiempo que mejoraron los negocios con socios de la Uni\u00f3n Europea y de la zona euro.<\/p>\n<p>Muchos economistas pronostican que la econom\u00eda alemana perder\u00e1 ritmo en los pr\u00f3ximos meses despu\u00e9s de expandirse en el primer trimestre del a\u00f1o en un 0,7 por ciento comparado con el \u00faltimo trimestre de 2015, cuando creci\u00f3 un 0,3 por ciento.<\/p>\n<p>\u00abMientras que seguimos siendo optimistas respecto al mercado laboral, creemos que el impulso proveniente de los precios bajos del petr\u00f3leo en los ingresos reales est\u00e1 perdiendo intensidad\u00bb, se\u00f1al\u00f3 el Deutsche Bank en un informe mensual remitido a sus clientes. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wiesbaden (Alemania), 9 jun (dpa) &#8211; Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas<\/p>\n","protected":false},"author":1,"featured_media":16457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29934","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-10T08:44:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-10T08:44:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#listItem\",\"name\":\"Las exportaciones alemanas se estancan en abril\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#listItem\",\"position\":3,\"name\":\"Las exportaciones alemanas se estancan en abril\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#newsarticle\",\"name\":\"Las exportaciones alemanas se estancan en abril | Cand\\u00e1s 365\",\"headline\":\"Las exportaciones alemanas se estancan en abril\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/c365noticias.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-06-10T10:14:08+02:00\",\"dateModified\":\"2016-06-10T10:14:08+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 10, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/\",\"name\":\"Las exportaciones alemanas se estancan en abril | Cand\\u00e1s 365\",\"description\":\"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\\u00edda de la demanda de China y de las principales econom\\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\\u00eda de Europa al comienzo del segundo trimestre del a\\u00f1o. Las ventas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/c365noticias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/las-exportaciones-alemanas-se-estancan-en-abril\\\/#mainImage\"},\"datePublished\":\"2016-06-10T10:14:08+02:00\",\"dateModified\":\"2016-06-10T10:14:08+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365","description":"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas","canonical_url":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#listItem","name":"Las exportaciones alemanas se estancan en abril"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#listItem","position":3,"name":"Las exportaciones alemanas se estancan en abril","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#newsarticle","name":"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365","headline":"Las exportaciones alemanas se estancan en abril","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","width":655,"height":360},"datePublished":"2016-06-10T10:14:08+02:00","dateModified":"2016-06-10T10:14:08+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 10, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#webpage","url":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/","name":"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365","description":"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/#mainImage"},"datePublished":"2016-06-10T10:14:08+02:00","dateModified":"2016-06-10T10:14:08+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365","og:description":"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas","og:url":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-06-10T08:44:08+00:00","article:modified_time":"2016-06-10T08:44:08+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Las exportaciones alemanas se estancan en abril | Cand\u00e1s 365","twitter:description":"Wiesbaden (Alemania), 9 jun (dpa) - Las exportaciones alemanas se estancaron en abril ante la ca\u00edda de la demanda de China y de las principales econom\u00edas emergentes, al tiempo que se contrajeron las importaciones para completar un panorama menos alentador sobre la mayor econom\u00eda de Europa al comienzo del segundo trimestre del a\u00f1o. Las ventas","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"29934","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:35:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:30","updated":"2026-05-15 21:35:22","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLas exportaciones alemanas se estancan en abril\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Las exportaciones alemanas se estancan en abril","link":"https:\/\/candas365.es\/noticias\/las-exportaciones-alemanas-se-estancan-en-abril\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29934"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/16457"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}