{"id":29910,"date":"2016-06-10T10:01:36","date_gmt":"2016-06-10T08:31:36","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29910"},"modified":"2016-06-10T10:01:36","modified_gmt":"2016-06-10T08:31:36","slug":"luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/","title":{"rendered":"Luz verde para llamada a talleres de 1,1 millones de autos de VW"},"content":{"rendered":"<p> (dpa) &#8211; Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. <\/p>\n<p>Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo de manipulaci\u00f3n de las emisiones de los motores di\u00e9sel recibe un nuevo impulso. <\/p>\n<p>Desde comienzos del a\u00f1o se ha recibido luz verde para la llamada a talleres de m\u00e1s de 2,5 millones de veh\u00edculos afectados, inform\u00f3 la empresa en un comunicado de prensa. <\/p>\n<p>La mayor automotriz de Europa recibi\u00f3 la confirmaci\u00f3n oficial de la Oficina Federal de Veh\u00edculos Motorizados (KBA, por sus siglas en alem\u00e1n) para llevar a cabo sus mejoras en los coches de VW, veh\u00edculos de servicio de VW y Audi. <\/p>\n<p>En concreto, la llamada a talleres afecta a los modelos de VW Golf, Passat y Tiguan y al A4, A5, A6 y Q5 de Audi. En el caso del Seat Exeo la modificaci\u00f3n se produce seg\u00fan lo previsto por la compa\u00f1\u00eda.<\/p>\n<p>En total en Europa hay 8,5 millones de veh\u00edculos con motores di\u00e9sel afectados por el esc\u00e1ndalo de manipulaci\u00f3n, un tercio de ellos en Alemania. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo<\/p>\n","protected":false},"author":1,"featured_media":16457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29910","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-10T08:31:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-10T08:31:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#listItem\",\"name\":\"Luz verde para llamada a talleres de 1,1 millones de autos de VW\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#listItem\",\"position\":3,\"name\":\"Luz verde para llamada a talleres de 1,1 millones de autos de VW\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#newsarticle\",\"name\":\"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\\u00e1s 365\",\"headline\":\"Luz verde para llamada a talleres de 1,1 millones de autos de VW\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/c365noticias.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-06-10T10:01:36+02:00\",\"dateModified\":\"2016-06-10T10:01:36+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 10, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/\",\"name\":\"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\\u00e1s 365\",\"description\":\"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\\u00e1s de 1,1 millones de coches del gigante automotor alem\\u00e1n Volkswagen dotados con motores di\\u00e9sel que simulaban menores emisiones contaminantes, comunic\\u00f3 hoy la compa\\u00f1\\u00eda. Tras meses de retrasos, la revisi\\u00f3n de los autom\\u00f3viles de VW afectados por el esc\\u00e1ndalo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/c365noticias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\\\/#mainImage\"},\"datePublished\":\"2016-06-10T10:01:36+02:00\",\"dateModified\":\"2016-06-10T10:01:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365","description":"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo","canonical_url":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#listItem","name":"Luz verde para llamada a talleres de 1,1 millones de autos de VW"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#listItem","position":3,"name":"Luz verde para llamada a talleres de 1,1 millones de autos de VW","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#newsarticle","name":"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365","headline":"Luz verde para llamada a talleres de 1,1 millones de autos de VW","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","width":655,"height":360},"datePublished":"2016-06-10T10:01:36+02:00","dateModified":"2016-06-10T10:01:36+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 10, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#webpage","url":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/","name":"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365","description":"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/#mainImage"},"datePublished":"2016-06-10T10:01:36+02:00","dateModified":"2016-06-10T10:01:36+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365","og:description":"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo","og:url":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-06-10T08:31:36+00:00","article:modified_time":"2016-06-10T08:31:36+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Luz verde para llamada a talleres de 1,1 millones de autos de VW | Cand\u00e1s 365","twitter:description":"(dpa) - Las autoridades alemanas dieron luz verde para la llamada a talleres en Europa de m\u00e1s de 1,1 millones de coches del gigante automotor alem\u00e1n Volkswagen dotados con motores di\u00e9sel que simulaban menores emisiones contaminantes, comunic\u00f3 hoy la compa\u00f1\u00eda. Tras meses de retrasos, la revisi\u00f3n de los autom\u00f3viles de VW afectados por el esc\u00e1ndalo","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/c365noticias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"29910","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:32:34","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:29","updated":"2026-05-15 21:32:34","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLuz verde para llamada a talleres de 1,1 millones de autos de VW\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Luz verde para llamada a talleres de 1,1 millones de autos de VW","link":"https:\/\/candas365.es\/noticias\/luz-verde-para-llamada-a-talleres-de-11-millones-de-autos-de-vw\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29910"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/16457"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}