{"id":29871,"date":"2016-06-10T09:44:16","date_gmt":"2016-06-10T08:14:16","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29871"},"modified":"2016-06-10T09:44:16","modified_gmt":"2016-06-10T08:14:16","slug":"hierro-fima-con-el-real-oviedo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/","title":{"rendered":"Hierro fima con el Real Oviedo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-29872\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-360x257.jpg\" alt=\"fotonoticia_20160608102813_800\" width=\"360\" height=\"257\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-360x257.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-650x463.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-768x547.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-150x107.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-450x321.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-655x467.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-100x70.jpg 100w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-696x496.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800-589x420.jpg 589w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg 800w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3 el club.<\/p>\n<p>Como jugador, el malague\u00f1o desarroll\u00f3 la mayor parte de su trayectoria deportiva en el Real Madrid (1989-2003), donde conquist\u00f3 cinco Ligas, tres Ligas de Campeones y dos Copas Intercontinentales. Adem\u00e1s, como internacional, el exjugador visti\u00f3 la camiseta de la selecci\u00f3n en 89 ocasiones y particip\u00f3 en cuatro Mundiales y dos Eurocopas, anotando un total de 31 goles.<\/p>\n<p>Tras su retirada como futbolista, el andaluz pas\u00f3 a ocupar el cargo de director deportivo de la Real Federaci\u00f3n Espa\u00f1ola de F\u00fatbol (RFEF) durante cuatro a\u00f1os (2007-2011) y luego se incorpor\u00f3 al M\u00e1laga CF como manager del equipo. Ya por \u00faltimo en la temporada 2014-15, el exjugador blanco form\u00f3 parte del cuerpo t\u00e9cnico del Real Madrid, ocupando el cargo de segundo entrenador del italiano Carlo Ancelotti.<\/p>\n<p>Hierro toma el relevo en el banquillo del conjunto asturiano del tambi\u00e9n exjugador David Generelo, que no pudo lograr la clasificaci\u00f3n para los &#8216;play-offs&#8217; de ascenso a la Liga BBVA. Generelo ocup\u00f3 el cargo ya empezado el curso 2015-16 tras la dimisi\u00f3n de Sergio Egea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3<\/p>\n","protected":false},"author":1,"featured_media":29872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29871","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hierro fima con el Real Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-10T08:14:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-10T08:14:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hierro fima con el Real Oviedo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#listItem\",\"name\":\"Hierro fima con el Real Oviedo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#listItem\",\"position\":3,\"name\":\"Hierro fima con el Real Oviedo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#newsarticle\",\"name\":\"Hierro fima con el Real Oviedo | Cand\\u00e1s 365\",\"headline\":\"Hierro fima con el Real Oviedo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160608102813_800.jpg\",\"width\":800,\"height\":570},\"datePublished\":\"2016-06-10T09:44:16+02:00\",\"dateModified\":\"2016-06-10T09:44:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 10, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/\",\"name\":\"Hierro fima con el Real Oviedo | Cand\\u00e1s 365\",\"description\":\"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\\u00f3n a una temporada m\\u00e1s, y comenzar\\u00e1 a trabajar a partir de la semana que viene, cuando ser\\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\\u00edn del Olmo, seg\\u00fan inform\\u00f3\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/fotonoticia_20160608102813_800.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#mainImage\",\"width\":800,\"height\":570},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/hierro-fima-con-el-real-oviedo\\\/#mainImage\"},\"datePublished\":\"2016-06-10T09:44:16+02:00\",\"dateModified\":\"2016-06-10T09:44:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Hierro fima con el Real Oviedo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Hierro fima con el Real Oviedo | Cand\u00e1s 365","description":"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3","canonical_url":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#listItem","name":"Hierro fima con el Real Oviedo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#listItem","position":3,"name":"Hierro fima con el Real Oviedo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#newsarticle","name":"Hierro fima con el Real Oviedo | Cand\u00e1s 365","headline":"Hierro fima con el Real Oviedo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg","width":800,"height":570},"datePublished":"2016-06-10T09:44:16+02:00","dateModified":"2016-06-10T09:44:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 10, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#webpage","url":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/","name":"Hierro fima con el Real Oviedo | Cand\u00e1s 365","description":"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg","@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#mainImage","width":800,"height":570},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/#mainImage"},"datePublished":"2016-06-10T09:44:16+02:00","dateModified":"2016-06-10T09:44:16+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Hierro fima con el Real Oviedo | Cand\u00e1s 365","og:description":"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3","og:url":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg","og:image:width":800,"og:image:height":570,"article:published_time":"2016-06-10T08:14:16+00:00","article:modified_time":"2016-06-10T08:14:16+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Hierro fima con el Real Oviedo | Cand\u00e1s 365","twitter:description":"El exjugador del Real Madrid Fernando Hierro ha sido nombrado este mi\u00e9rcoles nuevo entrenador del Real Oviedo hasta junio de 2017, con opci\u00f3n a una temporada m\u00e1s, y comenzar\u00e1 a trabajar a partir de la semana que viene, cuando ser\u00e1 presentado, para confeccionar la plantilla junto al asesor del equipo, Joaqu\u00edn del Olmo, seg\u00fan inform\u00f3","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2016\/06\/fotonoticia_20160608102813_800.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"29871","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:29:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:56:29","updated":"2026-05-15 21:29:24","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tHierro fima con el Real Oviedo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Hierro fima con el Real Oviedo","link":"https:\/\/candas365.es\/noticias\/hierro-fima-con-el-real-oviedo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29871"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/29872"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}