{"id":29711,"date":"2016-06-02T18:40:56","date_gmt":"2016-06-02T17:10:56","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29711"},"modified":"2016-06-02T18:40:56","modified_gmt":"2016-06-02T17:10:56","slug":"cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/","title":{"rendered":"Cuatro muertos por fuertes lluvias en el sur de Alemania"},"content":{"rendered":"<p>Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) &#8211; Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales.<\/p>\n<p>Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach am Inn, en el sur de Alemania, tras las fuertes lluvias registradas en un corto periodo de tiempo durante el mi\u00e9rcoles. Los cuerpos fueron hallados por buzos alrededor de las 20:30 hora local (18:30 GMT) en el pueblo del sudeste de Baviera.<\/p>\n<p>La cuarta v\u00edctima, una mujer, fue encontrada m\u00e1s tarde en un arroyo cerca del pueblo de Julbach, tambi\u00e9n en el sudeste de Baviera. Las calles de muchos pueblos de la regi\u00f3n registraban hasta un metro de agua.<\/p>\n<p>La inundaci\u00f3n arrastr\u00f3 coches y \u00e1rboles y muchos vecinos tuvieron que subirse a los techos de sus casas y ser rescatados por helic\u00f3pteros debido a la subida del agua.<\/p>\n<p>Cientos de ni\u00f1os de la regi\u00f3n pasaban la noche en sus escuelas debido al anegamiento de los caminos.<\/p>\n<p>\u00abLa situaci\u00f3n empeor\u00f3 dram\u00e1ticamente en las \u00faltimas horas. Todo el centro qued\u00f3 inundado\u00bb, explic\u00f3 a la agencia dpa Walter Czcechel, alcalde de la localidad de Triftern, de 5.000 habitantes, situada cerca de la frontera con Austria.<\/p>\n<p>El temporal produjo tambi\u00e9n inundaciones en diversos puntos del pa\u00eds. El agua aneg\u00f3 calles en Leipzig, en el este, mientras que los bomberos se emplearon a fondo para bombear s\u00f3tanos inundados en Bremen o Hannover, en el norte.<\/p>\n<p>El servicio meteorol\u00f3gico alem\u00e1n (DWD) emiti\u00f3 alertas por lluvias y tormentas en el sureste, este y norte del pa\u00eds.<\/p>\n<p>Entre tanto, un bombero voluntario fallecido el lunes cuando intentaba rescatar del agua a otra persona que tambi\u00e9n muri\u00f3 fue despedido ayer en Schw\u00e4bisch Gm\u00fcnd, en el sur de Alemania.<\/p>\n<p>En la misma zona murieron tambi\u00e9n del domingo al lunes una ni\u00f1a de 13 a\u00f1os y un hombre de 60 debido al temporal, que tambi\u00e9n derrumb\u00f3 viviendas, bloque\u00f3 carreteras y oblig\u00f3 a suspender parte del servicio ferroviario en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) &#8211; Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach<\/p>\n","protected":false},"author":1,"featured_media":14237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29711","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-02T17:10:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-02T17:10:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#listItem\",\"name\":\"Cuatro muertos por fuertes lluvias en el sur de Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#listItem\",\"position\":3,\"name\":\"Cuatro muertos por fuertes lluvias en el sur de Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#newsarticle\",\"name\":\"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\\u00e1s 365\",\"headline\":\"Cuatro muertos por fuertes lluvias en el sur de Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/internet.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-06-02T18:40:56+02:00\",\"dateModified\":\"2016-06-02T18:40:56+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 2, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/\",\"name\":\"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn\\\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\\u00e1s cientos de ni\\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/internet.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\\\/#mainImage\"},\"datePublished\":\"2016-06-02T18:40:56+02:00\",\"dateModified\":\"2016-06-02T18:40:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365","description":"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach","canonical_url":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#listItem","name":"Cuatro muertos por fuertes lluvias en el sur de Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#listItem","position":3,"name":"Cuatro muertos por fuertes lluvias en el sur de Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#newsarticle","name":"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365","headline":"Cuatro muertos por fuertes lluvias en el sur de Alemania","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","width":655,"height":360},"datePublished":"2016-06-02T18:40:56+02:00","dateModified":"2016-06-02T18:40:56+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 2, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#webpage","url":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/","name":"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365","description":"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/#mainImage"},"datePublished":"2016-06-02T18:40:56+02:00","dateModified":"2016-06-02T18:40:56+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365","og:description":"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach","og:url":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-06-02T17:10:56+00:00","article:modified_time":"2016-06-02T17:10:56+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Cuatro muertos por fuertes lluvias en el sur de Alemania | Cand\u00e1s 365","twitter:description":"Berl\u00edn\/Triftern (Alemania), 2 jun (dpa) - Cuatro personas murieron ayer debido a las fuertes inundaciones en el sur de Alemania, que hicieron que adem\u00e1s cientos de ni\u00f1os tuvieran que pasar la noche en sus escuelas, informaron funcionarios locales. Los cad\u00e1veres de tres personas fueron encontrados ayer en una casa inundada en la localidad de Simbach","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"29711","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:16:40","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:55:56","updated":"2026-05-15 21:16:40","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCuatro muertos por fuertes lluvias en el sur de Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Cuatro muertos por fuertes lluvias en el sur de Alemania","link":"https:\/\/candas365.es\/noticias\/cuatro-muertos-por-fuertes-lluvias-en-el-sur-de-alemania\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29711"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/14237"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}