{"id":29707,"date":"2016-06-02T18:38:16","date_gmt":"2016-06-02T17:08:16","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29707"},"modified":"2016-06-02T18:38:16","modified_gmt":"2016-06-02T17:08:16","slug":"steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/","title":{"rendered":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura"},"content":{"rendered":"<p>(dpa) &#8211; El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano.<\/p>\n<p>As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas de la dictadura -alrededor de 30.000, seg\u00fan c\u00e1lculos de organismos de derechos humanos- hab\u00eda muchos de origen o nacionalidad alemana.<\/p>\n<p>Por el contrario, el ministro socialdem\u00f3crata (SPD) aclar\u00f3 el martes que no tiene previsto anunciar nuevos pasos para revisar la pol\u00edtica de derechos humanos de Alemania hacia Argentina en tiempos de la dictadura, una de las expectativas que hab\u00eda generado su viaje.<\/p>\n<p>El programa de su visita incluye tambi\u00e9n una reuni\u00f3n con el presidente Mauricio Macri, que viajar\u00e1 a Alemania el 5 de julio. La preparaci\u00f3n de esa visita es uno de los objetivos centrales del viaje de Steinmeier.<\/p>\n<p>\u00abEs una visita con agenda abierta en la que podemos y queremos impulsar un nuevo cap\u00edtulo en las relaciones\u00bb, defini\u00f3 el ministro alem\u00e1n el martes.<\/p>\n<p>Tras pasar el jueves y el viernes en Argentina, Steinmeier seguir\u00e1 viaje el s\u00e1bado a M\u00e9xico, donde adem\u00e1s de reuniones pol\u00edticas inaugurar\u00e1 el lunes oficialmente el \u00abA\u00f1o de Alemania\u00bb en el pa\u00eds norteamericano.<\/p>\n<p>El ministro alem\u00e1n y candidato a canciller para las elecciones de 2009 emprendi\u00f3 su gira latinoamericana acompa\u00f1ado por una amplia delegaci\u00f3n de representantes del mundo econ\u00f3mico y cultural de la primera potencia europea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas<\/p>\n","protected":false},"author":1,"featured_media":14237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29707","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-02T17:08:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-02T17:08:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#listItem\",\"name\":\"Steinmeier se reunir\\u00e1 en Argentina con v\\u00edctimas de la dictadura\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#listItem\",\"position\":3,\"name\":\"Steinmeier se reunir\\u00e1 en Argentina con v\\u00edctimas de la dictadura\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#newsarticle\",\"name\":\"Steinmeier se reunir\\u00e1 en Argentina con v\\u00edctimas de la dictadura | Cand\\u00e1s 365\",\"headline\":\"Steinmeier se reunir\\u00e1 en Argentina con v\\u00edctimas de la dictadura\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/internet.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-06-02T18:38:16+02:00\",\"dateModified\":\"2016-06-02T18:38:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 2, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/\",\"name\":\"Steinmeier se reunir\\u00e1 en Argentina con v\\u00edctimas de la dictadura | Cand\\u00e1s 365\",\"description\":\"(dpa) - El ministro de Exteriores alem\\u00e1n, Frank-Walter Steinmeier, se reunir\\u00e1 con familiares de v\\u00edctimas de la \\u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\\u00e1 ma\\u00f1ana jueves al pa\\u00eds sudamericano. As\\u00ed lo inform\\u00f3 hoy el Ministerio de Exteriores en Berl\\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\\u00edctimas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/internet.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\\\/#mainImage\"},\"datePublished\":\"2016-06-02T18:38:16+02:00\",\"dateModified\":\"2016-06-02T18:38:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365","description":"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas","canonical_url":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#listItem","name":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#listItem","position":3,"name":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#newsarticle","name":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365","headline":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","width":655,"height":360},"datePublished":"2016-06-02T18:38:16+02:00","dateModified":"2016-06-02T18:38:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 2, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#webpage","url":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/","name":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365","description":"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/#mainImage"},"datePublished":"2016-06-02T18:38:16+02:00","dateModified":"2016-06-02T18:38:16+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365","og:description":"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas","og:url":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-06-02T17:08:16+00:00","article:modified_time":"2016-06-02T17:08:16+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura | Cand\u00e1s 365","twitter:description":"(dpa) - El ministro de Exteriores alem\u00e1n, Frank-Walter Steinmeier, se reunir\u00e1 con familiares de v\u00edctimas de la \u00faltima dictadura militar argentina (1976-1983) durante la visita que iniciar\u00e1 ma\u00f1ana jueves al pa\u00eds sudamericano. As\u00ed lo inform\u00f3 hoy el Ministerio de Exteriores en Berl\u00edn antes de que Steinmeier tomara el vuelo a Buenos Aires. Entre las v\u00edctimas","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/internet.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"29707","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:16:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:55:56","updated":"2026-05-15 21:16:27","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSteinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Steinmeier se reunir\u00e1 en Argentina con v\u00edctimas de la dictadura","link":"https:\/\/candas365.es\/noticias\/steinmeier-se-reunira-en-argentina-con-victimas-de-la-dictadura\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29707"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/14237"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}