{"id":29634,"date":"2016-06-02T07:40:14","date_gmt":"2016-06-02T06:10:14","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=29634"},"modified":"2016-06-02T07:40:14","modified_gmt":"2016-06-02T06:10:14","slug":"un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/","title":{"rendered":"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\u00f3metros"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-11776\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera-360x198.jpg\" alt=\"carretera\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido.<\/p>\n<p>Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General de Tr\u00e1fico consultada por Europa Press, el carril izquierdo de la autov\u00eda permaneci\u00f3 cerrado al tr\u00e1fico durante m\u00e1s de una hora y las mayores retenciones se produjeron entre los puntos kilom\u00e9tricos 14.9 y 19.<\/p>\n<p>Actualmente la circulaci\u00f3n en sentido Gij\u00f3n de la denominada &#8216;Y&#8217; ya est\u00e1 restablecida, quedando \u00fanicamente el arc\u00e9n cerrado a la altura del punto kilom\u00e9trico 15 (Remoria).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General<\/p>\n","protected":false},"author":1,"featured_media":11776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-29634","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-02T06:10:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-02T06:10:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#listItem\",\"name\":\"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\\u00f3metros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#listItem\",\"position\":3,\"name\":\"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\\u00f3metros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#newsarticle\",\"name\":\"Un accidente en la autopista \\u2018Y\\u2019 causa retenciones de varios kil\\u00f3metros | Cand\\u00e1s 365\",\"headline\":\"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\\u00f3metros\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/carretera.jpg\",\"width\":655,\"height\":360},\"datePublished\":\"2016-06-02T07:40:14+02:00\",\"dateModified\":\"2016-06-02T07:40:14+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 2, 2016.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/\",\"name\":\"Un accidente en la autopista \\u2018Y\\u2019 causa retenciones de varios kil\\u00f3metros | Cand\\u00e1s 365\",\"description\":\"Un accidente en la autopista A-66 entre tres veh\\u00edculos ha provocado, a primera hora de esta ma\\u00f1ana, retenciones de hasta cuatro kil\\u00f3metros en sentido Gij\\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\\u00e9rcoles y el tr\\u00e1fico ya est\\u00e1 restablecido. Seg\\u00fan informaci\\u00f3n de la Direcci\\u00f3n General\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/carretera.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#mainImage\",\"width\":655,\"height\":360},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\\\/#mainImage\"},\"datePublished\":\"2016-06-02T07:40:14+02:00\",\"dateModified\":\"2016-06-02T07:40:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365","description":"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General","canonical_url":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#listItem","name":"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\u00f3metros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#listItem","position":3,"name":"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\u00f3metros","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#newsarticle","name":"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365","headline":"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\u00f3metros","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg","width":655,"height":360},"datePublished":"2016-06-02T07:40:14+02:00","dateModified":"2016-06-02T07:40:14+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 2, 2016."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#webpage","url":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/","name":"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365","description":"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg","@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#mainImage","width":655,"height":360},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/#mainImage"},"datePublished":"2016-06-02T07:40:14+02:00","dateModified":"2016-06-02T07:40:14+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365","og:description":"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General","og:url":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg","og:image:width":655,"og:image:height":360,"article:published_time":"2016-06-02T06:10:14+00:00","article:modified_time":"2016-06-02T06:10:14+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Un accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros | Cand\u00e1s 365","twitter:description":"Un accidente en la autopista A-66 entre tres veh\u00edculos ha provocado, a primera hora de esta ma\u00f1ana, retenciones de hasta cuatro kil\u00f3metros en sentido Gij\u00f3n, entre Remoria y Santa Rosa. El accidente se produjo en torno a las 8.30 horas de este mi\u00e9rcoles y el tr\u00e1fico ya est\u00e1 restablecido. Seg\u00fan informaci\u00f3n de la Direcci\u00f3n General","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/06\/carretera.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"29634","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 21:09:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 12:55:54","updated":"2026-05-15 21:09:39","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUn accidente en la autopista \u2018Y\u2019 causa retenciones de varios kil\u00f3metros\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Un accidente en la autopista &#8216;Y&#8217; causa retenciones de varios kil\u00f3metros","link":"https:\/\/candas365.es\/noticias\/un-accidente-en-la-autopista-y-causa-retenciones-de-varios-kilometros\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=29634"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/29634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/11776"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=29634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=29634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=29634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}