{"id":195927,"date":"2026-06-22T21:58:14","date_gmt":"2026-06-22T19:58:14","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=195927"},"modified":"2026-06-22T21:58:14","modified_gmt":"2026-06-22T19:58:14","slug":"san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/","title":{"rendered":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente"},"content":{"rendered":"<p>El <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" title=\"Ayuntamiento de Gij\u00f3n\" href=\"https:\/\/www.gijon.es\/es\" target=\"_blank\" rel=\"noopener\"><strong>Ayuntamiento de Gij\u00f3n<\/strong><\/a><\/span> ha recordado que, en la Noche de <a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\"><span style=\"color: #ff6600;\"><strong>San Xuan<\/strong><\/span><\/a>, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente, adem\u00e1s de la instalada por el Consistorio.<\/p>\n<figure id=\"attachment_195928\" aria-describedby=\"caption-attachment-195928\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-195928\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-650x434.jpg\" alt=\"San Xuan 2026 en Gij\u00f3n\" width=\"650\" height=\"434\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-650x434.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-768x513.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-150x100.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon-450x301.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg 1123w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-195928\" class=\"wp-caption-text\">EUROPA PRESS<\/figcaption><\/figure>\n<p>El Ayuntamiento de Gij\u00f3n, a trav\u00e9s de la Concejal\u00eda de Seguridad Ciudadana y Emergencias, ha recordado este lunes que solo est\u00e1n permitidas en la playa de Poniente, con motivo de la Noche de San Xuan, las hogueras de particulares con dimensiones m\u00e1ximas de 50 cent\u00edmetros, al margen de la instalada por el Consistorio.<\/p>\n<p>Para ello, el Servicio de Prevenci\u00f3n y Extinci\u00f3n de Incendios y Salvamentos ha elaborado una serie de normas preventivas, seg\u00fan una nota de prensa del Consistorio gijon\u00e9s.<\/p>\n<p>En primer t\u00e9rmino, solo estar\u00e1n permitidas peque\u00f1as hogueras, con dimensiones m\u00e1ximas de 50 cent\u00edmetros de alto, ancho y largo, en la playa de Poniente, y deber\u00e1n estar separadas entre ellas, al menos, seis metros.<\/p>\n<p>Se destaca, en este sentido, que cuanto m\u00e1s peque\u00f1a sea la hoguera, menos contaminaci\u00f3n del aire respirable se producir\u00e1. De igual modo, solo est\u00e1 permitida la quema de maderas y cartones.<\/p>\n<p>No se podr\u00e1n, por tanto, quemar basuras, residuos, espumas, colchones, botes, pl\u00e1sticos, spray o cualquier material semejante, como tampoco se podr\u00e1n utilizar artificios pirot\u00e9cnicos ni maderas que contengan clavos tornillos u objetos punzantes.<\/p>\n<p>Por otra parte, a la hora de encender la hoguera no se utilizar\u00e1n l\u00edquidos inflamables como alcohol, queroseno, gasolina, disolventes y otros que puedan suponer un riesgo. El Ayuntamiento ha advertido, al respecto, de que el uso de estos l\u00edquidos produce vapores que pueden arder de forma imprevista y generar quemaduras.<\/p>\n<p>Asimismo, deber\u00e1 haber una persona mayor de edad presente hasta el apagado total de cada hoguera. Una vez concluida la quema, se deber\u00e1 verificar su total extinci\u00f3n, con objeto de evitar que rescoldos o brasas puedan ser arrastrados por el viento. Para ello, recomiendan el uso de agua fundamentalmente.<\/p>\n<p>No est\u00e1 permitido, adem\u00e1s, saltar por encima de las hogueras o de los rescoldos, ni sacar de las mismas materiales ardiendo o incandescentes. Tampoco se recomienda caminar descalzo por la playa y se aconseja tener a los ni\u00f1os vigilados en todo momento.<\/p>\n<p>En el caso de los residentes de los pisos cercanos a la playa de Poniente, se les recomienda que cierren las ventanas y que retiren de balcones y terrazas cualquier producto que pueda arder.<\/p>\n<h1 class=\"ladillo\">DISPOSITIVO ESPECIAL DE LIMPIEZA<\/h1>\n<p>Con motivo de la hoguera de San Xuan, Emulsa ha dise\u00f1ado un dispositivo especial de limpieza, con el objetivo de garantizar que los principales espacios p\u00fablicos, playas y parques de la ciudad recuperen su uso habitual en el menor tiempo posible tras la noche de la celebraci\u00f3n.<\/p>\n<p>El operativo se activar\u00e1 a partir de las 6:00 horas del pr\u00f3ximo mi\u00e9rcoles, 24 de junio, una vez recibida la autorizaci\u00f3n del servicio de extinci\u00f3n. Contar\u00e1 inicialmente con 18 operarios, que podr\u00e1n ser reforzados en funci\u00f3n de la cantidad de residuos acumulados y la evoluci\u00f3n de los trabajos de limpieza.<\/p>\n<p>En los accesos a la playa de Poniente, asimismo, se instalar\u00e1 un refuerzo espec\u00edfico de contenedores de recogida selectiva, especialmente de envases y cart\u00f3n, con el objetivo de facilitar el reciclaje y mejorar la separaci\u00f3n de residuos durante la jornada festiva.<\/p>\n<p>Emulsa ha hecho, adem\u00e1s, un llamamiento a la ciudadan\u00eda para que durante la celebraci\u00f3n se haga un uso responsable de los espacios p\u00fablicos, especialmente en playas y zonas verdes, evitando el abandono de residuos y utilizando los contenedores habilitados para la correcta separaci\u00f3n de los mismos.<\/p>\n<p>De forma espec\u00edfica, se recuerda la necesidad de extremar la precauci\u00f3n con el vidrio, ya que su presencia en la arena y espacios p\u00fablicos puede generar riesgos para los usuarios al d\u00eda siguiente, especialmente ba\u00f1istas.<\/p>\n<p>Tambi\u00e9n se ha recordado que est\u00e1 terminantemente prohibido el uso de palets con clavos u otros elementos de madera no autorizados para las hogueras, debi\u00e9ndose utilizar exclusivamente le\u00f1a permitida conforme a la normativa vigente.<\/p>\n<p>EUROPA PRESS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente, adem\u00e1s de la instalada por el Consistorio. El Ayuntamiento de Gij\u00f3n, a trav\u00e9s de la Concejal\u00eda de Seguridad Ciudadana y Emergencias, ha recordado este lunes que solo est\u00e1n<\/p>\n","protected":false},"author":1,"featured_media":195928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[512,465],"class_list":["post-195927","post","type-post","status-publish","format-standard","has-post-thumbnail","category-revista","tag-gijon","tag-ocio"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"revista\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1123\" \/>\n\t\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-22T19:58:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-22T19:58:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"position\":2,\"name\":\"Revista\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#listItem\",\"name\":\"San Xuan 2026 en Gij\\u00f3n: solo hogueras peque\\u00f1as en Poniente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#listItem\",\"position\":3,\"name\":\"San Xuan 2026 en Gij\\u00f3n: solo hogueras peque\\u00f1as en Poniente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/revista\\\/#listItem\",\"name\":\"Revista\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#newsarticle\",\"name\":\"San Xuan 2026 en Gij\\u00f3n: solo hogueras peque\\u00f1as en Poniente | Cand\\u00e1s 365\",\"headline\":\"San Xuan 2026 en Gij\\u00f3n: solo hogueras peque\\u00f1as en Poniente\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Xuan-2026-en-Gijon.jpg\",\"width\":1123,\"height\":750,\"caption\":\"EUROPA PRESS\"},\"datePublished\":\"2026-06-22T21:58:14+02:00\",\"dateModified\":\"2026-06-22T21:58:14+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#webpage\"},\"articleSection\":\"Revista, Gij\\u00f3n, Ocio\",\"dateline\":\"Publicado el junio 22, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/\",\"name\":\"San Xuan 2026 en Gij\\u00f3n: solo hogueras peque\\u00f1as en Poniente | Cand\\u00e1s 365\",\"description\":\"El Ayuntamiento de Gij\\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\\u00edmetros en la playa de Poniente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Xuan-2026-en-Gijon.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#mainImage\",\"width\":1123,\"height\":750,\"caption\":\"EUROPA PRESS\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\\\/#mainImage\"},\"datePublished\":\"2026-06-22T21:58:14+02:00\",\"dateModified\":\"2026-06-22T21:58:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365","description":"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente","canonical_url":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/","robots":"max-image-preview:large","keywords":"revista","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","position":2,"name":"Revista","item":"https:\/\/candas365.es\/noticias\/category\/revista\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#listItem","name":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#listItem","position":3,"name":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/revista\/#listItem","name":"Revista"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#newsarticle","name":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365","headline":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg","width":1123,"height":750,"caption":"EUROPA PRESS"},"datePublished":"2026-06-22T21:58:14+02:00","dateModified":"2026-06-22T21:58:14+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#webpage"},"articleSection":"Revista, Gij\u00f3n, Ocio","dateline":"Publicado el junio 22, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#webpage","url":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/","name":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365","description":"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg","@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#mainImage","width":1123,"height":750,"caption":"EUROPA PRESS"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/#mainImage"},"datePublished":"2026-06-22T21:58:14+02:00","dateModified":"2026-06-22T21:58:14+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365","og:description":"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente","og:url":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg","og:image:width":1123,"og:image:height":750,"article:published_time":"2026-06-22T19:58:14+00:00","article:modified_time":"2026-06-22T19:58:14+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente | Cand\u00e1s 365","twitter:description":"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/San-Xuan-2026-en-Gijon.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"195927","title":null,"description":"El Ayuntamiento de Gij\u00f3n ha recordado que, en la Noche de San Xuan, solo se permiten hogueras particulares de hasta 50 cent\u00edmetros en la playa de Poniente","keywords":null,"keyphrases":{"focus":{"keyphrase":"San Xuan","score":85,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"Gij\u00f3n","score":80,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},{"keyphrase":"Poniente","score":87,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-22 20:00:31","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-22 19:50:47","updated":"2026-06-22 20:01:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/revista\/\" title=\"Revista\">Revista<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSan Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Revista","link":"https:\/\/candas365.es\/noticias\/category\/revista\/"},{"label":"San Xuan 2026 en Gij\u00f3n: solo hogueras peque\u00f1as en Poniente","link":"https:\/\/candas365.es\/noticias\/san-xuan-2026-en-gijon-solo-hogueras-pequenas-en-poniente\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/195927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=195927"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/195927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/195928"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=195927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=195927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=195927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}