{"id":195870,"date":"2026-06-22T15:21:26","date_gmt":"2026-06-22T13:21:26","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=195870"},"modified":"2026-06-22T15:21:26","modified_gmt":"2026-06-22T13:21:26","slug":"barbon-rechaza-en-candas-el-uso-politico-de-cerredo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/","title":{"rendered":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo"},"content":{"rendered":"<p>El presidente del <a href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Principado<\/strong><\/span><\/a> de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en <a href=\"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/\"><span style=\"color: #ff6600;\"><strong>Cand\u00e1s<\/strong><\/span><\/a> que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo<\/p>\n<figure id=\"attachment_195871\" aria-describedby=\"caption-attachment-195871\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-195871\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-650x375.jpg\" alt=\"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo\" width=\"650\" height=\"375\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-650x375.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-360x208.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-768x444.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-150x87.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo-450x260.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg 1181w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-195871\" class=\"wp-caption-text\">Foto: Nacho Berm\u00fadez<\/figcaption><\/figure>\n<p>El presidente del Gobierno del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha dicho este lunes que conf\u00eda plenamente en la acci\u00f3n de la justicia en relaci\u00f3n al accidente minero de Cerredo, en el municipio asturiano de Dega\u00f1a, en el que murieron cinco personas y otros cuatro resultaron heridos.<\/p>\n<p>Precisamente esta semana se va a aprobar en el pleno de la Junta General del Principado de Asturias el dictamen de la comisi\u00f3n de investigaci\u00f3n que ha investigado el accidente, producido hace un a\u00f1o. \u00ab\u00bfEst\u00e1 utilizando la oposici\u00f3n eso para hacer da\u00f1o electoral al Gobierno?\u00bb, se ha preguntado. \u00abPues seguramente lo est\u00e1 intentando\u00bb, ha a\u00f1adido posteriormente.<\/p>\n<p>Barb\u00f3n, a preguntas de los periodistas en Cand\u00e1s, ha criticado duramente lo que considera un aprovechamiento electoral de la tragedia por parte de la oposici\u00f3n, afirmando que \u00aba la inmensa mayor\u00eda de la ciudadan\u00eda asturiana le asquea que se utilice la muerte de una persona para hacer debate electoral o intereses en inter\u00e9s electoral\u00bb.<\/p>\n<p>El presidente ha reiterado su compromiso con el esclarecimiento de los hechos, manifestando que est\u00e1 \u00abconvencido que sabremos qui\u00e9nes son los responsables y los culpables de esas muertes, que es a lo que yo me compromet\u00ed de llegar hasta el final y que la justicia act\u00fae\u00bb.<\/p>\n<p>Barb\u00f3n ha destacado la colaboraci\u00f3n del Gobierno asturiano con la justicia en la investigaci\u00f3n, subrayando que \u00abmientras en otras comunidades se retiraban apoyos a los juzgados que instruyen causas con muchos m\u00e1s muertos, en Asturias reforzamos con todo el personal que se nos pidi\u00f3\u00bb.<\/p>\n<p>El presidente ha concluido enfatizando su determinaci\u00f3n de mantener el apoyo necesario a la investigaci\u00f3n judicial, aseverando que \u00ablo reforzaremos tantas veces sea necesario porque es mi compromiso\u00bb, dejando clara su prioridad en que prevalezca la justicia sobre cualquier consideraci\u00f3n electoral.<\/p>\n<p>EUROPA PRESS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo El presidente del Gobierno del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha dicho este lunes que conf\u00eda plenamente en la acci\u00f3n de la justicia en relaci\u00f3n al accidente minero de<\/p>\n","protected":false},"author":1,"featured_media":195871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380,366,470],"class_list":["post-195870","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias","tag-asturias","tag-candas","tag-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-22T13:21:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-22T13:21:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#listItem\",\"name\":\"Barb\\u00f3n rechaza en Cand\\u00e1s el uso pol\\u00edtico de Cerredo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#listItem\",\"position\":3,\"name\":\"Barb\\u00f3n rechaza en Cand\\u00e1s el uso pol\\u00edtico de Cerredo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#newsarticle\",\"name\":\"Barb\\u00f3n rechaza en Cand\\u00e1s el uso pol\\u00edtico de Cerredo | Cand\\u00e1s 365\",\"headline\":\"Barb\\u00f3n rechaza en Cand\\u00e1s el uso pol\\u00edtico de Cerredo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg\",\"width\":1181,\"height\":682,\"caption\":\"Foto: Nacho Berm\\u00fadez\"},\"datePublished\":\"2026-06-22T15:21:26+02:00\",\"dateModified\":\"2026-06-22T15:21:26+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias, Cand\\u00e1s, pol\\u00edtica\",\"dateline\":\"Publicado el junio 22, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/\",\"name\":\"Barb\\u00f3n rechaza en Cand\\u00e1s el uso pol\\u00edtico de Cerredo | Cand\\u00e1s 365\",\"description\":\"El presidente del Principado de Asturias, Adri\\u00e1n Barb\\u00f3n, ha rechazado hoy en Cand\\u00e1s que se haga un uso pol\\u00edtico y electoral del accidente minero de Cerredo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#mainImage\",\"width\":1181,\"height\":682,\"caption\":\"Foto: Nacho Berm\\u00fadez\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\\\/#mainImage\"},\"datePublished\":\"2026-06-22T15:21:26+02:00\",\"dateModified\":\"2026-06-22T15:21:26+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365","description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo","canonical_url":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#listItem","name":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#listItem","position":3,"name":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#newsarticle","name":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365","headline":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg","width":1181,"height":682,"caption":"Foto: Nacho Berm\u00fadez"},"datePublished":"2026-06-22T15:21:26+02:00","dateModified":"2026-06-22T15:21:26+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#webpage"},"articleSection":"Asturias, Asturias, Cand\u00e1s, pol\u00edtica","dateline":"Publicado el junio 22, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#webpage","url":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/","name":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365","description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg","@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#mainImage","width":1181,"height":682,"caption":"Foto: Nacho Berm\u00fadez"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/#mainImage"},"datePublished":"2026-06-22T15:21:26+02:00","dateModified":"2026-06-22T15:21:26+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365","og:description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo","og:url":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg","og:image:width":1181,"og:image:height":682,"article:published_time":"2026-06-22T13:21:26+00:00","article:modified_time":"2026-06-22T13:21:26+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo | Cand\u00e1s 365","twitter:description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/06\/Barbon-rechaza-en-Candas-el-uso-politico-de-Cerredo.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"195870","title":null,"description":"El presidente del Principado de Asturias, Adri\u00e1n Barb\u00f3n, ha rechazado hoy en Cand\u00e1s que se haga un uso pol\u00edtico y electoral del accidente minero de Cerredo","keywords":null,"keyphrases":{"focus":{"keyphrase":"Barb\u00f3n","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Cerredo","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},{"keyphrase":"Cand\u00e1s","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-22 13:22:59","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-22 13:15:41","updated":"2026-06-22 13:36:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tBarb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Barb\u00f3n rechaza en Cand\u00e1s el uso pol\u00edtico de Cerredo","link":"https:\/\/candas365.es\/noticias\/barbon-rechaza-en-candas-el-uso-politico-de-cerredo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/195870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=195870"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/195870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/195871"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=195870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=195870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=195870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}