{"id":194970,"date":"2026-05-29T23:59:06","date_gmt":"2026-05-29T21:59:06","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=194970"},"modified":"2026-05-29T23:59:06","modified_gmt":"2026-05-29T21:59:06","slug":"asturias-analizara-una-posible-veda-del-salmon","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/","title":{"rendered":"Asturias analizar\u00e1 una posible veda del salm\u00f3n"},"content":{"rendered":"<p>El <a href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Principado de Asturias<\/strong><\/span><\/a> estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios t\u00e9cnicos y cient\u00edficos.<\/p>\n<figure id=\"attachment_194971\" aria-describedby=\"caption-attachment-194971\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-194971\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-644x480.jpg\" alt=\"Asturias analizar\u00e1 una posible veda del salm\u00f3n\" width=\"644\" height=\"480\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-644x480.jpg 644w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-360x268.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-768x573.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-150x112.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon-450x335.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg 1104w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-194971\" class=\"wp-caption-text\">Archivo &#8211; Un pescador en Asturias<br \/>&#8211; GOBIERNO DE ASTURIAS &#8211; Archivo<\/figcaption><\/figure>\n<p data-start=\"405\" data-end=\"676\">El consejero de Medio Rural y Pol\u00edtica Agraria, Marcelino Marcos, ha manifestado en el pleno que ser\u00e1 una vez que acabe la temporada del salm\u00f3n y \u00abcon criterios t\u00e9cnicos, cient\u00edficos y de sostenibilidad en el largo plazo\u00bb cuando se analice una posible veda de la especie.<\/p>\n<p data-start=\"678\" data-end=\"856\">As\u00ed se lo ha trasladado al diputado del Grupo Mixto por Foro, Adri\u00e1n Pumares, al que ha advertido de que no comparte su opini\u00f3n de que \u00abla izquierda quiere todo lo que es vedar\u00bb.<\/p>\n<p data-start=\"858\" data-end=\"1289\">\u00abOiga, que Galicia lo tiene vedado, Euskadi lo tiene vedado. Entonces, vamos a poner cada cosa en su sitio porque si se llega a una decisi\u00f3n de esas caracter\u00edsticas no es cosa de la izquierda. Cuando se toma una decisi\u00f3n de esas caracter\u00edsticas es en base al conocimiento y a la situaci\u00f3n que se tiene, no solamente en un a\u00f1o, sino a la evoluci\u00f3n de una especie determinada. Entonces, partamos de esa situaci\u00f3n\u00bb, dijo el consejero.<\/p>\n<h2 data-section-id=\"1f8xd1o\" data-start=\"1291\" data-end=\"1361\">El Principado defiende una gesti\u00f3n basada en criterios cient\u00edficos<\/h2>\n<p data-start=\"1363\" data-end=\"1563\">Ha explicado que \u00abla situaci\u00f3n poblacional del salm\u00f3n atl\u00e1ntico no se puede valorar \u00fanicamente por las pol\u00edticas llevadas a cabo por las administraciones, en este caso por la administraci\u00f3n regional\u00bb.<\/p>\n<p data-start=\"1565\" data-end=\"1874\">Marcos L\u00edndez ha indicado que hay que \u00abhablar del salm\u00f3n con responsabilidad, con rigor y con honestidad, lejos de titulares period\u00edsticos\u00bb y por ello desde el Principado lo que vienen defendiendo desde hace tiempo son los datos en base a criterios t\u00e9cnicos, cient\u00edficos y de sostenibilidad en el largo plazo.<\/p>\n<p data-start=\"1876\" data-end=\"2136\">\u00abLa gesti\u00f3n pisc\u00edcola no puede hacerse con decisiones improvisadas, tiene que hacerse apoy\u00e1ndose en esa informaci\u00f3n cient\u00edfica, en el seguimiento continuado de poblaciones, en el conocimiento acumulado desde hace d\u00e9cadas de trabajo t\u00e9cnico\u00bb, dijo el consejero.<\/p>\n<p data-start=\"2138\" data-end=\"2453\">Marcelino Marcos respond\u00eda as\u00ed a una interpelaci\u00f3n del diputado del Grupo Mixto por Foro, Adri\u00e1n Pumares, con quien ha dicho compartir que achacar la situaci\u00f3n del salm\u00f3n al esfuerzo pesquero es desconocer totalmente las distintas razones que pueden llegar a provocar una situaci\u00f3n como la que atraviesa la especie.<\/p>\n<p data-start=\"2455\" data-end=\"3075\">\u00abEl esfuerzo pesquero ha descendido notablemente por la reducci\u00f3n del n\u00famero de licencias, del n\u00famero de pescadores y de la demanda de permisos en cotos salmoneros. Es decir, no estamos ante una presi\u00f3n pesquera creciente, sino ante un escenario donde las restricciones se han endurecido progresivamente y donde los pescadores tambi\u00e9n han asumido a lo largo de los \u00faltimos a\u00f1os importantes sacrificios. Por lo tanto, cuando hablamos de situaci\u00f3n del salm\u00f3n, vuelvo a decir lo que tenemos que hablar desde una visi\u00f3n amplia y rigurosa. Y evidentemente existen m\u00faltiples factores que afectan al salm\u00f3n\u00bb, dijo el consejero.<\/p>\n<h1 data-section-id=\"1vbanve\" data-start=\"3077\" data-end=\"3131\">Foro rechaza que la pesca sea la causa del declive<\/h1>\n<p data-start=\"3133\" data-end=\"3638\"><a href=\"https:\/\/candas365.es\/noticias\/tag\/politica\/\"><span style=\"color: #ff6600;\"><strong>Adri\u00e1n Pumares<\/strong><\/span><\/a> por su parte ha considerado el salm\u00f3n un s\u00edmbolo de algo que forma parte de la entidad del Principado de Asturias desde hace mucho tiempo y ha manifestado que frente a la \u00abinsistencia de algunos de demonizar a los ribere\u00f1os y a los deportistas que practican la tradici\u00f3n de la pesca del salm\u00f3n, hay la obligaci\u00f3n de decir alto y claro que las ca\u00f1as no son la causa de la falta de salm\u00f3n en los r\u00edos asturianos. Creo que hay que partir el debate desde ah\u00ed\u00bb, dijo el diputado del Grupo Mixto.<\/p>\n<p data-start=\"3640\" data-end=\"3924\">\u00abHace aproximadamente una semana, sus socios de gobierno reclamaron la veda de salm\u00f3n como medida urgente ante el evidente declive progresivo de la especie. Yo soy consciente de que es atractivo, sobre todo en esta regi\u00f3n poner soluciones f\u00e1ciles a problemas complejos\u00bb, dijo Pumares.<\/p>\n<p data-start=\"3926\" data-end=\"4293\">En este sentido el diputado de Foro ha instado al Gobierno a analizar las causas reales de este declive y tambi\u00e9n a ofrecer datos claros y fiables sobre el n\u00famero de ejemplares. Adem\u00e1s ha planteado algunas propuestas para hacer frente a la situaci\u00f3n como hacer un esfuerzo para instalar contadores en las cuencas salmoneras para contar con datos con rigor cient\u00edfico.<\/p>\n<p data-start=\"4295\" data-end=\"4524\">\u00abVuelvo a decir lo mismo, la veda desde luego no es la soluci\u00f3n. Culpar a las ca\u00f1as en los r\u00edos es no entender nada de la situaci\u00f3n que enfrenta el salm\u00f3n y adem\u00e1s tendr\u00eda un problema en relaci\u00f3n con las repoblaciones\u00bb, insisti\u00f3.<\/p>\n<p data-start=\"4526\" data-end=\"4538\" data-is-last-node=\"\" data-is-only-node=\"\">EUROPA PRESS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios t\u00e9cnicos y cient\u00edficos. El consejero de Medio Rural y Pol\u00edtica Agraria, Marcelino Marcos, ha manifestado en el pleno que ser\u00e1 una vez que acabe la temporada del salm\u00f3n y \u00abcon criterios t\u00e9cnicos,<\/p>\n","protected":false},"author":1,"featured_media":194971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380],"class_list":["post-194970","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias","tag-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-29T21:59:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-29T21:59:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#listItem\",\"name\":\"Asturias analizar\\u00e1 una posible veda del salm\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#listItem\",\"position\":3,\"name\":\"Asturias analizar\\u00e1 una posible veda del salm\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#newsarticle\",\"name\":\"Asturias analizar\\u00e1 una posible veda del salm\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"Asturias analizar\\u00e1 una posible veda del salm\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Asturias-analizara-una-posible-veda-del-salmon.jpg\",\"width\":1104,\"height\":823,\"caption\":\"Archivo - Un pescador en Asturias\\n- GOBIERNO DE ASTURIAS - Archivo\"},\"datePublished\":\"2026-05-29T23:59:06+02:00\",\"dateModified\":\"2026-05-29T23:59:06+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias\",\"dateline\":\"Publicado el mayo 29, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/\",\"name\":\"Asturias analizar\\u00e1 una posible veda del salm\\u00f3n | Cand\\u00e1s 365\",\"description\":\"El Principado de Asturias estudiar\\u00e1 una posible veda del salm\\u00f3n cuando concluya la temporada y asegura que cualquier decisi\\u00f3n se adoptar\\u00e1 con criterios\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Asturias-analizara-una-posible-veda-del-salmon.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#mainImage\",\"width\":1104,\"height\":823,\"caption\":\"Archivo - Un pescador en Asturias\\n- GOBIERNO DE ASTURIAS - Archivo\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-analizara-una-posible-veda-del-salmon\\\/#mainImage\"},\"datePublished\":\"2026-05-29T23:59:06+02:00\",\"dateModified\":\"2026-05-29T23:59:06+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365","description":"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios","canonical_url":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#listItem","name":"Asturias analizar\u00e1 una posible veda del salm\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#listItem","position":3,"name":"Asturias analizar\u00e1 una posible veda del salm\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#newsarticle","name":"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365","headline":"Asturias analizar\u00e1 una posible veda del salm\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg","width":1104,"height":823,"caption":"Archivo - Un pescador en Asturias\n- GOBIERNO DE ASTURIAS - Archivo"},"datePublished":"2026-05-29T23:59:06+02:00","dateModified":"2026-05-29T23:59:06+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#webpage"},"articleSection":"Asturias, Asturias","dateline":"Publicado el mayo 29, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#webpage","url":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/","name":"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365","description":"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg","@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#mainImage","width":1104,"height":823,"caption":"Archivo - Un pescador en Asturias\n- GOBIERNO DE ASTURIAS - Archivo"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/#mainImage"},"datePublished":"2026-05-29T23:59:06+02:00","dateModified":"2026-05-29T23:59:06+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365","og:description":"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios","og:url":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg","og:image:width":1104,"og:image:height":823,"article:published_time":"2026-05-29T21:59:06+00:00","article:modified_time":"2026-05-29T21:59:06+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Asturias analizar\u00e1 una posible veda del salm\u00f3n | Cand\u00e1s 365","twitter:description":"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Asturias-analizara-una-posible-veda-del-salmon.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"194970","title":null,"description":"El Principado de Asturias estudiar\u00e1 una posible veda del salm\u00f3n cuando concluya la temporada y asegura que cualquier decisi\u00f3n se adoptar\u00e1 con criterios","keywords":null,"keyphrases":{"focus":{"keyphrase":"Asturias","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"salm\u00f3n","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-29 22:01:43","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-29 21:52:52","updated":"2026-05-29 22:03:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAsturias analizar\u00e1 una posible veda del salm\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Asturias analizar\u00e1 una posible veda del salm\u00f3n","link":"https:\/\/candas365.es\/noticias\/asturias-analizara-una-posible-veda-del-salmon\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=194970"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/194971"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=194970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=194970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=194970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}