{"id":194885,"date":"2026-05-28T21:44:58","date_gmt":"2026-05-28T19:44:58","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=194885"},"modified":"2026-05-28T21:44:58","modified_gmt":"2026-05-28T19:44:58","slug":"corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/","title":{"rendered":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026"},"content":{"rendered":"<p>El \u00e1rea recreativa de Overo acogi\u00f3 el <a href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\"><span style=\"color: #ff6600;\"><strong>D\u00eda del \u00c1rbol en Corvera<\/strong><\/span><\/a>, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.<\/p>\n<figure id=\"attachment_194886\" aria-describedby=\"caption-attachment-194886\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-194886\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-650x366.jpg\" alt=\"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026\" width=\"650\" height=\"366\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-650x366.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-360x203.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-768x433.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-150x85.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-450x254.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026-1200x676.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg 1235w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-194886\" class=\"wp-caption-text\">Foto: Prensa Ayuntamiento de Corvera<\/figcaption><\/figure>\n<p data-start=\"366\" data-end=\"721\">El <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.corvera.es\/\" target=\"_blank\" rel=\"noopener\"><strong>Ayuntamiento de Corvera<\/strong><\/a><\/span> ha acogido la celebraci\u00f3n del \u201cD\u00eda del \u00c1rbol\u201d, una cita que cada a\u00f1o se celebra en un municipio distinto de Asturias y que, en esta ocasi\u00f3n, ha tenido como escenario el \u00e1rea recreativa de Overo. La jornada ha contado con un marcado car\u00e1cter educativo y de sensibilizaci\u00f3n medioambiental dirigido especialmente a los m\u00e1s j\u00f3venes.<\/p>\n<p data-start=\"724\" data-end=\"1278\">A esta celebraci\u00f3n del \u201cD\u00eda del \u00c1rbol\u201d, han asistido el director general de gesti\u00f3n forestal del Principado, Javier Vigil; el alcalde de Corvera, Iv\u00e1n Fern\u00e1ndez; Jos\u00e9 Luis Montes, concejal de Cultura del Ayuntamiento de Corvera; y Jorge Su\u00e1rez Jaimes, concejal de Obras y Servicios del Ayuntamiento de Corvera; alcaldes y alcaldesas de municipios que anteriormente acogieron esta celebraci\u00f3n, asociaciones culturales y deportivas, AMPAS y colectivos sociales y festivos de Corvera; y representantes de las empresas colaboradoras y organizadoras del acto.<\/p>\n<p data-start=\"1281\" data-end=\"1884\">El alcalde de Corvera, Iv\u00e1n Fern\u00e1ndez, ha destacado la importancia de que el municipio haya sido elegido para acoger este a\u00f1o una cita de car\u00e1cter regional como el D\u00eda del \u00c1rbol y ha subrayado el valor educativo y social de la jornada: \u201cPara Corvera es un orgullo convertirse durante un d\u00eda en el centro de una actividad festiva, educativa y de concienciaci\u00f3n ambiental dirigida especialmente a los m\u00e1s j\u00f3venes. Este tipo de iniciativas ayudan a transmitir valores fundamentales como el respeto al entorno, la sostenibilidad y la importancia de cuidar nuestro patrimonio natural desde edades tempranas\u201d.<\/p>\n<h1 data-section-id=\"21er6o\" data-start=\"1886\" data-end=\"1927\">Actividades ambientales para escolares<\/h1>\n<p data-start=\"1929\" data-end=\"2614\">En la actividad han participado alrededor de 320 alumnos y alumnas de primero a cuarto curso de distintos centros educativos, acompa\u00f1ados durante toda la jornada por cerca de 60 monitores encargados de coordinar y tutelar las actividades previstas. La elecci\u00f3n de los niveles participantes fue consensuada con los propios colegios tras varias reuniones preparatorias mantenidas con la organizaci\u00f3n. Tras la llegada de los escolares han comenzado las actividades en el \u00e1rea recreativa de Overo, actividades l\u00fadicas y educativas relacionadas con el medio ambiente y la conservaci\u00f3n del entorno natural. Uno de los actos centrales de la jornada ha sido la tradicional plantada de \u00e1rboles.<\/p>\n<h2 data-section-id=\"61c1si\" data-start=\"2617\" data-end=\"2667\">Concurso de dibujo y entrega del Casta\u00f1o de Oro<\/h2>\n<p data-start=\"2669\" data-end=\"3356\">Como actividad previa al evento, se celebr\u00f3 un concurso de dibujo en los centros educativos abierto a todo el alumnado interesado. El fallo del certamen tuvo lugar el pasado lunes y cont\u00f3 con un jurado integrado por representantes de la Consejer\u00eda, de UCOFA \u2014entidad organizadora\u2014 y del Ayuntamiento de Corvera, a trav\u00e9s del \u00e1rea de Cultura. Se conceder\u00e1n premios en cuatro categor\u00edas. La entrega de premios ha tenido lugar durante la jornada. Adem\u00e1s, se realiz\u00f3 la entrega del XII Galard\u00f3n Casta\u00f1o de Oro, que este a\u00f1o ha reca\u00eddo en la Primera Promoci\u00f3n de capataces agr\u00edcolas de la Escuela de Servicultura de Tineo, recogiendo el premio Santiago P\u00e9rez, antiguo alcalde de la localidad.<\/p>\n<h2 data-section-id=\"1bwpdxd\" data-start=\"3359\" data-end=\"3413\">Corvera destinar\u00e1 145.000 euros al patrimonio verde<\/h2>\n<p data-start=\"3415\" data-end=\"4129\">La semana pasada, el Ayuntamiento de Corvera present\u00f3 adem\u00e1s un plan de plantaci\u00f3n y renovaci\u00f3n del arbolado urbano con una inversi\u00f3n estimada de 100.000 euros, complementaria al reciente Plan de Seguridad para la poda y tala selectiva de arbolado, dotado con otros 45.000 euros. En total, el Consistorio destinar\u00e1 145.000 euros a actuaciones relacionadas con la mejora y mantenimiento del patrimonio verde municipal. Las previsiones municipales contemplan la plantaci\u00f3n de cerca de 200 nuevos ejemplares en distintas zonas del concejo. Las actuaciones alcanzar\u00e1n a 15 espacios verdes municipales, entre ellos el \u00e1rea recreativa de Overo, y priorizar\u00e1n especies adaptadas al clima local y con alto valor ambiental.<\/p>\n<p data-start=\"4132\" data-end=\"4915\" data-is-last-node=\"\" data-is-only-node=\"\">El alcalde ha a\u00f1adido que la celebraci\u00f3n supone tambi\u00e9n \u201cun compromiso que asumimos con responsabilidad. No se trata solo de acoger un evento, sino de implicarnos activamente en una jornada que promueve la educaci\u00f3n ambiental y la participaci\u00f3n colectiva. Queremos que los ni\u00f1os y ni\u00f1as vivan esta experiencia como algo cercano, positivo y \u00fatil para su formaci\u00f3n personal\u201d. Ha querido agradecer, asimismo, la colaboraci\u00f3n de todas las entidades implicadas en la organizaci\u00f3n del D\u00eda del \u00c1rbol, as\u00ed como la implicaci\u00f3n de la comunidad educativa y del tejido asociativo local. \u201cLa respuesta de los centros escolares, de las asociaciones y de tantas personas que han querido sumarse demuestra que en Corvera existe sensibilidad y compromiso con este tipo de actividades.\u201d, ha concluido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental. El Ayuntamiento de Corvera ha acogido la celebraci\u00f3n del \u201cD\u00eda del \u00c1rbol\u201d, una cita que cada a\u00f1o se celebra en un municipio distinto de Asturias y que, en esta ocasi\u00f3n, ha<\/p>\n","protected":false},"author":1,"featured_media":194886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380],"class_list":["post-194885","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias","tag-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1235\" \/>\n\t\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-28T19:44:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-28T19:44:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#listItem\",\"name\":\"Corvera re\\u00fane a 320 escolares en el D\\u00eda del \\u00c1rbol 2026\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#listItem\",\"position\":3,\"name\":\"Corvera re\\u00fane a 320 escolares en el D\\u00eda del \\u00c1rbol 2026\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#newsarticle\",\"name\":\"Corvera re\\u00fane a 320 escolares en el D\\u00eda del \\u00c1rbol 2026 | Cand\\u00e1s 365\",\"headline\":\"Corvera re\\u00fane a 320 escolares en el D\\u00eda del \\u00c1rbol 2026\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg\",\"width\":1235,\"height\":696,\"caption\":\"Foto: Prensa Ayuntamiento de Corvera\"},\"datePublished\":\"2026-05-28T21:44:58+02:00\",\"dateModified\":\"2026-05-28T21:44:58+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias\",\"dateline\":\"Publicado el mayo 28, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/\",\"name\":\"Corvera re\\u00fane a 320 escolares en el D\\u00eda del \\u00c1rbol 2026 | Cand\\u00e1s 365\",\"description\":\"El \\u00e1rea recreativa de Overo acogi\\u00f3 el D\\u00eda del \\u00c1rbol en Corvera, con la participaci\\u00f3n de 320 escolares y actividades centradas en educaci\\u00f3n ambiental.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#mainImage\",\"width\":1235,\"height\":696,\"caption\":\"Foto: Prensa Ayuntamiento de Corvera\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\\\/#mainImage\"},\"datePublished\":\"2026-05-28T21:44:58+02:00\",\"dateModified\":\"2026-05-28T21:44:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365","description":"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.","canonical_url":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#listItem","name":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#listItem","position":3,"name":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#newsarticle","name":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365","headline":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg","width":1235,"height":696,"caption":"Foto: Prensa Ayuntamiento de Corvera"},"datePublished":"2026-05-28T21:44:58+02:00","dateModified":"2026-05-28T21:44:58+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#webpage"},"articleSection":"Asturias, Asturias","dateline":"Publicado el mayo 28, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#webpage","url":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/","name":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365","description":"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg","@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#mainImage","width":1235,"height":696,"caption":"Foto: Prensa Ayuntamiento de Corvera"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/#mainImage"},"datePublished":"2026-05-28T21:44:58+02:00","dateModified":"2026-05-28T21:44:58+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365","og:description":"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.","og:url":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg","og:image:width":1235,"og:image:height":696,"article:published_time":"2026-05-28T19:44:58+00:00","article:modified_time":"2026-05-28T19:44:58+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026 | Cand\u00e1s 365","twitter:description":"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Corvera-reune-a-320-escolares-en-el-Dia-del-Arbol-2026.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"194885","title":null,"description":"El \u00e1rea recreativa de Overo acogi\u00f3 el D\u00eda del \u00c1rbol en Corvera, con la participaci\u00f3n de 320 escolares y actividades centradas en educaci\u00f3n ambiental.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Corvera","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"D\u00eda del \u00c1rbol","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-28 19:45:29","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-28 19:27:32","updated":"2026-05-28 20:28:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCorvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Corvera re\u00fane a 320 escolares en el D\u00eda del \u00c1rbol 2026","link":"https:\/\/candas365.es\/noticias\/corvera-reune-a-320-escolares-en-el-dia-del-arbol-2026\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=194885"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/194886"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=194885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=194885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=194885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}