{"id":194566,"date":"2026-05-11T22:36:39","date_gmt":"2026-05-11T20:36:39","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=194566"},"modified":"2026-05-11T22:36:39","modified_gmt":"2026-05-11T20:36:39","slug":"aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/","title":{"rendered":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda"},"content":{"rendered":"<p>El <span style=\"color: #ff6600;\"><strong><a style=\"color: #ff6600;\" title=\"Ayuntamiento de Avil\u00e9s\" href=\"https:\/\/aviles.es\/\" target=\"_blank\" rel=\"noopener\">Ayuntamiento de Avil\u00e9s<\/a><\/strong><\/span> present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda, movilidad y equipamientos<\/p>\n<figure id=\"attachment_194567\" aria-describedby=\"caption-attachment-194567\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-194567\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-650x364.jpg\" alt=\"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda\" width=\"650\" height=\"364\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-650x364.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-360x201.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-768x430.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-150x84.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-450x252.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda-1200x671.jpg 1200w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg 1251w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-194567\" class=\"wp-caption-text\">Foto: Prensa Ayuntamiento de Avil\u00e9s<\/figcaption><\/figure>\n<p data-start=\"400\" data-end=\"763\">El Ayuntamiento de Avil\u00e9s ha presentado las acciones espec\u00edficas del Plan de Barrios 2026-2031, para el \u00e1mbito de <a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\"><span style=\"color: #ff6600;\"><strong>La Carriona, Miranda y San Crist\u00f3bal<\/strong><\/span><\/a>, en un encuentro celebrado en el Centro Sociocultural de La Carriona con entidades, vecinos y vecinas, y en el que han participado la alcaldesa, Mariv\u00ed Monteser\u00edn, y los concejales Agust\u00edn Medina y Pelayo Garc\u00eda.<\/p>\n<p data-start=\"767\" data-end=\"1189\">El periodo 2026-2029 supondr\u00e1 una etapa de importantes inversiones para La Carriona, Miranda y San Crist\u00f3bal, impulsadas especialmente gracias a la estrategia \u201cLa Carriona en Movimiento\u201d, que permitir\u00e1 movilizar 8,9 millones de euros del Plan EDIL para acometer actuaciones orientadas a mejorar los edificios y el espacio p\u00fablico, reforzar la cohesi\u00f3n social y avanzar hacia un modelo de ciudad m\u00e1s sostenible y accesible.<\/p>\n<h1 data-section-id=\"18vrw1n\" data-start=\"1193\" data-end=\"1221\">Equipamientos y movilidad<\/h1>\n<p data-start=\"1225\" data-end=\"1641\">Entre las principales actuaciones previstas destaca la construcci\u00f3n del nuevo Centro Deportivo de La Carriona-Miranda, cuyo proyecto ya ha sido licitado y que contar\u00e1 con una inversi\u00f3n de 4 millones de euros. Este nuevo equipamiento se concibe como un espacio multifuncional y multigeneracional al servicio de todo el barrio, destinado a fomentar la pr\u00e1ctica deportiva, la convivencia y las actividades comunitarias.<\/p>\n<p data-start=\"1645\" data-end=\"1820\">El Plan de Barrios apuesta tambi\u00e9n por la mejora de la eficiencia energ\u00e9tica en edificios p\u00fablicos, con actuaciones previstas en el Colegio P\u00fablico La Carriona-Miranda y en el<\/p>\n<p data-start=\"1824\" data-end=\"2097\">Centro Sociocultural de La Carriona. Estas intervenciones permitir\u00e1n optimizar el consumo energ\u00e9tico, reducir el impacto ambiental de los equipamientos municipales y mejorar la accesibilidad para todos los usuarios, favoreciendo la inclusi\u00f3n y el bienestar de la comunidad.<\/p>\n<p data-start=\"2101\" data-end=\"2562\">A ello se suma el impulso a la generaci\u00f3n de energ\u00eda fotovoltaica mediante la instalaci\u00f3n de sistemas solares en diversos edificios p\u00fablicos del barrio, contribuyendo as\u00ed a promover la sostenibilidad energ\u00e9tica y reducir la dependencia de fuentes de energ\u00eda no renovables. Asimismo, se incrementar\u00e1 la capacidad y accesibilidad de los puntos limpios de La Carriona mediante nuevas infraestructuras que facilitar\u00e1n el reciclaje y la correcta gesti\u00f3n de residuos.<\/p>\n<p data-start=\"2566\" data-end=\"2960\">En el \u00e1mbito de la movilidad y la accesibilidad, el Plan contempla una actuaci\u00f3n integral para mejorar la conexi\u00f3n entre La Carriona y el centro urbano, mediante la renovaci\u00f3n del itinerario entre La Carriona y La Grandiella, en las calles La Carriona y Buenavista, donde se implantar\u00e1 nuevo mobiliario urbano y se mejorar\u00e1 la accesibilidad para hacer m\u00e1s amable y seguro el recorrido peatonal.<\/p>\n<p data-start=\"2964\" data-end=\"3208\">Igualmente, y gracias al compromiso del Gobierno del Principado de Asturias, se actuar\u00e1 en el acondicionamiento de la glorieta de El Corte Ingl\u00e9s, mejorando su seguridad, accesibilidad e imagen como una de las principales entradas de la ciudad.<\/p>\n<p data-start=\"3212\" data-end=\"3611\">Uno de los grandes objetivos del Plan de Barrios es reforzar las conexiones entre los distintos barrios y n\u00facleos del entorno rural. En este sentido, se pone en valor la construcci\u00f3n de la senda peatonal y carril bici entre Miranda y Los Llaos, una actuaci\u00f3n muy demandada y utilizada diariamente por numerosos vecinos y vecinas. Adem\u00e1s, ya se han iniciado los trabajos para instalar ba\u00f1os p\u00fablicos.<\/p>\n<p data-start=\"3615\" data-end=\"4085\">Adem\u00e1s, se continuar\u00e1 avanzando en la mejora y renovaci\u00f3n de caminos y viales, as\u00ed como en el abastecimiento, con actuaciones en los caminos de El Caleyo, La Cabianca, El Rey, Camino La Folleca a El Rey, Valdredo a Sablera, Caliero, Bret\u00f3n, Gas\u00edn y Camino La C\u00e1ndida. junto a intervenciones en la calle Valencia, la avenida de Asturias y Pozo La Granda. A ello se sumar\u00e1n nuevas actuaciones de asfaltado en la calle Chinch\u00f3n, en El Alfaraz, y en el camino de La Folleca.<\/p>\n<h2 data-section-id=\"ytqdvi\" data-start=\"4089\" data-end=\"4125\">Vivienda y equipamientos p\u00fablicos<\/h2>\n<p data-start=\"4129\" data-end=\"4432\">La vivienda constituye otra de las l\u00edneas estrat\u00e9gicas del Plan de Barrios. En este \u00e1mbito, se impulsar\u00e1 la rehabilitaci\u00f3n de las antiguas viviendas de maestros de La Carriona, as\u00ed como la reforma integral del barrio de La Pedrisca, contribuyendo as\u00ed a mejorar el parque residencial y el entorno urbano.<\/p>\n<p data-start=\"4436\" data-end=\"4769\">El Plan contin\u00faa avanzando tambi\u00e9n en la mejora de los equipamientos p\u00fablicos del barrio. En los \u00faltimos a\u00f1os se han realizado actuaciones en el Colegio P\u00fablico La Carriona, con la instalaci\u00f3n de un nuevo escenario en el sal\u00f3n de actos, la renovaci\u00f3n del pavimento del patio y la creaci\u00f3n de nuevos espacios como los huertos urbanos.<\/p>\n<p data-start=\"4773\" data-end=\"5045\">En el \u00e1mbito deportivo, se ha actuado en la accesibilidad del campo de tiro con arco y, de cara a los pr\u00f3ximos a\u00f1os, se contempla la dotaci\u00f3n de un campo de balonmano playa en el Centro Deportivo de Miranda, as\u00ed como nuevas mejoras en instalaciones deportivas del entorno.<\/p>\n<p data-start=\"5049\" data-end=\"5334\">Asimismo, se acometer\u00e1 el refuerzo del vel\u00f3dromo de San Crist\u00f3bal, la construcci\u00f3n de un camino vecinal y la mejora de la red de saneamiento. Adem\u00e1s, el \u00e1rea central del vel\u00f3dromo incorporar\u00e1 una nueva pista multideporte destinada al disfrute de los vecinos y vecinas de San Crist\u00f3bal.<\/p>\n<h2 data-section-id=\"vou636\" data-start=\"5338\" data-end=\"5374\">Patrimonio y actividades sociales<\/h2>\n<p data-start=\"5378\" data-end=\"5636\">El Plan de Barrios mantiene tambi\u00e9n su compromiso con la conservaci\u00f3n y puesta en valor del patrimonio hist\u00f3rico, dando continuidad a actuaciones como la recuperaci\u00f3n del Lavadero Caliero y avanzando pr\u00f3ximamente en la rehabilitaci\u00f3n del lavadero de Miranda.<\/p>\n<p data-start=\"5640\" data-end=\"5944\">Junto a las inversiones en infraestructuras y equipamientos, el Plan incorpora nuevas actividades culturales, deportivas y de ocio, con iniciativas de teatro, cine y conciertos, adem\u00e1s de programas orientados al fomento de la convivencia y a la lucha contra la soledad no deseada de las personas mayores.<\/p>\n<p data-start=\"5948\" data-end=\"6317\" data-is-last-node=\"\" data-is-only-node=\"\">En total, el Plan de Barrios moviliza en La Carriona, Miranda y San Crist\u00f3bal una inversi\u00f3n cercana a los 16 millones de euros (15.939.029,60 \u20ac), de los cuales ya se han ejecutado 1.289.957,21 \u20ac. Entre 2026 y 2027 se impulsar\u00e1n inversiones por importe de 5.832.472,39 \u20ac, mientras que para el periodo 2028-2031 ya est\u00e1n previstas actuaciones por valor de 8.816.600,00 \u20ac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda, movilidad y equipamientos El Ayuntamiento de Avil\u00e9s ha presentado las acciones espec\u00edficas del Plan de Barrios 2026-2031, para el \u00e1mbito de La Carriona, Miranda y San Crist\u00f3bal, en un encuentro celebrado en<\/p>\n","protected":false},"author":1,"featured_media":194567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380],"class_list":["post-194566","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias","tag-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1251\" \/>\n\t\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-11T20:36:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-11T20:36:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#listItem\",\"name\":\"Avil\\u00e9s impulsa nuevas obras en La Carriona y Miranda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#listItem\",\"position\":3,\"name\":\"Avil\\u00e9s impulsa nuevas obras en La Carriona y Miranda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#newsarticle\",\"name\":\"Avil\\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\\u00e1s 365\",\"headline\":\"Avil\\u00e9s impulsa nuevas obras en La Carriona y Miranda\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg\",\"width\":1251,\"height\":700,\"caption\":\"Foto: Prensa Ayuntamiento de Avil\\u00e9s\"},\"datePublished\":\"2026-05-11T22:36:39+02:00\",\"dateModified\":\"2026-05-11T22:36:39+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias\",\"dateline\":\"Publicado el mayo 11, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/\",\"name\":\"Avil\\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\\u00e1s 365\",\"description\":\"El Ayuntamiento de Avil\\u00e9s present\\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\\u00f3bal, con inversiones en vivienda\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#mainImage\",\"width\":1251,\"height\":700,\"caption\":\"Foto: Prensa Ayuntamiento de Avil\\u00e9s\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\\\/#mainImage\"},\"datePublished\":\"2026-05-11T22:36:39+02:00\",\"dateModified\":\"2026-05-11T22:36:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365","description":"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda","canonical_url":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#listItem","name":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#listItem","position":3,"name":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#newsarticle","name":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365","headline":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg","width":1251,"height":700,"caption":"Foto: Prensa Ayuntamiento de Avil\u00e9s"},"datePublished":"2026-05-11T22:36:39+02:00","dateModified":"2026-05-11T22:36:39+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#webpage"},"articleSection":"Asturias, Asturias","dateline":"Publicado el mayo 11, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#webpage","url":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/","name":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365","description":"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg","@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#mainImage","width":1251,"height":700,"caption":"Foto: Prensa Ayuntamiento de Avil\u00e9s"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/#mainImage"},"datePublished":"2026-05-11T22:36:39+02:00","dateModified":"2026-05-11T22:36:39+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365","og:description":"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda","og:url":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg","og:image:width":1251,"og:image:height":700,"article:published_time":"2026-05-11T20:36:39+00:00","article:modified_time":"2026-05-11T20:36:39+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda | Cand\u00e1s 365","twitter:description":"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/05\/Aviles-impulsa-nuevas-obras-en-La-Carriona-y-Miranda.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"194566","title":null,"description":"El Ayuntamiento de Avil\u00e9s present\u00f3 las actuaciones del Plan de Barrios 2026-2031 para La Carriona, Miranda y San Crist\u00f3bal, con inversiones en vivienda","keywords":null,"keyphrases":{"focus":{"keyphrase":"Avil\u00e9s","score":78,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"La Carriona","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-11 20:48:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-11 20:30:44","updated":"2026-05-11 20:50:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAvil\u00e9s impulsa nuevas obras en La Carriona y Miranda\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Avil\u00e9s impulsa nuevas obras en La Carriona y Miranda","link":"https:\/\/candas365.es\/noticias\/aviles-impulsa-nuevas-obras-en-la-carriona-y-miranda\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=194566"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/194566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/194567"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=194566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=194566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=194566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}