{"id":192611,"date":"2026-03-06T14:17:52","date_gmt":"2026-03-06T13:17:52","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=192611"},"modified":"2026-03-06T14:17:52","modified_gmt":"2026-03-06T13:17:52","slug":"asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/","title":{"rendered":"Asturias pide a los ayuntamientos agilizar la dependencia"},"content":{"rendered":"<p data-start=\"61\" data-end=\"404\">La consejera del <a href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>Principado<\/strong> <\/span><\/a>de Asturias <strong data-start=\"108\" data-end=\"126\">Marta del Arco<\/strong>, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar en las labores de valoraci\u00f3n de la <a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\"><span style=\"color: #ff6600;\"><strong>situaci\u00f3n de dependencia<\/strong><\/span><\/a> y en la elaboraci\u00f3n de los <strong data-start=\"314\" data-end=\"358\">programas individuales de atenci\u00f3n (PIA)<\/strong> para reducir los tiempos de las resoluciones.<\/p>\n<figure id=\"attachment_192613\" aria-describedby=\"caption-attachment-192613\" style=\"width: 648px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-192613\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-648x480.jpg\" alt=\"Asturias pide a los ayuntamientos agilizar la dependencia\" width=\"648\" height=\"480\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-648x480.jpg 648w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-360x267.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-768x569.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-150x111.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia-450x333.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg 1124w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><figcaption id=\"caption-attachment-192613\" class=\"wp-caption-text\">Foto: Prensa Principado de Asturias<\/figcaption><\/figure>\n<p data-start=\"406\" data-end=\"678\">La medida forma parte del <strong data-start=\"432\" data-end=\"448\">Plan Agiliza<\/strong>, impulsado por el Gobierno de Asturias para acortar tr\u00e1mites y garantizar una atenci\u00f3n m\u00e1s eficaz a las personas que requieren apoyos en su vida diaria. Este sistema combina <strong data-start=\"623\" data-end=\"677\">financiaci\u00f3n auton\u00f3mica, formaci\u00f3n y apoyo t\u00e9cnico<\/strong>.<\/p>\n<p data-start=\"680\" data-end=\"1150\">En una reuni\u00f3n telem\u00e1tica mantenida con responsables municipales, Del Arco ha precisado que la colaboraci\u00f3n de los ayuntamientos es <strong data-start=\"812\" data-end=\"826\">voluntaria<\/strong> y que su finalidad es <strong data-start=\"849\" data-end=\"865\">complementar<\/strong>, y en ning\u00fan caso sustituir, la actividad de los equipos auton\u00f3micos. \u201cSe trata de aprovechar la cercan\u00eda de los servicios sociales locales para que realicen la valoraci\u00f3n de la dependencia en los domicilios y determinen cu\u00e1l es la prestaci\u00f3n m\u00e1s adecuada en cada caso\u201d, ha explicado.<\/p>\n<h1 data-start=\"1152\" data-end=\"1204\"><strong data-start=\"1152\" data-end=\"1204\">Modelo de colaboraci\u00f3n con las entidades locales<\/strong><\/h1>\n<p data-start=\"1206\" data-end=\"1551\">En la sesi\u00f3n, en la que tambi\u00e9n ha participado la directora general de Gesti\u00f3n de Derechos Sociales, <strong data-start=\"1307\" data-end=\"1324\">Paula \u00c1lvarez<\/strong>, junto con representantes de la pr\u00e1ctica totalidad de los ayuntamientos, la consejera ha detallado las caracter\u00edsticas del modelo, que ya funciona en <strong data-start=\"1475\" data-end=\"1550\">cinco municipios: Castropol, Coa\u00f1a, Villay\u00f3n, Cangas del Narcea e Ibias<\/strong>.<\/p>\n<p data-start=\"1553\" data-end=\"1720\">El sistema se basa en una <strong data-start=\"1579\" data-end=\"1625\">encomienda de valoraci\u00f3n de la dependencia<\/strong> integrada en el <strong data-start=\"1642\" data-end=\"1719\">plan concertado de prestaciones b\u00e1sicas de servicios sociales (2024-2027)<\/strong>.<\/p>\n<p data-start=\"1722\" data-end=\"2088\">Del Arco ha se\u00f1alado que en esta primera reuni\u00f3n \u201cse han sentado las bases de la colaboraci\u00f3n entre la consejer\u00eda y las entidades locales para conocer qu\u00e9 ayuntamientos podr\u00edan asumir estas funciones y comenzar a trabajar\u201d, dado que la iniciativa requiere una labor preparatoria previa, como la formaci\u00f3n de los profesionales y el acceso a herramientas corporativas.<\/p>\n<h2 data-start=\"2090\" data-end=\"2142\"><strong data-start=\"2090\" data-end=\"2142\">Financiaci\u00f3n y requisitos para los profesionales<\/strong><\/h2>\n<p data-start=\"2144\" data-end=\"2311\">La consejer\u00eda ha fijado <strong data-start=\"2168\" data-end=\"2188\">finales de marzo<\/strong> como plazo para que las corporaciones locales planteen dudas o soliciten aclaraciones sobre el funcionamiento del sistema.<\/p>\n<p data-start=\"2313\" data-end=\"2570\">El personal de los servicios sociales municipales encargado de realizar la valoraci\u00f3n y elaborar los programas individuales de atenci\u00f3n deber\u00e1 contar con <strong data-start=\"2467\" data-end=\"2569\">titulaci\u00f3n en Trabajo Social, <a href=\"https:\/\/eldigitaldeasturias.com\/radio\/category\/salud\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">Medicina<\/span><\/a>, Psicolog\u00eda, Enfermer\u00eda, Fisioterapia o Terapia Ocupacional<\/strong>.<\/p>\n<p data-start=\"2572\" data-end=\"2946\">Por su parte, la consejer\u00eda abonar\u00e1 <strong data-start=\"2608\" data-end=\"2672\">190 euros a los ayuntamientos por cada expediente gestionado<\/strong>, con pagos anticipados en cada ejercicio. Adem\u00e1s, Derechos Sociales asumir\u00e1 la <strong data-start=\"2752\" data-end=\"2810\">formaci\u00f3n certificada de los profesionales municipales<\/strong> y la <strong data-start=\"2816\" data-end=\"2846\">supervisi\u00f3n y coordinaci\u00f3n<\/strong> a trav\u00e9s de los equipos territoriales del Sistema para la Autonom\u00eda y la Atenci\u00f3n a la Dependencia.<\/p>\n<p data-start=\"2948\" data-end=\"3150\">Los equipos especializados de la consejer\u00eda continuar\u00e1n colaborando con los ayuntamientos que se adhieran a esta iniciativa con el objetivo de <strong data-start=\"3091\" data-end=\"3149\">garantizar una atenci\u00f3n homog\u00e9nea en toda la comunidad<\/strong>.<\/p>\n<p data-start=\"3152\" data-end=\"3423\" data-is-last-node=\"\" data-is-only-node=\"\">\u201cEsta f\u00f3rmula de colaboraci\u00f3n ha demostrado ser muy eficaz en concejos del \u00e1mbito rural que cuentan con disponibilidad para asumir estas tareas con todas las personas solicitantes que solicitan la dependencia en su territorio o con una parte\u201d, ha valorado Marta del Arco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar en las labores de valoraci\u00f3n de la situaci\u00f3n de dependencia y en la elaboraci\u00f3n de los programas individuales de atenci\u00f3n (PIA) para reducir los tiempos de las resoluciones. La medida forma<\/p>\n","protected":false},"author":1,"featured_media":192613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380],"class_list":["post-192611","post","type-post","status-publish","format-standard","has-post-thumbnail","category-asturias","tag-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1124\" \/>\n\t\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-06T13:17:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-06T13:17:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#listItem\",\"name\":\"Asturias pide a los ayuntamientos agilizar la dependencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#listItem\",\"position\":3,\"name\":\"Asturias pide a los ayuntamientos agilizar la dependencia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#newsarticle\",\"name\":\"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\\u00e1s 365\",\"headline\":\"Asturias pide a los ayuntamientos agilizar la dependencia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg\",\"width\":1124,\"height\":833,\"caption\":\"Foto: Prensa Principado de Asturias\"},\"datePublished\":\"2026-03-06T14:17:52+01:00\",\"dateModified\":\"2026-03-06T14:17:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias\",\"dateline\":\"Publicado el marzo 6, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/\",\"name\":\"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\\u00e1s 365\",\"description\":\"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\\u00f3n que les permite participar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#mainImage\",\"width\":1124,\"height\":833,\"caption\":\"Foto: Prensa Principado de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\\\/#mainImage\"},\"datePublished\":\"2026-03-06T14:17:52+01:00\",\"dateModified\":\"2026-03-06T14:17:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365","description":"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar","canonical_url":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#listItem","name":"Asturias pide a los ayuntamientos agilizar la dependencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#listItem","position":3,"name":"Asturias pide a los ayuntamientos agilizar la dependencia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#newsarticle","name":"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365","headline":"Asturias pide a los ayuntamientos agilizar la dependencia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg","width":1124,"height":833,"caption":"Foto: Prensa Principado de Asturias"},"datePublished":"2026-03-06T14:17:52+01:00","dateModified":"2026-03-06T14:17:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#webpage"},"articleSection":"Asturias, Asturias","dateline":"Publicado el marzo 6, 2026."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#webpage","url":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/","name":"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365","description":"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg","@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#mainImage","width":1124,"height":833,"caption":"Foto: Prensa Principado de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/#mainImage"},"datePublished":"2026-03-06T14:17:52+01:00","dateModified":"2026-03-06T14:17:52+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365","og:description":"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar","og:url":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg","og:image:width":1124,"og:image:height":833,"article:published_time":"2026-03-06T13:17:52+00:00","article:modified_time":"2026-03-06T13:17:52+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Asturias pide a los ayuntamientos agilizar la dependencia | Cand\u00e1s 365","twitter:description":"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/03\/Asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"192611","title":null,"description":"La consejera del Principado de Asturias Marta del Arco, ha animado a los ayuntamientos a incorporarse al modelo de colaboraci\u00f3n que les permite participar","keywords":null,"keyphrases":{"focus":{"keyphrase":"Asturias","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"ayuntamientos","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-03-06 14:14:34","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-06 13:11:46","updated":"2026-03-06 14:14:34"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAsturias pide a los ayuntamientos agilizar la dependencia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Asturias pide a los ayuntamientos agilizar la dependencia","link":"https:\/\/candas365.es\/noticias\/asturias-pide-a-los-ayuntamientos-agilizar-la-dependencia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/192611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=192611"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/192611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/192613"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=192611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=192611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=192611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}