{"id":186363,"date":"2025-05-08T17:26:04","date_gmt":"2025-05-08T15:26:04","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=186363"},"modified":"2025-05-08T17:26:04","modified_gmt":"2025-05-08T15:26:04","slug":"junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/","title":{"rendered":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno"},"content":{"rendered":"<p>Junts ha dado el visto bueno al <a href=\"https:\/\/candas365.es\/noticias\/category\/economia\/\"><span style=\"color: #ff6600;\"><strong>plan antiaranceles del Gobierno<\/strong> <\/span><\/a>validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros previstos en decreto-ley se efect\u00faen con respeto al equilibrio territorial y sobre la base de las exportaciones de bienes con destino a los Estados Unidos.<\/p>\n<figure id=\"attachment_186364\" aria-describedby=\"caption-attachment-186364\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-186364\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-650x426.jpg\" alt=\"Miriam Nogueras Junts\" width=\"650\" height=\"426\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-650x426.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-360x236.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-768x504.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-150x98.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts-450x295.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg 979w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-186364\" class=\"wp-caption-text\">Miriam Nogueras en el Congreso | Foto del Congreso de los Diputados<\/figcaption><\/figure>\n<p>Junts ha blindado que las ayudas previstas para mitigar el impacto de la medida comercial de Trump se rijan por el porcentaje de las exportaciones de cada comunidad, siendo Catalu\u00f1a de las m\u00e1s din\u00e1micas y por tanto beneficiadas, y con particular atenci\u00f3n a aquellas que tengan una mayor exposici\u00f3n.<\/p>\n<p>Para la formaci\u00f3n independentista, ha sido clave cerrar este criterio para proteger al tejido empresarial catal\u00e1n, que se ha caracterizado siempre por su dinamismo y su talante exportador y abierto a nuevos mercados.<\/p>\n<p>Por ello, se ha garantizado que habr\u00e1 mecanismos de seguimiento por parte de Catalu\u00f1a y el resto de las comunidades para garantizar la transparencia, la equidad y la coherencia en la ejecuci\u00f3n del plan. Trimestralmente, el Gobierno remitir\u00e1 al Congreso un informe desglosado por territorio, sector y beneficiarios, para cada uno de los instrumentos previstos en el real decreto-ley. Asimismo, los criterios de ejecuci\u00f3n no podr\u00e1n estar condicionados a criterios de oportunidad pol\u00edtica o de arbitrariedad del \u00f3rgano que las concede.<\/p>\n<p>Junts tambi\u00e9n ha pactado que el ministro de Econom\u00eda comparezca ante la Comisi\u00f3n de Econom\u00eda, Comercio y Transformaci\u00f3n Digital del Congreso, con periodicidad trimestral, para dar cuenta del plan. Las negociaciones entre ambos han discurrido en un contexto de colaboraci\u00f3n y buena predisposici\u00f3n, seg\u00fan las fuentes consultadas.<\/p>\n<p>Seg\u00fan la C\u00e1mara de Comercio de Barcelona, los sectores m\u00e1s afectados, atendiendo a los datos de las exportaciones catalanas al extranjero, ser\u00e1n los productos qu\u00edmicos y farmac\u00e9uticos, la cosm\u00e9tica y la perfumer\u00eda, la maquinaria y los bienes de equipo, el sector agroalimentario (especialmente el aceite oliva y el vino), y el sector de la metalurgia y los productos met\u00e1licos, entre otros.<\/p>\n<p>(<a href=\"https:\/\/www.servimedia.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>SERVIMEDIA<\/strong><\/span><\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros previstos en decreto-ley se efect\u00faen con respeto al equilibrio territorial y sobre la base de las exportaciones de bienes con destino a los Estados Unidos. Junts ha blindado que las ayudas<\/p>\n","protected":false},"author":1,"featured_media":186364,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[470],"class_list":{"0":"post-186363","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-politica"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"979\" \/>\n\t\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-08T15:26:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-08T15:26:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#listItem\",\"name\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#listItem\",\"position\":3,\"name\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#newsarticle\",\"name\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\\u00e1s 365\",\"headline\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Miriam-Nogueras-Junts.jpg\",\"width\":979,\"height\":642,\"caption\":\"Miriam Nogueras en el Congreso | Foto del Congreso de los Diputados\"},\"datePublished\":\"2025-05-08T17:26:04+02:00\",\"dateModified\":\"2025-05-08T17:26:04+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#webpage\"},\"articleSection\":\"Actualidad, pol\\u00edtica\",\"dateline\":\"Publicado el mayo 8, 2025.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/\",\"name\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\\u00e1s 365\",\"description\":\"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Miriam-Nogueras-Junts.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#mainImage\",\"width\":979,\"height\":642,\"caption\":\"Miriam Nogueras en el Congreso | Foto del Congreso de los Diputados\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\\\/#mainImage\"},\"datePublished\":\"2025-05-08T17:26:04+02:00\",\"dateModified\":\"2025-05-08T17:26:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365","description":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros","canonical_url":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#listItem","name":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#listItem","position":3,"name":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#newsarticle","name":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365","headline":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg","width":979,"height":642,"caption":"Miriam Nogueras en el Congreso | Foto del Congreso de los Diputados"},"datePublished":"2025-05-08T17:26:04+02:00","dateModified":"2025-05-08T17:26:04+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#webpage"},"articleSection":"Actualidad, pol\u00edtica","dateline":"Publicado el mayo 8, 2025."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#webpage","url":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/","name":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365","description":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg","@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#mainImage","width":979,"height":642,"caption":"Miriam Nogueras en el Congreso | Foto del Congreso de los Diputados"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/#mainImage"},"datePublished":"2025-05-08T17:26:04+02:00","dateModified":"2025-05-08T17:26:04+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365","og:description":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros","og:url":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg","og:image:width":979,"og:image:height":642,"article:published_time":"2025-05-08T15:26:04+00:00","article:modified_time":"2025-05-08T15:26:04+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno | Cand\u00e1s 365","twitter:description":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2025\/05\/Miriam-Nogueras-Junts.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"186363","title":null,"description":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno validado en el Congreso tras garantizarse que los fondos y los instrumentos financieros","keywords":null,"keyphrases":{"focus":{"keyphrase":"Junts","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Junts","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-03 12:33:33","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-05-08 15:13:09","updated":"2025-09-03 12:33:33"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tJunts ha dado el visto bueno al plan antiaranceles del Gobierno\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Junts ha dado el visto bueno al plan antiaranceles del Gobierno","link":"https:\/\/candas365.es\/noticias\/junts-ha-dado-el-visto-bueno-al-plan-antiaranceles-del-gobierno\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/186363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=186363"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/186363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/186364"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=186363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=186363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=186363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}